{"id":2122,"date":"2009-09-01T06:35:00","date_gmt":"2009-09-01T06:35:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20"},"modified":"2016-03-11T09:48:55","modified_gmt":"2016-03-11T09:48:55","slug":"turismo-y-la-web-20-hoteles-20","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/","title":{"rendered":"Turismo y la web 2.0: Hoteles 2.0"},"content":{"rendered":"<p><a href=\"http:\/\/www.ityis.com\/images\/logo_web2.0.gif\" onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\"><img decoding=\"async\" alt=\"\" border=\"0\" src=\"http:\/\/www.ityis.com\/images\/logo_web2.0.gif\" style=\"cursor: pointer; float: right; height: 70px; margin: 0pt 0pt 10px 10px; width: 165px;\" \/><\/a>3 art\u00edculos sobre el sector tur\u00edstico y las herramientas web 2.0. Este es el primero.<\/p>\n<p>Hoteles 2.0<\/p>\n<p>En los \u00faltimos a\u00f1os se ha producido un cambio en el sector de los viajes  producto de la <a href=\"http:\/\/es.wikipedia.org\/wiki\/Web_2.0\">web 2.0<\/a>. En  este nuevo Internet se fomenta la colaboraci\u00f3n y el intercambio de informaci\u00f3n  entre los usuarios de una comunidad o red social.  <br \/>\nEl sector tur\u00edstico ha abrazado el 2.0 debido a una nueva generaci\u00f3n de  b\u00fasquedas de viajes, con contenido generado por el usuario y con conversaci\u00f3n en  los usuarios.<br \/>\nAs\u00ed, las empresas no controlan las decisiones de los  usuarios. Los usuarios tienen el control bas\u00e1ndose en experiencias reales. Los  usuarios quieren el 100% de transparencia.<\/p>\n<p>Algunos hoteles usan la web  2.0 para conseguir m\u00e1s presencia en Internet, m\u00e1s visibilidad y m\u00e1s reservas. En  los pr\u00f3ximos d\u00edas vamos a poner algunos ejemplos de c\u00f3mo algunos hoteles usan  este concepto de web 2.0 para convertir su hotel tradicional en un verdadero  hotel 2.0. Crean p\u00e1ginas en redes sociales donde los usuarios muestran fotos y  videos y comentan sus experiencias, utilizan los blogs para conversar con sus  usuarios y herramientas de microblogging para orientar a sus clientes y ofrecer  sus ofertas.<\/p>\n<p>Ejemplos de algunos hoteles que usan el 2.0 paraconseguir  m\u00e1s visibilidad (y m\u00e1s reservas) son:<\/p>\n<ul>\n<li>El hotel <a href=\"http:\/\/www.mgmgrand.com\/\" target=\"_blank\">MGM Grand Las Vegas<\/a> tiene  m\u00e1s de 30.000 fans en <a href=\"http:\/\/www.facebook.com\/home.php?ref=home#\/MGMGrand?ref=ts\" target=\"_blank\">Facebook<\/a>.<\/li>\n<li>El hotel <a href=\"http:\/\/www.creatorsinn.com\/\" target=\"_blank\">Creators Inn by Elvine<\/a> ofrece,  a trav\u00e9s de su web y su p\u00e1gina en Facebook, estancias cortas de manera gratuita  a creadores que visiten Estocolmo.<\/li>\n<li>El proyecto <a href=\"http:\/\/www.sheraton-kauai.com\/act_guestlib.htm\" target=\"_blank\">Link@Sheraton<\/a> propone  a los hu\u00e9spedes poder disfrutar de distintas actividades recreativas mediante  Internet: acceder a conexi\u00f3n Wi-Fi de manera gratuita, poder enviar video  postales desde la p\u00e1gina del Sheraton, y enviarlo a varios destinatarios con el  objetivo de que \u201clos visitantes, ya sea de negocios o turistas, est\u00e9n conectados  con su trabajo y su familia en sus lugares de origen\u201d.<\/li>\n<li>Hyatt cre\u00f3  en twitter @<a href=\"http:\/\/twitter.com\/HyattConcierge\" target=\"_blank\">HyattConcierge<\/a> un  conserje virtual que informa a los clientes de todas las cuestiones requeridas.<\/li>\n<li><a href=\"http:\/\/www.ichotelsgroup.com\/\" target=\"_blank\">InterContinental Hotels Group<\/a> lanz\u00f3  su propia red social para los miembros del Priority club llamada <a href=\"http:\/\/community.priorityclub.com\/index.jspa\" target=\"_blank\">Priority Club  Connect<\/a>, una oportunidad para los usuarios para compartir y narrar sus experiencias de  viaje, subir fotos y compartir videos en una comunidad online.<\/li>\n<li>En  Espa\u00f1a, los hoteles <a href=\"http:\/\/holidayinnelche.com\/\" target=\"_blank\">Holiday  Inn Elche<\/a> y  <a href=\"http:\/\/holidayinnalicante.com\/\" target=\"_blank\">Holiday Inn Alicante  Playa de San Juan<\/a> incluyen  enlaces a comunidades como TripAdvisor, Trivago, Hoobing y Booking en su portada  para que los clientes puedan ver de primera mano las opiniones de los usuarios.  Y, por supuesto, usan <a href=\"http:\/\/maps.google.es\/maps?hl=es&amp;client=firefox-a&amp;rls=org.mozilla:es-ES:official&amp;hs=D4K&amp;um=1&amp;ie=UTF-8&amp;q=hotel+holiday+inn+elche&amp;fb=1&amp;split=1&amp;gl=es&amp;view=text&amp;latlng=9249623745542651526&amp;dtab=2&amp;ei=4_qYStidCMfRjAfK6cW8BQ&amp;sa=X&amp;oi=local_result&amp;ct=result&amp;resnum=2\" target=\"_blank\">Google Maps<\/a> para que los usuarios encuentren la mejor manera  de llegar al hotel.<\/li>\n<li>La <a href=\"http:\/\/hotelesmagic.ning.com\/\" target=\"_blank\">comunidad de amigos de los hoteles magic costa blanca<\/a> crece  cada temporada con promociones y ofertas. Adem\u00e1s, la cadena promociona eventos  para bloggers, twitteros y profesionales del sector Tur\u00edstico como el  twitts&amp;wines en Benidorm.<\/li>\n<li><a href=\"http:\/\/www.sbhotels.es\/\" target=\"_blank\">SB Hotels<\/a> enlaza su  web con <a href=\"http:\/\/twitter.com\/sb_hotels\" target=\"_blank\">Twitter<\/a>,  <a href=\"http:\/\/www.facebook.com\/HotelCoronaTortosa\" target=\"_blank\">Facebook<\/a>,  <a href=\"http:\/\/picasaweb.google.es\/HotelsSB\" target=\"_blank\">Picasa<\/a> o <a href=\"https:\/\/www.youtube.com\/sbhotels\" target=\"_blank\">Youtube<\/a> contactando  con usuarios y clientes en espacios diferentes a los habituales.<\/li>\n<\/ul>\n<p>Relacionados: <a href=\"http:\/\/www.euroresidentes.com\/hoteles\/espana\/\">Hoteles en Espa\u00f1a<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>3 art\u00edculos sobre el sector tur\u00edstico y las herramientas web 2.0. Este es el primero. Hoteles 2.0 En los \u00faltimos a\u00f1os se ha producido un cambio en el sector de los viajes producto de la web 2.0. En este nuevo Internet se fomenta la colaboraci\u00f3n y el intercambio de informaci\u00f3n entre los usuarios de una comunidad o red social. El sector tur\u00edstico ha abrazado el 2.0 debido a una nueva generaci\u00f3n de b\u00fasquedas de viajes, con contenido generado por el usuario y con conversaci\u00f3n en los usuarios. As\u00ed, las empresas no controlan las decisiones de los usuarios. Los usuarios tienen <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2122","post","type-post","status-publish","format-standard","hentry","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Turismo y la web 2.0: Hoteles 2.0 - Viajar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Turismo y la web 2.0: Hoteles 2.0 - Viajar\" \/>\n<meta property=\"og:description\" content=\"3 art\u00edculos sobre el sector tur\u00edstico y las herramientas web 2.0. Este es el primero. Hoteles 2.0 En los \u00faltimos a\u00f1os se ha producido un cambio en el sector de los viajes producto de la web 2.0. En este nuevo Internet se fomenta la colaboraci\u00f3n y el intercambio de informaci\u00f3n entre los usuarios de una comunidad o red social. El sector tur\u00edstico ha abrazado el 2.0 debido a una nueva generaci\u00f3n de b\u00fasquedas de viajes, con contenido generado por el usuario y con conversaci\u00f3n en los usuarios. As\u00ed, las empresas no controlan las decisiones de los usuarios. Los usuarios tienen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/\" \/>\n<meta property=\"og:site_name\" content=\"Viajar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/euroresidentes\/\" \/>\n<meta property=\"article:published_time\" content=\"2009-09-01T06:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-11T09:48:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.ityis.com\/images\/logo_web2.0.gif\" \/>\n<meta name=\"author\" content=\"Euroresidentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Euroresidentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/\",\"url\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/\",\"name\":\"Turismo y la web 2.0: Hoteles 2.0 - Viajar\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.ityis.com\/images\/logo_web2.0.gif\",\"datePublished\":\"2009-09-01T06:35:00+00:00\",\"dateModified\":\"2016-03-11T09:48:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#\/schema\/person\/4bbb21ebb04e241332a6c1c0c1f40bc1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/#primaryimage\",\"url\":\"http:\/\/www.ityis.com\/images\/logo_web2.0.gif\",\"contentUrl\":\"http:\/\/www.ityis.com\/images\/logo_web2.0.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Turismo y la web 2.0: Hoteles 2.0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/\",\"name\":\"Viajar\",\"description\":\"Viajar Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#\/schema\/person\/4bbb21ebb04e241332a6c1c0c1f40bc1\",\"name\":\"Euroresidentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2016\/03\/logo-euroresidentes-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2016\/03\/logo-euroresidentes-150x150.jpg\",\"caption\":\"Euroresidentes\"},\"description\":\"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de al vida cotidiana.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/info.htm\"],\"url\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/author\/euroresidentes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Turismo y la web 2.0: Hoteles 2.0 - Viajar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/","og_locale":"es_ES","og_type":"article","og_title":"Turismo y la web 2.0: Hoteles 2.0 - Viajar","og_description":"3 art\u00edculos sobre el sector tur\u00edstico y las herramientas web 2.0. Este es el primero. Hoteles 2.0 En los \u00faltimos a\u00f1os se ha producido un cambio en el sector de los viajes producto de la web 2.0. En este nuevo Internet se fomenta la colaboraci\u00f3n y el intercambio de informaci\u00f3n entre los usuarios de una comunidad o red social. El sector tur\u00edstico ha abrazado el 2.0 debido a una nueva generaci\u00f3n de b\u00fasquedas de viajes, con contenido generado por el usuario y con conversaci\u00f3n en los usuarios. As\u00ed, las empresas no controlan las decisiones de los usuarios. Los usuarios tienen","og_url":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/","og_site_name":"Viajar","article_publisher":"https:\/\/www.facebook.com\/euroresidentes\/","article_published_time":"2009-09-01T06:35:00+00:00","article_modified_time":"2016-03-11T09:48:55+00:00","og_image":[{"url":"http:\/\/www.ityis.com\/images\/logo_web2.0.gif","type":"","width":"","height":""}],"author":"Euroresidentes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Euroresidentes","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/","url":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/","name":"Turismo y la web 2.0: Hoteles 2.0 - Viajar","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/#primaryimage"},"image":{"@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ityis.com\/images\/logo_web2.0.gif","datePublished":"2009-09-01T06:35:00+00:00","dateModified":"2016-03-11T09:48:55+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#\/schema\/person\/4bbb21ebb04e241332a6c1c0c1f40bc1"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/#primaryimage","url":"http:\/\/www.ityis.com\/images\/logo_web2.0.gif","contentUrl":"http:\/\/www.ityis.com\/images\/logo_web2.0.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/turismo-y-la-web-20-hoteles-20\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/"},{"@type":"ListItem","position":2,"name":"Turismo y la web 2.0: Hoteles 2.0"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#website","url":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/","name":"Viajar","description":"Viajar Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#\/schema\/person\/4bbb21ebb04e241332a6c1c0c1f40bc1","name":"Euroresidentes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2016\/03\/logo-euroresidentes-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2016\/03\/logo-euroresidentes-150x150.jpg","caption":"Euroresidentes"},"description":"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de al vida cotidiana.","sameAs":["https:\/\/www.euroresidentes.com\/info.htm"],"url":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/author\/euroresidentes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/posts\/2122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/comments?post=2122"}],"version-history":[{"count":1,"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/posts\/2122\/revisions"}],"predecessor-version":[{"id":3463,"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/posts\/2122\/revisions\/3463"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/media?parent=2122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/categories?post=2122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/tags?post=2122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}