{"id":1072,"date":"2008-09-09T11:47:00","date_gmt":"2008-09-09T11:47:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo"},"modified":"2016-03-10T19:43:12","modified_gmt":"2016-03-10T19:43:12","slug":"liverpoo","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/","title":{"rendered":"Liverpool, m\u00e1s all\u00e1 de la ciudad de los Beatles"},"content":{"rendered":"<h3>\nEl acento de la ciudad<\/h3>\n<p><b><br \/><\/b><br \/>\n<b>Liverpool <\/b>es una de las ciudades m\u00e1s importantes del <b>Reino Unido<\/b>. Todav\u00eda tiene un puerto industrial y mucha de la riqueza de la ciudad durante el siglo XVIII llego con el trafico mar\u00edtimo con el resto de Europa y sus enlaces con el trafico de esclavos.  En los principios del siglo XIX casi 40% del comercio de todo el mundo pasaba por el puerto de Liverpool.<\/p>\n<p><b>Liverpool<\/b> esta situado en la regi\u00f3n de Inglaterra llamado Lancashire pero sus ciudadanos tiene su propio nombre y est\u00e1n conocidos como Liverpudlians o Scousers (el nombre viene de un cocido de carne). Aunque los habitantes de Liverpool vienen de todas partes del mundo y en particular Irlanda tienen un acento y dialecto especial y cuando escuchas a la gente hablar ya sabes donde estas sin tener que mirar los edificios magnificentes construidos cuando <b>Liverpool<\/b> estaba en su mayor apogeo.<\/p>\n<p>La ciudad sufri\u00f3 muchos bombardeos durante la <b>segunda guerra mundial<\/b> y tardo mucho para que la reconstrucci\u00f3n de la ciudad estuviera completada.<\/p>\n<h3>\nLa ciudad de los Beatles<\/h3>\n<div>\n<\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<a href=\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2008\/09\/Beatles_Liverpool.png\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" src=\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2008\/09\/Beatles_Liverpool.png\" height=\"292\" width=\"400\" \/><\/a><\/div>\n<div style=\"text-align: center;\">\n<\/div>\n<p>Durante los a\u00f1os sesenta <b>Liverpool<\/b> gano reconocimiento por su m\u00fasica conocido como Merseybeat, con muchos nuevos grupos, el m\u00e1s famoso &#8211; <b>los Beatles<\/b>. Su popularidad sigue atraendo turistas a la ciudad junto con otros atracciones culturales tales como <b>Tate Liverpool y los Walker Art Galleries<\/b>. Tambi\u00e9n tiene su orquesta la <b>Royal Liverpool Philharmonic<\/b> Orchestra bajo su carism\u00e1tico director Ruso, Vasily Petrenko. Tambi\u00e9n este a\u00f1o Liverpool esta compartiendo con Stavanger en Noruega el titulo de Ciudad Europea de la Cultura.<\/p>\n<p>El <b>teatro el Liverpool Playhouse<\/b> esta representando un musical llamado \u2018Once Upon A Time at the Adelphi\u2019 y en una critica en el peri\u00f3dico el Guardian dice que la canci\u00f3n \u2018Once Upon a Lifetime\u2019  (una vez en la vida) deber\u00eda ser nombrado el titulo oficial de la <b>capital Cultural Europea<\/b>\u2019 inmediatamente y es cierto que en mi opinion ninguna vida es completa sin visitar Liverpool.<\/p>\n<h3>\nSeguir leyendo:<\/h3>\n<p><\/p>\n<ul>\n<li><a href=\"http:\/\/ciudades-europeas.euroresidentes.com\/2010\/03\/liverpool-de-nuevo.html\" target=\"_blank\">Liverpool: una segunda visita<\/a><\/li>\n<\/ul>\n<p>B.R.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El acento de la ciudad Liverpool es una de las ciudades m\u00e1s importantes del Reino Unido. Todav\u00eda tiene un puerto industrial y mucha de la riqueza de la ciudad durante el siglo XVIII llego con el trafico mar\u00edtimo con el resto de Europa y sus enlaces con el trafico de esclavos. En los principios del siglo XIX casi 40% del comercio de todo el mundo pasaba por el puerto de Liverpool. Liverpool esta situado en la regi\u00f3n de Inglaterra llamado Lancashire pero sus ciudadanos tiene su propio nombre y est\u00e1n conocidos como Liverpudlians o Scousers (el nombre viene de un <\/p>\n","protected":false},"author":1,"featured_media":1153,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Liverpool, m\u00e1s all\u00e1 de la ciudad de los Beatles - Viajar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Liverpool, m\u00e1s all\u00e1 de la ciudad de los Beatles - Viajar\" \/>\n<meta property=\"og:description\" content=\"El acento de la ciudad Liverpool es una de las ciudades m\u00e1s importantes del Reino Unido. Todav\u00eda tiene un puerto industrial y mucha de la riqueza de la ciudad durante el siglo XVIII llego con el trafico mar\u00edtimo con el resto de Europa y sus enlaces con el trafico de esclavos. En los principios del siglo XIX casi 40% del comercio de todo el mundo pasaba por el puerto de Liverpool. Liverpool esta situado en la regi\u00f3n de Inglaterra llamado Lancashire pero sus ciudadanos tiene su propio nombre y est\u00e1n conocidos como Liverpudlians o Scousers (el nombre viene de un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/\" \/>\n<meta property=\"og:site_name\" content=\"Viajar\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/euroresidentes\/\" \/>\n<meta property=\"article:published_time\" content=\"2008-09-09T11:47:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-10T19:43:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2008\/09\/Beatles_Liverpool.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"586\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Euroresidentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Euroresidentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/\",\"url\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/\",\"name\":\"Liverpool, m\u00e1s all\u00e1 de la ciudad de los Beatles - Viajar\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2008\/09\/Beatles_Liverpool.png\",\"datePublished\":\"2008-09-09T11:47:00+00:00\",\"dateModified\":\"2016-03-10T19:43:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#\/schema\/person\/4bbb21ebb04e241332a6c1c0c1f40bc1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/#primaryimage\",\"url\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2008\/09\/Beatles_Liverpool.png\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2008\/09\/Beatles_Liverpool.png\",\"width\":800,\"height\":586},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Liverpool, m\u00e1s all\u00e1 de la ciudad de los Beatles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/\",\"name\":\"Viajar\",\"description\":\"Viajar Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#\/schema\/person\/4bbb21ebb04e241332a6c1c0c1f40bc1\",\"name\":\"Euroresidentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2016\/03\/logo-euroresidentes-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2016\/03\/logo-euroresidentes-150x150.jpg\",\"caption\":\"Euroresidentes\"},\"description\":\"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de al vida cotidiana.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/info.htm\"],\"url\":\"https:\/\/www.euroresidentes.com\/viajes\/viajar\/author\/euroresidentes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Liverpool, m\u00e1s all\u00e1 de la ciudad de los Beatles - Viajar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/","og_locale":"es_ES","og_type":"article","og_title":"Liverpool, m\u00e1s all\u00e1 de la ciudad de los Beatles - Viajar","og_description":"El acento de la ciudad Liverpool es una de las ciudades m\u00e1s importantes del Reino Unido. Todav\u00eda tiene un puerto industrial y mucha de la riqueza de la ciudad durante el siglo XVIII llego con el trafico mar\u00edtimo con el resto de Europa y sus enlaces con el trafico de esclavos. En los principios del siglo XIX casi 40% del comercio de todo el mundo pasaba por el puerto de Liverpool. Liverpool esta situado en la regi\u00f3n de Inglaterra llamado Lancashire pero sus ciudadanos tiene su propio nombre y est\u00e1n conocidos como Liverpudlians o Scousers (el nombre viene de un","og_url":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/","og_site_name":"Viajar","article_publisher":"https:\/\/www.facebook.com\/euroresidentes\/","article_published_time":"2008-09-09T11:47:00+00:00","article_modified_time":"2016-03-10T19:43:12+00:00","og_image":[{"width":800,"height":586,"url":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2008\/09\/Beatles_Liverpool.png","type":"image\/png"}],"author":"Euroresidentes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Euroresidentes","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/","url":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/","name":"Liverpool, m\u00e1s all\u00e1 de la ciudad de los Beatles - Viajar","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/#primaryimage"},"image":{"@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2008\/09\/Beatles_Liverpool.png","datePublished":"2008-09-09T11:47:00+00:00","dateModified":"2016-03-10T19:43:12+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#\/schema\/person\/4bbb21ebb04e241332a6c1c0c1f40bc1"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/#primaryimage","url":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2008\/09\/Beatles_Liverpool.png","contentUrl":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2008\/09\/Beatles_Liverpool.png","width":800,"height":586},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/liverpoo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/"},{"@type":"ListItem","position":2,"name":"Liverpool, m\u00e1s all\u00e1 de la ciudad de los Beatles"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#website","url":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/","name":"Viajar","description":"Viajar Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#\/schema\/person\/4bbb21ebb04e241332a6c1c0c1f40bc1","name":"Euroresidentes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2016\/03\/logo-euroresidentes-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-content\/uploads\/sites\/3\/2016\/03\/logo-euroresidentes-150x150.jpg","caption":"Euroresidentes"},"description":"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de al vida cotidiana.","sameAs":["https:\/\/www.euroresidentes.com\/info.htm"],"url":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/author\/euroresidentes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/posts\/1072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/comments?post=1072"}],"version-history":[{"count":1,"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/posts\/1072\/revisions"}],"predecessor-version":[{"id":1154,"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/posts\/1072\/revisions\/1154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/media\/1153"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/media?parent=1072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/categories?post=1072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/viajes\/viajar\/wp-json\/wp\/v2\/tags?post=1072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}