{"id":1175,"date":"2011-06-20T08:11:00","date_gmt":"2011-06-20T08:11:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz"},"modified":"2016-03-01T12:24:00","modified_gmt":"2016-03-01T12:24:00","slug":"busquedas-google-por-voz","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/","title":{"rendered":"B\u00fasquedas Google por voz"},"content":{"rendered":"<p><b>Google expande las b\u00fasquedas por voz a los ordenadores de escritorio<\/b><\/p>\n<div>Google est\u00e1 introduciendo m\u00e1s trucos tecnol\u00f3gicos para simplificar las b\u00fasquedas en Internet y dar a la gente una raz\u00f3n m\u00e1s para navegar por la Web con su navegador Chrome.<\/p>\n<\/div>\n<div>Las nuevas herramientas que ha dado a conocer incluyen una opci\u00f3n que permitir\u00e1 a los usuarios pronunciar sus solicitudes de b\u00fasqueda hablando en Ingl\u00e9s mientras est\u00e1n sentados frente a los ordenadores de su casa u oficina. Es algo que ya se puede hacer en los tel\u00e9fonos inteligentes con el software Android de Google.<\/p>\n<\/div>\n<div>Las nuevas caracter\u00edsticas sirven como otro recordatorio de que las b\u00fasquedas siguen siendo la espina dorsal de Google aunque la compa\u00f1\u00eda se expanda a campos como los dispositivos m\u00f3viles, los navegadores, los programas inform\u00e1ticos, la m\u00fasica e incluso la televisi\u00f3n.<\/p>\n<\/div>\n<div>Incorporando continuamente nuevas maneras de simplificar las solicitudes de b\u00fasqueda, Google espera ampliar su dominio en lo que hasta ahora ha sido el mercado m\u00e1s lucrativo de Internet: llevar a la gente a la informaci\u00f3n que quiere lo m\u00e1s r\u00e1pido posible. Fomentar m\u00e1s solicitudes de b\u00fasqueda proporciona a Google m\u00e1s oportunidades de mostrar los anuncios que generan la mayor parte de sus ingresos.<\/p>\n<\/div>\n<div>Por ahora, la opci\u00f3n de solicitud por voz para ordenadores de escritorio se ofrecer\u00e1 s\u00f3lo en el navegador Chrome de Google. Se activar\u00e1 pulsando el icono de un micr\u00f3fono dentro de la caja de b\u00fasqueda de Google. Los usuarios de Chrome dispondr\u00e1n de la nueva funci\u00f3n en los pr\u00f3ximos d\u00edas.<\/p>\n<\/div>\n<div>Google espera que, finalmente, todas las caracter\u00edsticas est\u00e9n disponibles tambi\u00e9n a trav\u00e9s de los navegadores Internet Explorer y Firefox, que tienen un p\u00fablico m\u00e1s amplio que Chrome. Con el tiempo, la gente tambi\u00e9n podr\u00e1 realizar solicitudes por voz en otros idiomas.<\/p>\n<\/div>\n<div>Fuente: <a href=\"http:\/\/news.yahoo.com\/s\/ap\/20110614\/ap_on_hi_te\/us_tec_google_search\">Yahoo<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Google expande las b\u00fasquedas por voz a los ordenadores de escritorio Google est\u00e1 introduciendo m\u00e1s trucos tecnol\u00f3gicos para simplificar las b\u00fasquedas en Internet y dar a la gente una raz\u00f3n m\u00e1s para navegar por la Web con su navegador Chrome. Las nuevas herramientas que ha dado a conocer incluyen una opci\u00f3n que permitir\u00e1 a los usuarios pronunciar sus solicitudes de b\u00fasqueda hablando en Ingl\u00e9s mientras est\u00e1n sentados frente a los ordenadores de su casa u oficina. Es algo que ya se puede hacer en los tel\u00e9fonos inteligentes con el software Android de Google. Las nuevas caracter\u00edsticas sirven como otro recordatorio <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1175","post","type-post","status-publish","format-standard","hentry","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>B\u00fasquedas Google por voz - Noticias Google<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B\u00fasquedas Google por voz - Noticias Google\" \/>\n<meta property=\"og:description\" content=\"Google expande las b\u00fasquedas por voz a los ordenadores de escritorio Google est\u00e1 introduciendo m\u00e1s trucos tecnol\u00f3gicos para simplificar las b\u00fasquedas en Internet y dar a la gente una raz\u00f3n m\u00e1s para navegar por la Web con su navegador Chrome. Las nuevas herramientas que ha dado a conocer incluyen una opci\u00f3n que permitir\u00e1 a los usuarios pronunciar sus solicitudes de b\u00fasqueda hablando en Ingl\u00e9s mientras est\u00e1n sentados frente a los ordenadores de su casa u oficina. Es algo que ya se puede hacer en los tel\u00e9fonos inteligentes con el software Android de Google. Las nuevas caracter\u00edsticas sirven como otro recordatorio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Google\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-20T08:11:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-01T12:24:00+00:00\" \/>\n<meta name=\"author\" content=\"Euroresidentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Euroresidentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/\",\"name\":\"B\u00fasquedas Google por voz - Noticias Google\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#website\"},\"datePublished\":\"2011-06-20T08:11:00+00:00\",\"dateModified\":\"2016-03-01T12:24:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B\u00fasquedas Google por voz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/\",\"name\":\"Noticias Google\",\"description\":\"Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907\",\"name\":\"Euroresidentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg\",\"caption\":\"Euroresidentes\"},\"description\":\"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de la vida cotidiana.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/info.htm\"],\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/author\/euroresidentes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"B\u00fasquedas Google por voz - Noticias Google","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/","og_locale":"es_ES","og_type":"article","og_title":"B\u00fasquedas Google por voz - Noticias Google","og_description":"Google expande las b\u00fasquedas por voz a los ordenadores de escritorio Google est\u00e1 introduciendo m\u00e1s trucos tecnol\u00f3gicos para simplificar las b\u00fasquedas en Internet y dar a la gente una raz\u00f3n m\u00e1s para navegar por la Web con su navegador Chrome. Las nuevas herramientas que ha dado a conocer incluyen una opci\u00f3n que permitir\u00e1 a los usuarios pronunciar sus solicitudes de b\u00fasqueda hablando en Ingl\u00e9s mientras est\u00e1n sentados frente a los ordenadores de su casa u oficina. Es algo que ya se puede hacer en los tel\u00e9fonos inteligentes con el software Android de Google. Las nuevas caracter\u00edsticas sirven como otro recordatorio","og_url":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/","og_site_name":"Noticias Google","article_published_time":"2011-06-20T08:11:00+00:00","article_modified_time":"2016-03-01T12:24:00+00:00","author":"Euroresidentes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Euroresidentes","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/","name":"B\u00fasquedas Google por voz - Noticias Google","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#website"},"datePublished":"2011-06-20T08:11:00+00:00","dateModified":"2016-03-01T12:24:00+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/busquedas-google-por-voz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/"},{"@type":"ListItem","position":2,"name":"B\u00fasquedas Google por voz"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#website","url":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/","name":"Noticias Google","description":"Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907","name":"Euroresidentes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg","caption":"Euroresidentes"},"description":"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de la vida cotidiana.","sameAs":["https:\/\/www.euroresidentes.com\/info.htm"],"url":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/author\/euroresidentes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/posts\/1175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/comments?post=1175"}],"version-history":[{"count":0,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/posts\/1175\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/media?parent=1175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/categories?post=1175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/tags?post=1175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}