{"id":1058,"date":"2015-07-28T17:51:00","date_gmt":"2015-07-28T15:51:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de"},"modified":"2016-06-19T12:28:34","modified_gmt":"2016-06-19T10:28:34","slug":"las-6-plantillas-de-documentos-de","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/","title":{"rendered":"Las 6 plantillas de documentos de Google m\u00e1s populares para profesores"},"content":{"rendered":"<p><b>Las plantillas son documentos que traen ya una estructura y maquetaci\u00f3n definidas<\/b>, de forma que el usuario solo tenga que elegir la plantilla m\u00e1s adecuada para el prop\u00f3sito de su documento y rellenar los apartados con la informaci\u00f3n. <b>Su uso agiliza considerablemente la creaci\u00f3n de documentos y mejora la productividad<\/b>.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"separator\" style=\"clear: both;text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/googleDocs1.png\" alt=\"Las 6 plantillas de documentos de Google m\u00e1s populares para profesores\" width=\"600\" height=\"450\" border=\"0\" \/><\/div>\n<p>En Documentos de Google, cualquier usuario puede crear una plantilla y colgarla en la Galer\u00eda de plantillas de Google para que otros usuarios la puedan descargar y usar de forma gratuita. Dentro de la galer\u00eda, las plantillas est\u00e1n clasificadas por temas en distintas categor\u00edas. Hay plantillas de calendarios y programaciones, cartas y faxes, curr\u00edculos y cartas de presentaci\u00f3n, etc.<\/p>\n<h2>Estas son las 6 plantillas m\u00e1s descargadas dentro de la categor\u00eda \u201cEstudiantes y profesores\u201d:<\/h2>\n<h3><b>1. Student report:<\/b><\/h3>\n<p>Plantilla para la elaboraci\u00f3n de un trabajo de clase. Ideal para clases de ciencias, historia o ingl\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"separator\" style=\"clear: both;text-align: center\"><a style=\"margin-left: 1em;margin-right: 1em\" href=\"http:\/\/4.bp.blogspot.com\/-tTY8d3kJ5C8\/Vbe5D9_BAZI\/AAAAAAAACEU\/zZfwf-jnCsw\/s1600\/Report.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/Report1.png\" alt=\"Plantilla &quot;Student report&quot; de Google Docs\" width=\"247\" height=\"320\" border=\"0\" \/><\/a><\/div>\n<h3><\/h3>\n<h3><b>2. Class Notes:<\/b><\/h3>\n<p>Plantilla b\u00e1sica para publicar las notas de clase.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"separator\" style=\"clear: both;text-align: center\"><a style=\"margin-left: 1em;margin-right: 1em\" href=\"http:\/\/3.bp.blogspot.com\/-r9jYVCwLGao\/Vbe5blMx9JI\/AAAAAAAACEc\/Sj80XjFQGQs\/s1600\/Class-notes.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/Class-notes1.png\" alt=\"Plantilla &quot;Class Notes&quot; de Google Docs\" width=\"247\" height=\"320\" border=\"0\" \/><\/a><\/div>\n<p>&nbsp;<br \/>\n<!-- inserta publi --><\/p>\n<h3><b>3. Essay grading rubric:<\/b><\/h3>\n<p>R\u00fabrica para la evaluaci\u00f3n de trabajos.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"separator\" style=\"clear: both;text-align: center\"><a style=\"margin-left: 1em;margin-right: 1em\" href=\"http:\/\/1.bp.blogspot.com\/-SDRD2gtG9f4\/Vbe6Cqv17fI\/AAAAAAAACEo\/1SeF83Qyero\/s1600\/rubrica-evaluacion-trabajos.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"\" src=\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/rubrica-evaluacion-trabajos1.png\" alt=\"Plantilla &quot;Essay grading rubric&quot; de Google Docs\" width=\"320\" height=\"247\" border=\"0\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<h3><\/h3>\n<h3><b>4. Syllabus &#8211; Simple:<\/b><\/h3>\n<p>Plantilla para la elaboraci\u00f3n del programa o plan de estudios de la asignatura o curso.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"separator\" style=\"clear: both;text-align: center\"><a style=\"margin-left: 1em;margin-right: 1em\" href=\"http:\/\/1.bp.blogspot.com\/-GG9b0935Zrs\/Vbe64u2WDzI\/AAAAAAAACE0\/0i-hAuwFo6k\/s1600\/syllabus-simple.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"\" src=\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/syllabus-simple1.png\" alt=\"Plantilla &quot;Syllabus - Simple&quot; de Google Docs\" width=\"247\" height=\"320\" border=\"0\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<h3><b>5. Syllabus &#8211; Basic:\u00a0<\/b><\/h3>\n<p>Otra plantilla para la elaboraci\u00f3n de un programa o plan de estudios.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"separator\" style=\"clear: both;text-align: center\"><a style=\"margin-left: 1em;margin-right: 1em\" href=\"http:\/\/1.bp.blogspot.com\/-UfxDpBd9ttk\/Vbe7hZqp-bI\/AAAAAAAACE8\/99BIeWH1xyE\/s1600\/syllabus-basic.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"\" src=\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/syllabus-basic1.png\" alt=\"Plantilla &quot;Syllabus - Basic&quot; de Google Docs\" width=\"247\" height=\"320\" border=\"0\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<h3><b>6. Lesson plan &#8211; Basic:\u00a0<\/b><\/h3>\n<p>Plantilla para la elaboraci\u00f3n de una unidad did\u00e1ctica, tema o lecci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"separator\" style=\"clear: both;text-align: center\"><a style=\"margin-left: 1em;margin-right: 1em\" href=\"http:\/\/4.bp.blogspot.com\/-sN_2H0nrXlg\/Vbe7rbTJ_dI\/AAAAAAAACFE\/G4S-SDprLyc\/s1600\/Lesson.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"\" src=\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/Lesson1.png\" alt=\"Plantilla &quot;Lesson plan&quot; de Google Docs\" width=\"247\" height=\"320\" border=\"0\" \/><\/a><\/div>\n<p>&nbsp;<\/p>\n<h3><b>Seguir leyendo:\u00a0<\/b><\/h3>\n<ul>\n<li><a href=\"http:\/\/noticias-google.euroresidentes.com\/2014\/10\/los-15-mejores-complementos-de-google.html\" target=\"_blank\">Los 15 mejores complementos de Google Drive para educaci\u00f3n<\/a><\/li>\n<li><a href=\"http:\/\/noticias-google.euroresidentes.com\/2014\/09\/15-plugins-de-gmail-que-potenciaran.html\" target=\"_blank\">15 Plugins de Gmail que potenciar\u00e1n nuestra productividad con el correo electr\u00f3nico<\/a><\/li>\n<li><a href=\"http:\/\/noticias-google.euroresidentes.com\/2014\/06\/google-drive-10-trucos-para-sacarle.html\" target=\"_blank\">Google Drive: 10 trucos para sacarle todo el partido<\/a><\/li>\n<li><a href=\"http:\/\/noticias-google.euroresidentes.com\/2014\/05\/8-cosas-que-se-pueden-hacer-con-google.html\" target=\"_blank\">8 cosas que se pueden hacer con Google Drive\u00a0<\/a><\/li>\n<li><a href=\"http:\/\/noticias-google.euroresidentes.com\/2014\/05\/google-crea-aplicaciones-moviles.html\" target=\"_blank\">Google crea aplicaciones m\u00f3viles independientes a Drive para sus documentos y hojas de c\u00e1lculo <\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Las plantillas son documentos que traen ya una estructura y maquetaci\u00f3n definidas, de forma que el usuario solo tenga que elegir la plantilla m\u00e1s adecuada para el prop\u00f3sito de su documento y rellenar los apartados con la informaci\u00f3n. Su uso agiliza considerablemente la creaci\u00f3n de documentos y mejora la productividad. &nbsp; En Documentos de Google, cualquier usuario puede crear una plantilla y colgarla en la Galer\u00eda de plantillas de Google para que otros usuarios la puedan descargar y usar de forma gratuita. Dentro de la galer\u00eda, las plantillas est\u00e1n clasificadas por temas en distintas categor\u00edas. Hay plantillas de calendarios y <\/p>\n","protected":false},"author":7,"featured_media":1558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-google-apps","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las 6 plantillas de documentos de Google m\u00e1s populares para profesores - Noticias Google<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las 6 plantillas de documentos de Google m\u00e1s populares para profesores - Noticias Google\" \/>\n<meta property=\"og:description\" content=\"Las plantillas son documentos que traen ya una estructura y maquetaci\u00f3n definidas, de forma que el usuario solo tenga que elegir la plantilla m\u00e1s adecuada para el prop\u00f3sito de su documento y rellenar los apartados con la informaci\u00f3n. Su uso agiliza considerablemente la creaci\u00f3n de documentos y mejora la productividad. &nbsp; En Documentos de Google, cualquier usuario puede crear una plantilla y colgarla en la Galer\u00eda de plantillas de Google para que otros usuarios la puedan descargar y usar de forma gratuita. Dentro de la galer\u00eda, las plantillas est\u00e1n clasificadas por temas en distintas categor\u00edas. Hay plantillas de calendarios y\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias Google\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100000186278104\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-28T15:51:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-19T10:28:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/googleDocs1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"M. Rodr\u00edguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mgarod3\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"M. Rodr\u00edguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/\",\"name\":\"Las 6 plantillas de documentos de Google m\u00e1s populares para profesores - Noticias Google\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/googleDocs1.png\",\"datePublished\":\"2015-07-28T15:51:00+00:00\",\"dateModified\":\"2016-06-19T10:28:34+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#\/schema\/person\/522527c848344b20d633af2744a64a3b\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/#primaryimage\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/googleDocs1.png\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/googleDocs1.png\",\"width\":600,\"height\":450,\"caption\":\"Las 6 plantillas de documentos de Google m\u00e1s populares para profesores\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las 6 plantillas de documentos de Google m\u00e1s populares para profesores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/\",\"name\":\"Noticias Google\",\"description\":\"Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#\/schema\/person\/522527c848344b20d633af2744a64a3b\",\"name\":\"M. Rodr\u00edguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2016\/09\/mrodriguez2-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2016\/09\/mrodriguez2-150x150.jpg\",\"caption\":\"M. Rodr\u00edguez\"},\"description\":\"Mercedes Rodr\u00edguezTraductora y editora de contenidos web apasionada de la ciencia y la tecnolog\u00eda.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/tecnologia\/merchy-rodriguez.html\",\"https:\/\/www.facebook.com\/profile.php?id=100000186278104\",\"https:\/\/x.com\/mgarod3\"],\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/author\/merchy\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las 6 plantillas de documentos de Google m\u00e1s populares para profesores - Noticias Google","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/","og_locale":"es_ES","og_type":"article","og_title":"Las 6 plantillas de documentos de Google m\u00e1s populares para profesores - Noticias Google","og_description":"Las plantillas son documentos que traen ya una estructura y maquetaci\u00f3n definidas, de forma que el usuario solo tenga que elegir la plantilla m\u00e1s adecuada para el prop\u00f3sito de su documento y rellenar los apartados con la informaci\u00f3n. Su uso agiliza considerablemente la creaci\u00f3n de documentos y mejora la productividad. &nbsp; En Documentos de Google, cualquier usuario puede crear una plantilla y colgarla en la Galer\u00eda de plantillas de Google para que otros usuarios la puedan descargar y usar de forma gratuita. Dentro de la galer\u00eda, las plantillas est\u00e1n clasificadas por temas en distintas categor\u00edas. Hay plantillas de calendarios y","og_url":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/","og_site_name":"Noticias Google","article_author":"https:\/\/www.facebook.com\/profile.php?id=100000186278104","article_published_time":"2015-07-28T15:51:00+00:00","article_modified_time":"2016-06-19T10:28:34+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/googleDocs1.png","type":"image\/png"}],"author":"M. Rodr\u00edguez","twitter_card":"summary_large_image","twitter_creator":"@mgarod3","twitter_misc":{"Written by":"M. Rodr\u00edguez","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/","name":"Las 6 plantillas de documentos de Google m\u00e1s populares para profesores - Noticias Google","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/#primaryimage"},"image":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/googleDocs1.png","datePublished":"2015-07-28T15:51:00+00:00","dateModified":"2016-06-19T10:28:34+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#\/schema\/person\/522527c848344b20d633af2744a64a3b"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/#primaryimage","url":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/googleDocs1.png","contentUrl":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2015\/07\/googleDocs1.png","width":600,"height":450,"caption":"Las 6 plantillas de documentos de Google m\u00e1s populares para profesores"},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/las-6-plantillas-de-documentos-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/"},{"@type":"ListItem","position":2,"name":"Las 6 plantillas de documentos de Google m\u00e1s populares para profesores"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#website","url":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/","name":"Noticias Google","description":"Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#\/schema\/person\/522527c848344b20d633af2744a64a3b","name":"M. Rodr\u00edguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2016\/09\/mrodriguez2-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-content\/uploads\/sites\/4\/2016\/09\/mrodriguez2-150x150.jpg","caption":"M. Rodr\u00edguez"},"description":"Mercedes Rodr\u00edguezTraductora y editora de contenidos web apasionada de la ciencia y la tecnolog\u00eda.","sameAs":["https:\/\/www.euroresidentes.com\/tecnologia\/merchy-rodriguez.html","https:\/\/www.facebook.com\/profile.php?id=100000186278104","https:\/\/x.com\/mgarod3"],"url":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/author\/merchy\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/posts\/1058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/comments?post=1058"}],"version-history":[{"count":0,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/posts\/1058\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/media\/1558"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/media?parent=1058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/categories?post=1058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/noticias-google\/wp-json\/wp\/v2\/tags?post=1058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}