{"id":5331,"date":"2017-06-06T19:23:30","date_gmt":"2017-06-06T17:23:30","guid":{"rendered":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/?p=5331"},"modified":"2017-06-21T11:41:27","modified_gmt":"2017-06-21T09:41:27","slug":"un-nuevo-nanomaterial-transparente-y-conductor","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/","title":{"rendered":"Un nuevo nanomaterial transparente y conductor podr\u00eda revolucionar la electr\u00f3nica"},"content":{"rendered":"<p>Investigadores de la Universidad de Minnesota, en EE.UU., han descubierto un nuevo nanomaterial transparente de pel\u00edcula delgada con la mayor conductividad observada hasta la fecha en cualquier material de su clase.<\/p>\n<p>Con estas asombrosas caracter\u00edsticas, <strong>podr\u00eda dar lugar a dispositivos electr\u00f3nicos m\u00e1s peque\u00f1os, r\u00e1pidos y potentes; y a c\u00e9lulas solares m\u00e1s eficientes<\/strong>.<\/p>\n<p>Adem\u00e1s, de por su <strong>elevada conductividad<\/strong>, el nuevo nanomaterial se caracteriza por tener una amplia banda prohibida, lo que permite que la luz pase f\u00e1cilmente a trav\u00e9s de \u00e9l, haci\u00e9ndolo <strong>\u00f3pticamente transparente<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5332\" src=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2017\/06\/telefono-transparente.jpg\" alt=\"Un nuevo nanomaterial transparente y conductor podr\u00eda revolucionar la electr\u00f3nica\" width=\"700\" height=\"525\" srcset=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2017\/06\/telefono-transparente.jpg 700w, https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2017\/06\/telefono-transparente-300x225.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>La combinaci\u00f3n de estas dos caracter\u00edsticas, gran conductividad y una amplia banda prohibida, es precisamente lo que hace de este nanomaterial algo tan especial. Y es que por lo general, los materiales con una amplia banda prohibida son malos conductores y se suelen utilizar como aislantes.<\/p>\n<p>Seg\u00fan Bharat Jalan, profesor de ingenier\u00eda qu\u00edmica y materiales de la Universidad de Minnesota e investigador principal del estudio:<\/p>\n<blockquote>\n<p>\u00abLa alta conductividad y amplia banda prohibida de este un material hacen que sea ideal para la fabricaci\u00f3n de pel\u00edculas conductoras \u00f3pticamente transparentes que pueden utilizarse en una amplia variedad de dispositivos electr\u00f3nicos, incluyendo dispositivos electr\u00f3nicos de gran potencia, pantallas electr\u00f3nicas, pantallas t\u00e1ctiles e incluso c\u00e9lulas solares en las que la luz necesita pasar a trav\u00e9s del dispositivo\u00bb.<\/p>\n<\/blockquote>\n<p><strong>En la actualidad, la mayor\u00eda de los dispositivos electr\u00f3nicos conductores y transparentes utilizan<\/strong> un elemento qu\u00edmico denominado <strong>indio<\/strong>.<\/p>\n<p>Sin embargo, se trata de un elemento <strong>poco abundante<\/strong> y, debido a su uso cada vez mayor en m\u00f3viles, tablets y otros dispositivos electr\u00f3nicos de consumo, a lo largo de los \u00faltimos 20 a\u00f1os <strong>su precio no ha parado de subir<\/strong>.<\/p>\n<p>De ah\u00ed que los cient\u00edficos lleven a\u00f1os buscando un material m\u00e1s barato y abundante que pueda reemplazarlo.<\/p>\n<p>Ahora, finalmente, los investigadores de la Universidad de Minnesota parecen haber descubierto una <strong>soluci\u00f3n<\/strong>.<\/p>\n<p>Utilizando un m\u00e9todo de s\u00edntesis novedoso, desarrollaron una <strong>pel\u00edcula delgada de estannato de bario<\/strong> (BaSnO3), formada a partir de una combinaci\u00f3n de tres elementos abundantes en la naturaleza y mucho m\u00e1s baratos que el indio: bario, esta\u00f1o y ox\u00edgeno; y reemplazaron la fuente elemental de esta\u00f1o por un precursor qu\u00edmico del esta\u00f1o.<\/p>\n<p>El precursor qu\u00edmico del esta\u00f1o tiene propiedades \u00fanicas y radicales que mejoran la reactividad qu\u00edmica y mejoran mucho el proceso de formaci\u00f3n de \u00f3xido met\u00e1lico.<\/p>\n<p>Y tanto el bario como el esta\u00f1o son significativamente m\u00e1s baratos que el indio y abundan en la naturaleza.<\/p>\n<blockquote>\n<p>\u00abNos sorprendi\u00f3 mucho lo bien que funcion\u00f3 este enfoque poco convencional la primera vez que usamos el precursor qu\u00edmico de esta\u00f1o\u00bb, se\u00f1al\u00f3 Abhinav Prakash, estudiante de postgrado de ingenier\u00eda qu\u00edmica y materiales en la Universidad de Minnesota y principal autor del trabajo.<\/p>\n<\/blockquote>\n<p>El nuevo proceso ha permitido a los investigadores crear el nanomaterial con un <strong>control sin precedentes sobre el espesor, la composici\u00f3n y la concentraci\u00f3n de los defectos<\/strong> y, seg\u00fan Jalan y Prakash, podr\u00eda ser adecuado para otros sistemas de materiales en los que el elemento es dif\u00edcil de oxidar. Adem\u00e1s, <strong>es reproducible y escalable<\/strong>.<\/p>\n<p>El siguiente paso, seg\u00fan los investigadores ser\u00e1 reducir los defectos a escala at\u00f3mica.<\/p>\n<blockquote>\n<p>\u00abSi bien este material ya tiene la conductividad m\u00e1s alta dentro de su misma clase de materiales, todav\u00eda hay mucho margen de mejora, adem\u00e1s del extraordinario potencial para descubrir nuevas propiedades f\u00edsicas si disminuimos los defectos. Ese es nuestro pr\u00f3ximo objetivo\u00bb, se\u00f1al\u00f3 Jalan.<\/p>\n<\/blockquote>\n<p>La investigaci\u00f3n ha sido financiada por la Fundaci\u00f3n Nacional para la Ciencia (NSF), la Oficina de Investigaci\u00f3n Cient\u00edfica de las Fuerzas A\u00e9reas (AFOSR) y el Departamento de Energ\u00eda de los Estados Unidos; y <strong>el trabajo ha sido publicado en la revista de acceso libre <a href=\"https:\/\/www.nature.com\/articles\/ncomms15167\" target=\"_blank\"><em>Nature Communications<\/em><\/a>.<\/strong><\/p>\n<p>Fuente: <a href=\"https:\/\/twin-cities.umn.edu\/news-events\/new-thin-transparent-film-could-improve-electronics-and-solar-cells\" target=\"_blank\">Universidad de Minnesota<\/a><\/p>\n<p><strong>Seguir leyendo:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/unas-nanohebras-de-plata-podrian-ser-la-clave-para-el-desarrollo-de-dispositivos-flexibles\">Unos nanohilos de plata podr\u00edan ser la clave para el desarrollo de dispositivos flexibles<\/a><\/li>\n<li><a href=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanodispositivos-mucho-mas-baratos\">La revoluci\u00f3n de los nanodispositivos: mucho m\u00e1s baratos gracias a nuevas t\u00e9cnicas de fabricaci\u00f3n de MEMS<\/a><\/li>\n<li><a href=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/condensador-de-grafeno-epfl\">Un condensador de grafeno podr\u00eda revolucionar el Internet de las cosas<\/a><\/li>\n<li><a href=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/plantas-de-espinacas-nanobionicas-detectan-explosivos\">Convierten plantas de espinacas en detectores de explosivos utilizando nanotecnolog\u00eda<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Investigadores de la Universidad de Minnesota, en EE.UU., han descubierto un nuevo nanomaterial transparente de pel\u00edcula delgada con la mayor conductividad observada hasta la fecha en cualquier material de su clase. Con estas asombrosas caracter\u00edsticas, podr\u00eda dar lugar a dispositivos electr\u00f3nicos m\u00e1s peque\u00f1os, r\u00e1pidos y potentes; y a c\u00e9lulas solares m\u00e1s eficientes. Adem\u00e1s, de por su elevada conductividad, el nuevo nanomaterial se caracteriza por tener una amplia banda prohibida, lo que permite que la luz pase f\u00e1cilmente a trav\u00e9s de \u00e9l, haci\u00e9ndolo \u00f3pticamente transparente. La combinaci\u00f3n de estas dos caracter\u00edsticas, gran conductividad y una amplia banda prohibida, es precisamente lo <\/p>\n","protected":false},"author":7,"featured_media":5332,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,53],"tags":[],"class_list":["post-5331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nanoelectronica","category-nanomateriales","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un nuevo nanomaterial transparente y conductor podr\u00eda revolucionar la electr\u00f3nica - Nanotecnolog\u00eda<\/title>\n<meta name=\"description\" content=\"El nuevo nanomaterial transparente de pel\u00edcula delgada presenta la mayor conductividad observada hasta la fecha en cualquier material de su clase.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un nuevo nanomaterial transparente y conductor podr\u00eda revolucionar la electr\u00f3nica - Nanotecnolog\u00eda\" \/>\n<meta property=\"og:description\" content=\"El nuevo nanomaterial transparente de pel\u00edcula delgada presenta la mayor conductividad observada hasta la fecha en cualquier material de su clase.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/\" \/>\n<meta property=\"og:site_name\" content=\"Nanotecnolog\u00eda\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/profile.php?id=100000186278104\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-06T17:23:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-21T09:41:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2017\/06\/telefono-transparente.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M. Rodr\u00edguez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mgarod3\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"M. Rodr\u00edguez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/\",\"name\":\"Un nuevo nanomaterial transparente y conductor podr\u00eda revolucionar la electr\u00f3nica - Nanotecnolog\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2017\/06\/telefono-transparente.jpg\",\"datePublished\":\"2017-06-06T17:23:30+00:00\",\"dateModified\":\"2017-06-21T09:41:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/522527c848344b20d633af2744a64a3b\"},\"description\":\"El nuevo nanomaterial transparente de pel\u00edcula delgada presenta la mayor conductividad observada hasta la fecha en cualquier material de su clase.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/#primaryimage\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2017\/06\/telefono-transparente.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2017\/06\/telefono-transparente.jpg\",\"width\":700,\"height\":525,\"caption\":\"Un nuevo nanomaterial transparente y conductor podr\u00eda revolucionar la electr\u00f3nica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un nuevo nanomaterial transparente y conductor podr\u00eda revolucionar la electr\u00f3nica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/\",\"name\":\"Nanotecnolog\u00eda\",\"description\":\"Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/522527c848344b20d633af2744a64a3b\",\"name\":\"M. Rodr\u00edguez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/09\/mrodriguez2-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/09\/mrodriguez2-150x150.jpg\",\"caption\":\"M. Rodr\u00edguez\"},\"description\":\"Mercedes Rodr\u00edguezTraductora y editora de contenidos web apasionada de la ciencia y la tecnolog\u00eda.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/tecnologia\/merchy-rodriguez.html\",\"https:\/\/www.facebook.com\/profile.php?id=100000186278104\",\"https:\/\/x.com\/mgarod3\"],\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/author\/merchy\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un nuevo nanomaterial transparente y conductor podr\u00eda revolucionar la electr\u00f3nica - Nanotecnolog\u00eda","description":"El nuevo nanomaterial transparente de pel\u00edcula delgada presenta la mayor conductividad observada hasta la fecha en cualquier material de su clase.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/","og_locale":"es_ES","og_type":"article","og_title":"Un nuevo nanomaterial transparente y conductor podr\u00eda revolucionar la electr\u00f3nica - Nanotecnolog\u00eda","og_description":"El nuevo nanomaterial transparente de pel\u00edcula delgada presenta la mayor conductividad observada hasta la fecha en cualquier material de su clase.","og_url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/","og_site_name":"Nanotecnolog\u00eda","article_author":"https:\/\/www.facebook.com\/profile.php?id=100000186278104","article_published_time":"2017-06-06T17:23:30+00:00","article_modified_time":"2017-06-21T09:41:27+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2017\/06\/telefono-transparente.jpg","type":"image\/jpeg"}],"author":"M. Rodr\u00edguez","twitter_card":"summary_large_image","twitter_creator":"@mgarod3","twitter_misc":{"Written by":"M. Rodr\u00edguez","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/","name":"Un nuevo nanomaterial transparente y conductor podr\u00eda revolucionar la electr\u00f3nica - Nanotecnolog\u00eda","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/#primaryimage"},"image":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2017\/06\/telefono-transparente.jpg","datePublished":"2017-06-06T17:23:30+00:00","dateModified":"2017-06-21T09:41:27+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/522527c848344b20d633af2744a64a3b"},"description":"El nuevo nanomaterial transparente de pel\u00edcula delgada presenta la mayor conductividad observada hasta la fecha en cualquier material de su clase.","breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/#primaryimage","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2017\/06\/telefono-transparente.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2017\/06\/telefono-transparente.jpg","width":700,"height":525,"caption":"Un nuevo nanomaterial transparente y conductor podr\u00eda revolucionar la electr\u00f3nica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/un-nuevo-nanomaterial-transparente-y-conductor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/"},{"@type":"ListItem","position":2,"name":"Un nuevo nanomaterial transparente y conductor podr\u00eda revolucionar la electr\u00f3nica"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/","name":"Nanotecnolog\u00eda","description":"Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/522527c848344b20d633af2744a64a3b","name":"M. Rodr\u00edguez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/09\/mrodriguez2-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/09\/mrodriguez2-150x150.jpg","caption":"M. Rodr\u00edguez"},"description":"Mercedes Rodr\u00edguezTraductora y editora de contenidos web apasionada de la ciencia y la tecnolog\u00eda.","sameAs":["https:\/\/www.euroresidentes.com\/tecnologia\/merchy-rodriguez.html","https:\/\/www.facebook.com\/profile.php?id=100000186278104","https:\/\/x.com\/mgarod3"],"url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/author\/merchy\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts\/5331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/comments?post=5331"}],"version-history":[{"count":0,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts\/5331\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/media\/5332"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/media?parent=5331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/categories?post=5331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/tags?post=5331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}