{"id":3468,"date":"2005-09-08T08:40:00","date_gmt":"2005-09-08T08:40:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos"},"modified":"2016-03-01T23:46:33","modified_gmt":"2016-03-01T23:46:33","slug":"nanotecnologa-para-aliviar-los-efectos","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/","title":{"rendered":"Nanotecnolog\u00eda para aliviar los efectos del hurac\u00e1n Katrina"},"content":{"rendered":"<p>La empresa de nanotecnolog\u00eda Interface Sciences Corporation, ha anunciado que adelantar\u00e1 el lanzamiento al mercado de una nueva soluci\u00f3n tratada con nanotecnolog\u00eda para facilitar la limpieza y recuperaci\u00f3n de petr\u00f3leo que ha sido derramada como consecuencia del hurac\u00e1n Katrina.<\/p>\n<p>La nueva soluci\u00f3n utiliza tecnolog\u00eda patentada que se llama <em>Self-Assembled Monolayer (SAMs)<\/em> y es capaz de absorber cantidades de petr\u00f3leo de hasta 40 veces su peso, lo que representa una sustancial mejora con respecto a otros materiales comercializados  Adem\u00e1s, como la soluci\u00f3n rechaza completamente el agua, se puede recuperar el crudo para futuro uso, lo que supone un gran beneficio en los esfuerzos para la recuperaci\u00f3n de crudo de petr\u00f3leo derramado. <\/p>\n<p>Seg\u00fan el consejero delegado de la empresa, Interface Sciences pretende facilitar el uso de su soluci\u00f3n para ayudar a mitigar los impactos medioambientales y sanitarios causados por los 3.000 derrames de petr\u00f3leo que ocurren cada a\u00f1o y, sobre todo, los da\u00f1os causados por el hurrac\u00e1n Katrina. <\/p>\n<p>ISC basa su decisi\u00f3n de adelantar el lanzamiento de la soluci\u00f3n en la situaci\u00f3n de urgencia generada en la zona sur-este de los Estados Unidos. Su presidente ha afirmado que disponen de suficiente material para abarcar la limpieza de la flora y fauna de las zonas afectadas, pero que necesitan encontrar un socio para acelerar la fabricaci\u00f3n y distribuci\u00f3n de grandes cantidades necesaria para abarcar la limpieza de los grandes derrames de petr\u00f3leo.<\/p>\n<p>Relacionado: <a href=\"http:\/\/www.euroresidentes.com\/futuro\/nanotecnologia\/nanotecnologia_responsable\/nanotecnologia_beneficios.htm\" target=\"blank\">Beneficios de la nanotecnologia<\/a><br \/><a href=\"http:\/\/www.euroresidentes.com\/futuro\/nanotecnologia\/nanotecnologia_responsable\/riesgos_nanotecnologia.htm\" target=\"_blank\">Riesgos de la nanotecnolog\u00eda<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa de nanotecnolog\u00eda Interface Sciences Corporation, ha anunciado que adelantar\u00e1 el lanzamiento al mercado de una nueva soluci\u00f3n tratada con nanotecnolog\u00eda para facilitar la limpieza y recuperaci\u00f3n de petr\u00f3leo que ha sido derramada como consecuencia del hurac\u00e1n Katrina. La nueva soluci\u00f3n utiliza tecnolog\u00eda patentada que se llama Self-Assembled Monolayer (SAMs) y es capaz de absorber cantidades de petr\u00f3leo de hasta 40 veces su peso, lo que representa una sustancial mejora con respecto a otros materiales comercializados Adem\u00e1s, como la soluci\u00f3n rechaza completamente el agua, se puede recuperar el crudo para futuro uso, lo que supone un gran beneficio en <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3468","post","type-post","status-publish","format-standard","hentry","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nanotecnolog\u00eda para aliviar los efectos del hurac\u00e1n Katrina - Nanotecnolog\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nanotecnolog\u00eda para aliviar los efectos del hurac\u00e1n Katrina - Nanotecnolog\u00eda\" \/>\n<meta property=\"og:description\" content=\"La empresa de nanotecnolog\u00eda Interface Sciences Corporation, ha anunciado que adelantar\u00e1 el lanzamiento al mercado de una nueva soluci\u00f3n tratada con nanotecnolog\u00eda para facilitar la limpieza y recuperaci\u00f3n de petr\u00f3leo que ha sido derramada como consecuencia del hurac\u00e1n Katrina. La nueva soluci\u00f3n utiliza tecnolog\u00eda patentada que se llama Self-Assembled Monolayer (SAMs) y es capaz de absorber cantidades de petr\u00f3leo de hasta 40 veces su peso, lo que representa una sustancial mejora con respecto a otros materiales comercializados Adem\u00e1s, como la soluci\u00f3n rechaza completamente el agua, se puede recuperar el crudo para futuro uso, lo que supone un gran beneficio en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/\" \/>\n<meta property=\"og:site_name\" content=\"Nanotecnolog\u00eda\" \/>\n<meta property=\"article:published_time\" content=\"2005-09-08T08:40:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-01T23:46:33+00:00\" \/>\n<meta name=\"author\" content=\"Euroresidentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Euroresidentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/\",\"name\":\"Nanotecnolog\u00eda para aliviar los efectos del hurac\u00e1n Katrina - Nanotecnolog\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website\"},\"datePublished\":\"2005-09-08T08:40:00+00:00\",\"dateModified\":\"2016-03-01T23:46:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nanotecnolog\u00eda para aliviar los efectos del hurac\u00e1n Katrina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/\",\"name\":\"Nanotecnolog\u00eda\",\"description\":\"Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907\",\"name\":\"Euroresidentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg\",\"caption\":\"Euroresidentes\"},\"description\":\"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de la vida cotidiana.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/info.htm\"],\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/author\/euroresidentes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nanotecnolog\u00eda para aliviar los efectos del hurac\u00e1n Katrina - Nanotecnolog\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/","og_locale":"es_ES","og_type":"article","og_title":"Nanotecnolog\u00eda para aliviar los efectos del hurac\u00e1n Katrina - Nanotecnolog\u00eda","og_description":"La empresa de nanotecnolog\u00eda Interface Sciences Corporation, ha anunciado que adelantar\u00e1 el lanzamiento al mercado de una nueva soluci\u00f3n tratada con nanotecnolog\u00eda para facilitar la limpieza y recuperaci\u00f3n de petr\u00f3leo que ha sido derramada como consecuencia del hurac\u00e1n Katrina. La nueva soluci\u00f3n utiliza tecnolog\u00eda patentada que se llama Self-Assembled Monolayer (SAMs) y es capaz de absorber cantidades de petr\u00f3leo de hasta 40 veces su peso, lo que representa una sustancial mejora con respecto a otros materiales comercializados Adem\u00e1s, como la soluci\u00f3n rechaza completamente el agua, se puede recuperar el crudo para futuro uso, lo que supone un gran beneficio en","og_url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/","og_site_name":"Nanotecnolog\u00eda","article_published_time":"2005-09-08T08:40:00+00:00","article_modified_time":"2016-03-01T23:46:33+00:00","author":"Euroresidentes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Euroresidentes","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/","name":"Nanotecnolog\u00eda para aliviar los efectos del hurac\u00e1n Katrina - Nanotecnolog\u00eda","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website"},"datePublished":"2005-09-08T08:40:00+00:00","dateModified":"2016-03-01T23:46:33+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/nanotecnologa-para-aliviar-los-efectos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/"},{"@type":"ListItem","position":2,"name":"Nanotecnolog\u00eda para aliviar los efectos del hurac\u00e1n Katrina"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/","name":"Nanotecnolog\u00eda","description":"Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907","name":"Euroresidentes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg","caption":"Euroresidentes"},"description":"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de la vida cotidiana.","sameAs":["https:\/\/www.euroresidentes.com\/info.htm"],"url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/author\/euroresidentes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts\/3468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/comments?post=3468"}],"version-history":[{"count":0,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts\/3468\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/media?parent=3468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/categories?post=3468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/tags?post=3468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}