{"id":3401,"date":"2007-08-14T10:17:00","date_gmt":"2007-08-14T10:17:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape"},"modified":"2016-03-01T23:46:24","modified_gmt":"2016-03-01T23:46:24","slug":"batera-de-pape","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/","title":{"rendered":"Bater\u00eda de papel"},"content":{"rendered":"<p><strong>Convierten papel en una fuente de energ\u00eda con nanotubos<\/strong><\/p>\n<p>Seg\u00fan un art\u00edculo publicado esta semana en Newscientist.com, cient\u00edficos estadounidenses han desarrollado una nueva fuente de energ\u00eda a partir de papel impregnado con nanotubos de carbono. Los investigadores afirman que este papel, que se puede doblar, enrollar, etc.; se podr\u00eda utilizar en dispositivos electr\u00f3nicos flexibles. <\/p>\n<p>La fuente de energ\u00eda (supercondensador y bater\u00eda h\u00edbrida) ha sido desarrollada por investigadores del Rensselaer Polytechnic Institute, de Troy, Nueva York. Un condensador es como una bater\u00eda, salvo por el hecho de que, en lugar de depender de una reacci\u00f3n qu\u00edmica para almacenar y liberar energ\u00eda, permite que la carga el\u00e9ctrica se acumule en una serie de discos conductores separados por un aislante. <\/p>\n<p>Los condensadores convencionales no pueden almacenar mucha energ\u00eda, pero los investigadores han empezados a investigar con \u201csupercondensadores\u201d, en los que utilizan nanotubos de carbono como electrodos. La amplia superficie de estos nanotubos puede almacenar una cantidad de carga relativamente elevada.  <\/p>\n<p>Para lograr que los supercondensadores de nanotubos sean flexibles, Victor Pushparaj y sus colegas cultivaron primero los nanotubos sobre un sustrato de silicio por medio de una reacci\u00f3n qu\u00edmica de deposici\u00f3n de vapor. A continuaci\u00f3n, disolvieron una mezcla de cloruro y celulosa vegetal y la extendieron entre los nanotubos. Tras despegar el conjunto del sustrato de silicio, lo dejaron sobre un trozo de papel de unas cuantas decenas de micr\u00f3metros de grosor, de modo que los nanotubos de carbono se adhirieron a un lado.<\/p>\n<p>Para crear el supercondensador, se pegaron dos hojas de este papel con los nanotubos hacia fuera, recubriendo ambas caras con papel de aluminio como en los colectores actuales. Al aplicar una corriente, el papel almacen\u00f3 la carga, sirviendo los nanotubos de electrodos y la celulosa de aislante. <\/p>\n<p>Posteriormente, los investigadores utilizaron un m\u00e9todo similar para crear una bater\u00eda flexible. Utilizaron un trozo de papel con nanotubos de carbono como c\u00e1todo y evaporaron una capa de litio sobre la otra cara para que hiciese de \u00e1nodo. Una vez m\u00e1s lo envolvieron con papel de aluminio, que sirvi\u00f3 como colector de corriente. <br \/>Por \u00faltimo, distribuyendo por capas los supercondensadores y las bater\u00edas de ion-litio, crearon un dispositivo h\u00edbrido en el que se podr\u00edan utilizar las bater\u00edas para cargar los supercondensadores. <\/p>\n<p>Sin embargo, los supercondensadores y bater\u00edas del experimento no todav\u00eda no tienen la suficiente densidad de energ\u00eda como para competir con las bater\u00edas convencionales, por lo que Pushparaj se\u00f1ala que el pr\u00f3ximo paso ser\u00e1 desarrollar diferentes f\u00f3rmulas de celulosa y electrolitos que incrementen su capacidad de almacenamiento.  <\/p>\n<p>Para Joel Schindall, ingeniero el\u00e9ctrico del MIT, en Boston, EEUU, este trabajo constituye un \u00abdesarrollo prometedor\u00bb, aunque se\u00f1ala que todav\u00eda hay que superar algunas dificultades de coste y fiabilidad.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.newscientisttech.com\/article.ns?id=dn12480&#038;feedId=online-news_rss20\">New Scientist<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Convierten papel en una fuente de energ\u00eda con nanotubos Seg\u00fan un art\u00edculo publicado esta semana en Newscientist.com, cient\u00edficos estadounidenses han desarrollado una nueva fuente de energ\u00eda a partir de papel impregnado con nanotubos de carbono. Los investigadores afirman que este papel, que se puede doblar, enrollar, etc.; se podr\u00eda utilizar en dispositivos electr\u00f3nicos flexibles. La fuente de energ\u00eda (supercondensador y bater\u00eda h\u00edbrida) ha sido desarrollada por investigadores del Rensselaer Polytechnic Institute, de Troy, Nueva York. Un condensador es como una bater\u00eda, salvo por el hecho de que, en lugar de depender de una reacci\u00f3n qu\u00edmica para almacenar y liberar energ\u00eda, <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[39],"class_list":["post-3401","post","type-post","status-publish","format-standard","hentry","category-general","tag-nuevas-energias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bater\u00eda de papel - Nanotecnolog\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bater\u00eda de papel - Nanotecnolog\u00eda\" \/>\n<meta property=\"og:description\" content=\"Convierten papel en una fuente de energ\u00eda con nanotubos Seg\u00fan un art\u00edculo publicado esta semana en Newscientist.com, cient\u00edficos estadounidenses han desarrollado una nueva fuente de energ\u00eda a partir de papel impregnado con nanotubos de carbono. Los investigadores afirman que este papel, que se puede doblar, enrollar, etc.; se podr\u00eda utilizar en dispositivos electr\u00f3nicos flexibles. La fuente de energ\u00eda (supercondensador y bater\u00eda h\u00edbrida) ha sido desarrollada por investigadores del Rensselaer Polytechnic Institute, de Troy, Nueva York. Un condensador es como una bater\u00eda, salvo por el hecho de que, en lugar de depender de una reacci\u00f3n qu\u00edmica para almacenar y liberar energ\u00eda,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/\" \/>\n<meta property=\"og:site_name\" content=\"Nanotecnolog\u00eda\" \/>\n<meta property=\"article:published_time\" content=\"2007-08-14T10:17:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-01T23:46:24+00:00\" \/>\n<meta name=\"author\" content=\"Euroresidentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Euroresidentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/\",\"name\":\"Bater\u00eda de papel - Nanotecnolog\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website\"},\"datePublished\":\"2007-08-14T10:17:00+00:00\",\"dateModified\":\"2016-03-01T23:46:24+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bater\u00eda de papel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/\",\"name\":\"Nanotecnolog\u00eda\",\"description\":\"Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907\",\"name\":\"Euroresidentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg\",\"caption\":\"Euroresidentes\"},\"description\":\"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de la vida cotidiana.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/info.htm\"],\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/author\/euroresidentes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bater\u00eda de papel - Nanotecnolog\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/","og_locale":"es_ES","og_type":"article","og_title":"Bater\u00eda de papel - Nanotecnolog\u00eda","og_description":"Convierten papel en una fuente de energ\u00eda con nanotubos Seg\u00fan un art\u00edculo publicado esta semana en Newscientist.com, cient\u00edficos estadounidenses han desarrollado una nueva fuente de energ\u00eda a partir de papel impregnado con nanotubos de carbono. Los investigadores afirman que este papel, que se puede doblar, enrollar, etc.; se podr\u00eda utilizar en dispositivos electr\u00f3nicos flexibles. La fuente de energ\u00eda (supercondensador y bater\u00eda h\u00edbrida) ha sido desarrollada por investigadores del Rensselaer Polytechnic Institute, de Troy, Nueva York. Un condensador es como una bater\u00eda, salvo por el hecho de que, en lugar de depender de una reacci\u00f3n qu\u00edmica para almacenar y liberar energ\u00eda,","og_url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/","og_site_name":"Nanotecnolog\u00eda","article_published_time":"2007-08-14T10:17:00+00:00","article_modified_time":"2016-03-01T23:46:24+00:00","author":"Euroresidentes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Euroresidentes","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/","name":"Bater\u00eda de papel - Nanotecnolog\u00eda","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website"},"datePublished":"2007-08-14T10:17:00+00:00","dateModified":"2016-03-01T23:46:24+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/batera-de-pape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/"},{"@type":"ListItem","position":2,"name":"Bater\u00eda de papel"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/","name":"Nanotecnolog\u00eda","description":"Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907","name":"Euroresidentes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg","caption":"Euroresidentes"},"description":"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de la vida cotidiana.","sameAs":["https:\/\/www.euroresidentes.com\/info.htm"],"url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/author\/euroresidentes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts\/3401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/comments?post=3401"}],"version-history":[{"count":0,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts\/3401\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/media?parent=3401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/categories?post=3401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/tags?post=3401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}