{"id":2077,"date":"2006-12-21T10:38:00","date_gmt":"2006-12-21T10:38:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de"},"modified":"2016-03-01T15:56:26","modified_gmt":"2016-03-01T15:56:26","slug":"catalizador-de-nanofibras-de-xido-de","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/","title":{"rendered":"Catalizador de nanofibras de \u00f3xido de manganeso"},"content":{"rendered":"<p><strong>Nuevo catalizador de nanofibras de \u00f3xido de manganeso de American Elements<\/strong><\/p>\n<p>Seg\u00fan un art\u00edculo publicado el 19 de diciembre de 2006 en Azonano.com, American Elements\u2019 Nanometal\u2122 ha anunciado el desarrollo de un nuevo catalizador de nanofibras de \u00f3xido de manganeso capaz de destruir los compuestos org\u00e1nicos vol\u00e1tiles (COV) presentes en las emisiones a una escala de partes por bill\u00f3n (ppb). Esta forma propietaria a nanoescala de \u00f3xido de manganeso se comercializar\u00e1 bajo la marca \u201cMangasorb\u2122\u201d.<\/p>\n<p>Mangasorb\u2122 es una tecnolog\u00eda de \u00faltima generaci\u00f3n para la eliminaci\u00f3n catal\u00edtica de los COV procedentes de las emisiones de residuos industriales y puede destruir cerca de 50 compuestos org\u00e1nicos vol\u00e1tiles de los residuos peligrosos regulados por la RICRA, recubierto en sustratos de \u00e1reas de elevada superficie. El producto estar\u00e1 disponible en muchos tama\u00f1os, de hasta 1.000kg. Tambi\u00e9n se podr\u00e1n hacer pedidos m\u00e1s peque\u00f1os para programas de I+D de empresas y universidades. La l\u00ednea de productos Mangasorb\u2122 de American Elements\u2019 incluye tambi\u00e9n un nanopolvo que var\u00eda en tama\u00f1o de 10nm a 1 micr\u00f3n.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.azonano.com\/news.asp?newsID=3523 \">Azonano<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuevo catalizador de nanofibras de \u00f3xido de manganeso de American Elements Seg\u00fan un art\u00edculo publicado el 19 de diciembre de 2006 en Azonano.com, American Elements\u2019 Nanometal\u2122 ha anunciado el desarrollo de un nuevo catalizador de nanofibras de \u00f3xido de manganeso capaz de destruir los compuestos org\u00e1nicos vol\u00e1tiles (COV) presentes en las emisiones a una escala de partes por bill\u00f3n (ppb). Esta forma propietaria a nanoescala de \u00f3xido de manganeso se comercializar\u00e1 bajo la marca \u201cMangasorb\u2122\u201d. Mangasorb\u2122 es una tecnolog\u00eda de \u00faltima generaci\u00f3n para la eliminaci\u00f3n catal\u00edtica de los COV procedentes de las emisiones de residuos industriales y puede destruir cerca <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2077","post","type-post","status-publish","format-standard","hentry","category-general"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Catalizador de nanofibras de \u00f3xido de manganeso - Nanotecnolog\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Catalizador de nanofibras de \u00f3xido de manganeso - Nanotecnolog\u00eda\" \/>\n<meta property=\"og:description\" content=\"Nuevo catalizador de nanofibras de \u00f3xido de manganeso de American Elements Seg\u00fan un art\u00edculo publicado el 19 de diciembre de 2006 en Azonano.com, American Elements\u2019 Nanometal\u2122 ha anunciado el desarrollo de un nuevo catalizador de nanofibras de \u00f3xido de manganeso capaz de destruir los compuestos org\u00e1nicos vol\u00e1tiles (COV) presentes en las emisiones a una escala de partes por bill\u00f3n (ppb). Esta forma propietaria a nanoescala de \u00f3xido de manganeso se comercializar\u00e1 bajo la marca \u201cMangasorb\u2122\u201d. Mangasorb\u2122 es una tecnolog\u00eda de \u00faltima generaci\u00f3n para la eliminaci\u00f3n catal\u00edtica de los COV procedentes de las emisiones de residuos industriales y puede destruir cerca\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/\" \/>\n<meta property=\"og:site_name\" content=\"Nanotecnolog\u00eda\" \/>\n<meta property=\"article:published_time\" content=\"2006-12-21T10:38:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-01T15:56:26+00:00\" \/>\n<meta name=\"author\" content=\"Euroresidentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Euroresidentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/\",\"name\":\"Catalizador de nanofibras de \u00f3xido de manganeso - Nanotecnolog\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website\"},\"datePublished\":\"2006-12-21T10:38:00+00:00\",\"dateModified\":\"2016-03-01T15:56:26+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalizador de nanofibras de \u00f3xido de manganeso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/\",\"name\":\"Nanotecnolog\u00eda\",\"description\":\"Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907\",\"name\":\"Euroresidentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg\",\"caption\":\"Euroresidentes\"},\"description\":\"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de la vida cotidiana.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/info.htm\"],\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/author\/euroresidentes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Catalizador de nanofibras de \u00f3xido de manganeso - Nanotecnolog\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/","og_locale":"es_ES","og_type":"article","og_title":"Catalizador de nanofibras de \u00f3xido de manganeso - Nanotecnolog\u00eda","og_description":"Nuevo catalizador de nanofibras de \u00f3xido de manganeso de American Elements Seg\u00fan un art\u00edculo publicado el 19 de diciembre de 2006 en Azonano.com, American Elements\u2019 Nanometal\u2122 ha anunciado el desarrollo de un nuevo catalizador de nanofibras de \u00f3xido de manganeso capaz de destruir los compuestos org\u00e1nicos vol\u00e1tiles (COV) presentes en las emisiones a una escala de partes por bill\u00f3n (ppb). Esta forma propietaria a nanoescala de \u00f3xido de manganeso se comercializar\u00e1 bajo la marca \u201cMangasorb\u2122\u201d. Mangasorb\u2122 es una tecnolog\u00eda de \u00faltima generaci\u00f3n para la eliminaci\u00f3n catal\u00edtica de los COV procedentes de las emisiones de residuos industriales y puede destruir cerca","og_url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/","og_site_name":"Nanotecnolog\u00eda","article_published_time":"2006-12-21T10:38:00+00:00","article_modified_time":"2016-03-01T15:56:26+00:00","author":"Euroresidentes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Euroresidentes","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/","name":"Catalizador de nanofibras de \u00f3xido de manganeso - Nanotecnolog\u00eda","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website"},"datePublished":"2006-12-21T10:38:00+00:00","dateModified":"2016-03-01T15:56:26+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/catalizador-de-nanofibras-de-xido-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/"},{"@type":"ListItem","position":2,"name":"Catalizador de nanofibras de \u00f3xido de manganeso"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/","name":"Nanotecnolog\u00eda","description":"Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907","name":"Euroresidentes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg","caption":"Euroresidentes"},"description":"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de la vida cotidiana.","sameAs":["https:\/\/www.euroresidentes.com\/info.htm"],"url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/author\/euroresidentes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts\/2077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/comments?post=2077"}],"version-history":[{"count":0,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts\/2077\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/media?parent=2077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/categories?post=2077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/tags?post=2077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}