{"id":2011,"date":"2007-04-17T10:15:00","date_gmt":"2007-04-17T10:15:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas"},"modified":"2016-03-01T15:52:51","modified_gmt":"2016-03-01T15:52:51","slug":"peligros-de-las-nanopartculas","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/","title":{"rendered":"Peligros de las nanopart\u00edculas"},"content":{"rendered":"<p>Cient\u00edficos de la Universidad de California, en San Diego, y del Veterans Affairs Medical Healthcare System, en La Jolla, ha concluido recientemente que las nanopart\u00edculas magn\u00e9ticas pueden ser perjudiciales para la salud.<\/p>\n<p>Una serie de experimentos han revelado que las part\u00edculas de \u00f3xido de hierro de menos de 10 nan\u00f3metros de di\u00e1metro atrofian el crecimiento de las c\u00e9lulas nerviosas. Otros experimentos independientes, realizados in vitro en el National Institute of Standards and Technology (NIST), han concluido tambi\u00e9n que los nanotubos de menos de 200 nan\u00f3metros de largo interfieren en las c\u00e9lulas pulmonares humanas.<\/p>\n<p>Ambos grupos han hecho un llamamiento para realizar pruebas con animales que cuantifiquen los efectos t\u00f3xicos de los nanomateriales en los organismos vivos y caractericen los tipos m\u00e1s t\u00f3xicos de nanomateriales. Actualmente, la National Science Foundation (NSF) invierte casi 10 veces m\u00e1s en el desarrollo de nanomateriales que en investigaci\u00f3n para evitar sus efectos t\u00f3xicos.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.eetimes.com\/news\/latest\/showArticle.jhtml;jsessionid=KGWYSWZX5SUJIQSNDLSCKHA?articleID=199000914\">EEtimes<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cient\u00edficos de la Universidad de California, en San Diego, y del Veterans Affairs Medical Healthcare System, en La Jolla, ha concluido recientemente que las nanopart\u00edculas magn\u00e9ticas pueden ser perjudiciales para la salud. Una serie de experimentos han revelado que las part\u00edculas de \u00f3xido de hierro de menos de 10 nan\u00f3metros de di\u00e1metro atrofian el crecimiento de las c\u00e9lulas nerviosas. Otros experimentos independientes, realizados in vitro en el National Institute of Standards and Technology (NIST), han concluido tambi\u00e9n que los nanotubos de menos de 200 nan\u00f3metros de largo interfieren en las c\u00e9lulas pulmonares humanas. Ambos grupos han hecho un llamamiento para <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[12],"class_list":["post-2011","post","type-post","status-publish","format-standard","hentry","category-general","tag-riesgos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peligros de las nanopart\u00edculas - Nanotecnolog\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peligros de las nanopart\u00edculas - Nanotecnolog\u00eda\" \/>\n<meta property=\"og:description\" content=\"Cient\u00edficos de la Universidad de California, en San Diego, y del Veterans Affairs Medical Healthcare System, en La Jolla, ha concluido recientemente que las nanopart\u00edculas magn\u00e9ticas pueden ser perjudiciales para la salud. Una serie de experimentos han revelado que las part\u00edculas de \u00f3xido de hierro de menos de 10 nan\u00f3metros de di\u00e1metro atrofian el crecimiento de las c\u00e9lulas nerviosas. Otros experimentos independientes, realizados in vitro en el National Institute of Standards and Technology (NIST), han concluido tambi\u00e9n que los nanotubos de menos de 200 nan\u00f3metros de largo interfieren en las c\u00e9lulas pulmonares humanas. Ambos grupos han hecho un llamamiento para\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/\" \/>\n<meta property=\"og:site_name\" content=\"Nanotecnolog\u00eda\" \/>\n<meta property=\"article:published_time\" content=\"2007-04-17T10:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-01T15:52:51+00:00\" \/>\n<meta name=\"author\" content=\"Euroresidentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Euroresidentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/\",\"name\":\"Peligros de las nanopart\u00edculas - Nanotecnolog\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website\"},\"datePublished\":\"2007-04-17T10:15:00+00:00\",\"dateModified\":\"2016-03-01T15:52:51+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peligros de las nanopart\u00edculas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/\",\"name\":\"Nanotecnolog\u00eda\",\"description\":\"Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907\",\"name\":\"Euroresidentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg\",\"caption\":\"Euroresidentes\"},\"description\":\"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de la vida cotidiana.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/info.htm\"],\"url\":\"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/author\/euroresidentes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peligros de las nanopart\u00edculas - Nanotecnolog\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/","og_locale":"es_ES","og_type":"article","og_title":"Peligros de las nanopart\u00edculas - Nanotecnolog\u00eda","og_description":"Cient\u00edficos de la Universidad de California, en San Diego, y del Veterans Affairs Medical Healthcare System, en La Jolla, ha concluido recientemente que las nanopart\u00edculas magn\u00e9ticas pueden ser perjudiciales para la salud. Una serie de experimentos han revelado que las part\u00edculas de \u00f3xido de hierro de menos de 10 nan\u00f3metros de di\u00e1metro atrofian el crecimiento de las c\u00e9lulas nerviosas. Otros experimentos independientes, realizados in vitro en el National Institute of Standards and Technology (NIST), han concluido tambi\u00e9n que los nanotubos de menos de 200 nan\u00f3metros de largo interfieren en las c\u00e9lulas pulmonares humanas. Ambos grupos han hecho un llamamiento para","og_url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/","og_site_name":"Nanotecnolog\u00eda","article_published_time":"2007-04-17T10:15:00+00:00","article_modified_time":"2016-03-01T15:52:51+00:00","author":"Euroresidentes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Euroresidentes","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/","name":"Peligros de las nanopart\u00edculas - Nanotecnolog\u00eda","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website"},"datePublished":"2007-04-17T10:15:00+00:00","dateModified":"2016-03-01T15:52:51+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/peligros-de-las-nanopartculas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/"},{"@type":"ListItem","position":2,"name":"Peligros de las nanopart\u00edculas"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#website","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/","name":"Nanotecnolog\u00eda","description":"Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/8cb13da0909a9d75116f29d6910d0907","name":"Euroresidentes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-content\/uploads\/sites\/6\/2016\/03\/logo-euroresidentes-300x300-150x150.jpg","caption":"Euroresidentes"},"description":"EuroresidentesContenidos \u00fatiles que ayudan a resolver las necesidades grandes y peque\u00f1as de la vida cotidiana.","sameAs":["https:\/\/www.euroresidentes.com\/info.htm"],"url":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/author\/euroresidentes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts\/2011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/comments?post=2011"}],"version-history":[{"count":0,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/posts\/2011\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/media?parent=2011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/categories?post=2011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/tecnologia\/nanotecnologia\/wp-json\/wp\/v2\/tags?post=2011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}