{"id":282,"date":"2004-11-11T00:30:00","date_gmt":"2004-11-11T00:30:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar"},"modified":"2016-02-26T10:12:23","modified_gmt":"2016-02-26T10:12:23","slug":"un-embajador-de-espaa-llamado-aznar","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar","title":{"rendered":"Un embajador de Espa\u00f1a llamado Aznar"},"content":{"rendered":"<p>Nos hemos cansado de leer en todos los peri\u00f3dicos los esfuerzos de Aznar ante Bush, para que, m\u00e1s all\u00e1 de los intereses personales y de partido, Espa\u00f1a y los estados Unidos normalizaran sus relaciones. No pod\u00edamos esperar otra cosa de un ex presidente del gobierno, alguien que ha tenido la responsabilidad, honor y privilegio de representar a todos los espa\u00f1oles, de defender y luchar por nuestros intereses.<\/p>\n<p>Aznar sabe que Espa\u00f1a no se puede permitir el lujo de vivir de espaldas a Estados Unidos. Por eso, respald\u00f3 a Bush consciente de los errores y costes que conllevaba un planteamiento pol\u00edticamente equivocado: la guerra contra Irak. Por eso aquella sacrificada foto de las Azores, era una foto de Estado. Habr\u00e1 victimas humanas, ni\u00f1os, una guerra&#8230; pero era una responsabilidad de Estado, la legitimidad de la lucha contra el terrorismo, algo que no comprendimos muchos espa\u00f1oles con nuestras cr\u00edticas y protestas.<\/p>\n<p>Por eso ahora, como ex presidente, en l\u00ednea con los grandes estadistas, ha aprovechado los 40 minutos de entrevista privada con Bush para apoyar la normalizaci\u00f3n de las relaciones. Algo que no ha trascendido, por la modestia de Aznar. Lo estoy viendo&#8230; como si estuviera en la Casa Blanca mirando por un agujerito:<\/p>\n<p> En un momento dado Aznar sin perder la sonrisa, pero con gesto serio dijo:<\/p>\n<p>\u201cVamos a llamar al chico este, a  Zapatero, si no te importa&#8230;\u201d \u201cQuiero que sepas y sepa \u00e9l que los intereses de estado deben prevalecer entre Espa\u00f1a y los Estados Unidos\u201d&#8230; <\/p>\n<p>Bush le dijo, \u00abNo, ahora no me apetece\u00bb.<\/p>\n<p> Aznar le sentenci\u00f3 sin que le pudiera replicar: \u201cOye George, mi pa\u00eds se habr\u00e1 retirado de Irak, pero estuvimos y  ahora estamos en Afganist\u00e1n.  Te pido por la amistad que nos une, que le llames ahora\u201d.<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos hemos cansado de leer en todos los peri\u00f3dicos los esfuerzos de Aznar ante Bush, para que, m\u00e1s all\u00e1 de los intereses personales y de partido, Espa\u00f1a y los estados Unidos normalizaran sus relaciones. No pod\u00edamos esperar otra cosa de un ex presidente del gobierno, alguien que ha tenido la responsabilidad, honor y privilegio de representar a todos los espa\u00f1oles, de defender y luchar por nuestros intereses. Aznar sabe que Espa\u00f1a no se puede permitir el lujo de vivir de espaldas a Estados Unidos. Por eso, respald\u00f3 a Bush consciente de los errores y costes que conllevaba un planteamiento pol\u00edticamente <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[33,34],"class_list":["post-282","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","tag-politica-exterior","tag-pp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un embajador de Espa\u00f1a llamado Aznar - Rodr\u00edguez Zapatero<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un embajador de Espa\u00f1a llamado Aznar - Rodr\u00edguez Zapatero\" \/>\n<meta property=\"og:description\" content=\"Nos hemos cansado de leer en todos los peri\u00f3dicos los esfuerzos de Aznar ante Bush, para que, m\u00e1s all\u00e1 de los intereses personales y de partido, Espa\u00f1a y los estados Unidos normalizaran sus relaciones. No pod\u00edamos esperar otra cosa de un ex presidente del gobierno, alguien que ha tenido la responsabilidad, honor y privilegio de representar a todos los espa\u00f1oles, de defender y luchar por nuestros intereses. Aznar sabe que Espa\u00f1a no se puede permitir el lujo de vivir de espaldas a Estados Unidos. Por eso, respald\u00f3 a Bush consciente de los errores y costes que conllevaba un planteamiento pol\u00edticamente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar\" \/>\n<meta property=\"og:site_name\" content=\"Rodr\u00edguez Zapatero\" \/>\n<meta property=\"article:published_time\" content=\"2004-11-11T00:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-26T10:12:23+00:00\" \/>\n<meta name=\"author\" content=\"euroresidentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"euroresidentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar\",\"url\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar\",\"name\":\"Un embajador de Espa\u00f1a llamado Aznar - Rodr\u00edguez Zapatero\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/#website\"},\"datePublished\":\"2004-11-11T00:30:00+00:00\",\"dateModified\":\"2016-02-26T10:12:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/#\/schema\/person\/6d45fc03936dc2e80f83afd41105b88c\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un embajador de Espa\u00f1a llamado Aznar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/\",\"name\":\"Rodr\u00edguez Zapatero\",\"description\":\"Otro sitio m\u00e1s de Sitios de Social Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/#\/schema\/person\/6d45fc03936dc2e80f83afd41105b88c\",\"name\":\"euroresidentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-content\/uploads\/sites\/10\/2017\/01\/logo-euroresidentes-300x300-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-content\/uploads\/sites\/10\/2017\/01\/logo-euroresidentes-300x300-150x150.jpg\",\"caption\":\"euroresidentes\"},\"description\":\"EuroresidentesQueremos emocionar y sorprender a nuestros usuarios, transmitir pasi\u00f3n por la vida y ayudar a las personas a resolver las necesidades grandes y peque\u00f1as de su vida cotidiana.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/info.htm\"],\"url\":\"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/author\/euroresidentes\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un embajador de Espa\u00f1a llamado Aznar - Rodr\u00edguez Zapatero","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar","og_locale":"es_ES","og_type":"article","og_title":"Un embajador de Espa\u00f1a llamado Aznar - Rodr\u00edguez Zapatero","og_description":"Nos hemos cansado de leer en todos los peri\u00f3dicos los esfuerzos de Aznar ante Bush, para que, m\u00e1s all\u00e1 de los intereses personales y de partido, Espa\u00f1a y los estados Unidos normalizaran sus relaciones. No pod\u00edamos esperar otra cosa de un ex presidente del gobierno, alguien que ha tenido la responsabilidad, honor y privilegio de representar a todos los espa\u00f1oles, de defender y luchar por nuestros intereses. Aznar sabe que Espa\u00f1a no se puede permitir el lujo de vivir de espaldas a Estados Unidos. Por eso, respald\u00f3 a Bush consciente de los errores y costes que conllevaba un planteamiento pol\u00edticamente","og_url":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar","og_site_name":"Rodr\u00edguez Zapatero","article_published_time":"2004-11-11T00:30:00+00:00","article_modified_time":"2016-02-26T10:12:23+00:00","author":"euroresidentes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"euroresidentes","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar","url":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar","name":"Un embajador de Espa\u00f1a llamado Aznar - Rodr\u00edguez Zapatero","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/#website"},"datePublished":"2004-11-11T00:30:00+00:00","dateModified":"2016-02-26T10:12:23+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/#\/schema\/person\/6d45fc03936dc2e80f83afd41105b88c"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/un-embajador-de-espaa-llamado-aznar#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/"},{"@type":"ListItem","position":2,"name":"Un embajador de Espa\u00f1a llamado Aznar"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/#website","url":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/","name":"Rodr\u00edguez Zapatero","description":"Otro sitio m\u00e1s de Sitios de Social Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/#\/schema\/person\/6d45fc03936dc2e80f83afd41105b88c","name":"euroresidentes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-content\/uploads\/sites\/10\/2017\/01\/logo-euroresidentes-300x300-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-content\/uploads\/sites\/10\/2017\/01\/logo-euroresidentes-300x300-150x150.jpg","caption":"euroresidentes"},"description":"EuroresidentesQueremos emocionar y sorprender a nuestros usuarios, transmitir pasi\u00f3n por la vida y ayudar a las personas a resolver las necesidades grandes y peque\u00f1as de su vida cotidiana.","sameAs":["https:\/\/www.euroresidentes.com\/info.htm"],"url":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/author\/euroresidentes"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-json\/wp\/v2\/posts\/282"}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":1,"href":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-json\/wp\/v2\/posts\/282\/revisions"}],"predecessor-version":[{"id":384,"href":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-json\/wp\/v2\/posts\/282\/revisions\/384"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-json\/wp\/v2\/media?parent=282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-json\/wp\/v2\/categories?post=282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/social\/rodriguez-zapatero\/wp-json\/wp\/v2\/tags?post=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}