 

{"id":535,"date":"2018-03-11T05:24:00","date_gmt":"2018-03-11T04:24:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/salud\/salud-ninos\/enfermedad-manos-pies-y-boca"},"modified":"2019-08-21T15:14:20","modified_gmt":"2019-08-21T13:14:20","slug":"enfermedad-manos-pies-y-boca-en-ninos","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/","title":{"rendered":"\u00bfQu\u00e9 es la enfermedad manos, pies y boca?"},"content":{"rendered":"<h3>Enfermedad boca, mano, pie<\/h3>\n<p style=\"text-align: left;\">Es una enfermedad viral que afecta principalmente a lactantes y a ni\u00f1os<\/p>\n<div>\n<p style=\"text-align: left;\">La enfermedad de manos, pies y boca es una afecci\u00f3n viral com\u00fan, que por lo general se presenta en beb\u00e9s y ni\u00f1os menores de 5 a\u00f1os, aunque tambi\u00e9n puede afectar a los adultos.<\/p>\n<p style=\"text-align: left;\">Los s\u00edntomas de la enfermedad de manos, pies y boca incluyen <strong>fiebre<\/strong>, <strong>aftas en la boca<\/strong> y <strong>erupci\u00f3n en la piel<\/strong>, principalmente en las manos y en los pies. \u00a0<\/p>\n<p>\u00bfQuieres saber m\u00e1s?<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"https:\/\/euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/childhood-illnesses-s6-hand-foot-mouth-disease1.jpg\"><img decoding=\"async\" title=\"Enfermedad manos, pies y boca\" src=\"https:\/\/euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/childhood-illnesses-s6-hand-foot-mouth-disease1.jpg\" alt=\"Enfermedad manos, pies y boca\" border=\"0\" \/><\/a><\/div>\n<h3 style=\"text-align: left;\">\u00bfQu\u00e9 sabemos sobre la enfermedad manos, pies y boca?<\/h3>\n<p style=\"text-align: left;\">Es causada por virus de la familia <i>Coxsackie<\/i> y <i>Enterovirus<\/i>. <strong>Es una enfermedad altamente contagiosa aunque no grave.<\/strong> <b> <\/b><\/p>\n<p style=\"text-align: left;\">Por lo general, los s\u00edntomas de la enfermedad de manos, pies y boca comienzan con <b>fiebre<\/b>, y otros s\u00edntomas t\u00edpicos de otros infecciones virales como p\u00e9rdida del apetito, malestar leve y dolor de garganta. Poco despu\u00e9s del inicio de la fiebre suelen aparecer <b>lesiones dolorosas<\/b>\u00a0en la <b>boca<\/b>, primero como peque\u00f1os puntos rojos que luego se convierten en ampollas. Estas ves\u00edculas se acaban rompiendo generando lesiones similares a las aftas, que son dolorosas.<\/p>\n<p style=\"text-align: left;\">La <b>erupci\u00f3n en la piel<\/b> aparece despu\u00e9s de 1 o 2 d\u00edas, y consiste en <b>ves\u00edculas<\/b> o granitos, normalmente con l\u00edquido en su interior, que habitualmente aparecen en las <b>palmas de las manos<\/b> y las <b>plantas de los pies<\/b>, aunque tambi\u00e9n pueden salir en las rodillas, los codos, en los gl\u00fateos o en el \u00e1rea genital.<\/p>\n<div style=\"text-align: left;\">\n<h3>\u00bfC\u00f3mo se contagia la enfermedad manos, pies y boca?<\/h3>\n<p>La enfermedad de manos, pies y boca se transmite de persona a persona <b style=\"font-size: 16px;\">por contacto directo <\/b><span style=\"font-size: 16px;\">con el <\/span><b style=\"font-size: 16px;\">virus<\/b><span style=\"font-size: 16px;\"> causante de la enfermedad. Estos virus se encuentran en las <\/span><b style=\"font-size: 16px;\">secreciones de la nariz<\/b><span style=\"font-size: 16px;\"> y la garganta como la <\/span><b style=\"font-size: 16px;\">saliva<\/b><span style=\"font-size: 16px;\">, el esputo o el moco, y tambi\u00e9n se encuentra en el <\/span><b style=\"font-size: 16px;\">l\u00edquido de las ampollas<\/b><span style=\"font-size: 16px;\"> y en las<\/span><b style=\"font-size: 16px;\"> heces<\/b><span style=\"font-size: 16px;\"> de las personas infectadas.<\/span><\/p>\n<p>Las personas infectadas son <b style=\"font-size: 16px;\">m\u00e1s contagiosas durante la primera semana<\/b><span style=\"font-size: 16px;\"> de la enfermedad, y aunque hayan desaparecido los s\u00edntomas, los virus que causan la enfermedad de manos, pies y boca pueden permanecer en el organismo durante semanas.<\/span><\/p>\n<p>La recuperaci\u00f3n completa se da en 5 a 7 d\u00edas.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<h3>\u00bfSe puede prevenir la enfermedad?<\/h3>\n<p style=\"text-align: left;\">No existe ninguna vacuna que proteja frente a los virus que causan la enfermedad de manos, pies y boca. Se puede intentar reducir el riesgo de infecci\u00f3n con una serie de acciones simples como:<\/p>\n<\/div>\n<ul>\n<li style=\"text-align: left;\"><b>Lavarse<\/b>\u00a0<b>las manos<\/b> con agua y jab\u00f3n con frecuencia, especialmente despu\u00e9s de cambiar pa\u00f1ales y de ir al ba\u00f1o.<\/li>\n<li style=\"text-align: left;\"><b>Desinfectar<\/b> las superficies y objetos sucios, incluidos los juguetes.<\/li>\n<li style=\"text-align: left;\"><b>Evitar el contacto <\/b>o <b>compartir<\/b> los vasos o utensilios con personas que tienen la enfermedad de manos, pies y boca.<\/li>\n<\/ul>\n<div style=\"text-align: justify;\">\n<h3 style=\"text-align: left;\"><a href=\"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-4780\" src=\"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie.jpeg\" alt=\"Enfermedad boca-mano-pie\" width=\"700\" height=\"525\" srcset=\"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie.jpeg 700w, https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie-300x225.jpeg 300w, https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie-396x297.jpeg 396w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/h3>\n<h3>\u00bfExiste alg\u00fan tratamiento para la enfermedad manos, pies y boca?<\/h3>\n<p style=\"text-align: left;\">No, no existe ning\u00fan tratamiento espec\u00edfico para la enfermedad de manos, pies y boca. Se pueden adoptar una serie de medidas sencillas para aliviar los s\u00edntomas, como:<\/p>\n<\/div>\n<ul>\n<li style=\"text-align: justify;\">Usar f\u00e1rmacos para aliviar el dolor y la <a href=\"https:\/\/www.euroresidentes.com\/salud\/fiebre-en-ninos\/\">fiebre<\/a>.<\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/que-sabes-sobre-los-enjuagues-bucales\">Enjuagues bucales<\/a> con agua con sal (1\/2 cucharadita de sal en 1 vaso de agua tibia) pueden servir como calmante.<\/li>\n<\/ul>\n<p><b>Lecturas relacionadas:<\/b><\/p>\n<ul>\n<li><a href=\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/no-nos-lavamos-las-manos-correctamente\">C\u00f3mo lavarse las manos correctamente<\/a><\/li>\n<li><a href=\"https:\/\/www.euroresidentes.com\/salud\/como-evitar-que-los-ninos-enfermen\/\">C\u00f3mo evitar que los ni\u00f1os enfermen<\/a><\/li>\n<li><a href=\"https:\/\/www.euroresidentes.com\/salud\/uso-de-paracetamol-en-ninos\/\">\u00bfCu\u00e1l es la dosis de paracetamol para un ni\u00f1o?<\/a><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Enfermedad boca, mano, pie Es una enfermedad viral que afecta principalmente a lactantes y a ni\u00f1os La enfermedad de manos, pies y boca es una afecci\u00f3n viral com\u00fan, que por lo general se presenta en beb\u00e9s y ni\u00f1os menores de 5 a\u00f1os, aunque tambi\u00e9n puede afectar a los adultos. Los s\u00edntomas de la enfermedad de manos, pies y boca incluyen fiebre, aftas en la boca y erupci\u00f3n en la piel, principalmente en las manos y en los pies. \u00a0 \u00bfQuieres saber m\u00e1s? \u00bfQu\u00e9 sabemos sobre la enfermedad manos, pies y boca? Es causada por virus de la familia Coxsackie y <\/p>\n","protected":false},"author":2,"featured_media":4780,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ninos","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 es la enfermedad manos, pies y boca? - Salud<\/title>\n<meta name=\"description\" content=\"La enfermedad de manos, pies y boca es una afecci\u00f3n viral com\u00fan. Se suele presenta en ni\u00f1os menores de 5 a\u00f1os, aunque tambi\u00e9n puede afectar a los adultos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es la enfermedad manos, pies y boca? - Salud\" \/>\n<meta property=\"og:description\" content=\"La enfermedad de manos, pies y boca es una afecci\u00f3n viral com\u00fan. Se suele presenta en ni\u00f1os menores de 5 a\u00f1os, aunque tambi\u00e9n puede afectar a los adultos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/\" \/>\n<meta property=\"og:site_name\" content=\"Salud\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-11T04:24:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-21T13:14:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Raquel Pomares\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel Pomares\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/\"},\"author\":{\"name\":\"Raquel Pomares\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/#\/schema\/person\/c0299534643677f2282b416ac1fe97f1\"},\"headline\":\"\u00bfQu\u00e9 es la enfermedad manos, pies y boca?\",\"datePublished\":\"2018-03-11T04:24:00+00:00\",\"dateModified\":\"2019-08-21T13:14:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/\"},\"wordCount\":577,\"commentCount\":127,\"image\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie.jpeg\",\"articleSection\":[\"Ni\u00f1os\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/\",\"url\":\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/\",\"name\":\"\u00bfQu\u00e9 es la enfermedad manos, pies y boca? - Salud\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie.jpeg\",\"datePublished\":\"2018-03-11T04:24:00+00:00\",\"dateModified\":\"2019-08-21T13:14:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/#\/schema\/person\/c0299534643677f2282b416ac1fe97f1\"},\"description\":\"La enfermedad de manos, pies y boca es una afecci\u00f3n viral com\u00fan. Se suele presenta en ni\u00f1os menores de 5 a\u00f1os, aunque tambi\u00e9n puede afectar a los adultos.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#primaryimage\",\"url\":\"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie.jpeg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie.jpeg\",\"width\":700,\"height\":525,\"caption\":\"Enfermedad boca-mano-pie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/salud\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es la enfermedad manos, pies y boca?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/salud\/\",\"name\":\"Salud\",\"description\":\"Consejos para el cuidado de la salud, vida sana, h\u00e1bitos saludables\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/salud\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/#\/schema\/person\/c0299534643677f2282b416ac1fe97f1\",\"name\":\"Raquel Pomares\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2016\/07\/YO2-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2016\/07\/YO2-150x150.jpg\",\"caption\":\"Raquel Pomares\"},\"description\":\"Raquel PomaresBi\u00f3loga, doctora y divulgadora cient\u00edfica especializada en temas de salud.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/salud\/raquel-pomares.html\"],\"url\":\"https:\/\/www.euroresidentes.com\/salud\/author\/raquel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es la enfermedad manos, pies y boca? - Salud","description":"La enfermedad de manos, pies y boca es una afecci\u00f3n viral com\u00fan. Se suele presenta en ni\u00f1os menores de 5 a\u00f1os, aunque tambi\u00e9n puede afectar a los adultos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es la enfermedad manos, pies y boca? - Salud","og_description":"La enfermedad de manos, pies y boca es una afecci\u00f3n viral com\u00fan. Se suele presenta en ni\u00f1os menores de 5 a\u00f1os, aunque tambi\u00e9n puede afectar a los adultos.","og_url":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/","og_site_name":"Salud","article_published_time":"2018-03-11T04:24:00+00:00","article_modified_time":"2019-08-21T13:14:20+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie.jpeg","type":"image\/jpeg"}],"author":"Raquel Pomares","twitter_misc":{"Written by":"Raquel Pomares","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#article","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/"},"author":{"name":"Raquel Pomares","@id":"https:\/\/www.euroresidentes.com\/salud\/#\/schema\/person\/c0299534643677f2282b416ac1fe97f1"},"headline":"\u00bfQu\u00e9 es la enfermedad manos, pies y boca?","datePublished":"2018-03-11T04:24:00+00:00","dateModified":"2019-08-21T13:14:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/"},"wordCount":577,"commentCount":127,"image":{"@id":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie.jpeg","articleSection":["Ni\u00f1os"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/","url":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/","name":"\u00bfQu\u00e9 es la enfermedad manos, pies y boca? - Salud","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/salud\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#primaryimage"},"image":{"@id":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie.jpeg","datePublished":"2018-03-11T04:24:00+00:00","dateModified":"2019-08-21T13:14:20+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/salud\/#\/schema\/person\/c0299534643677f2282b416ac1fe97f1"},"description":"La enfermedad de manos, pies y boca es una afecci\u00f3n viral com\u00fan. Se suele presenta en ni\u00f1os menores de 5 a\u00f1os, aunque tambi\u00e9n puede afectar a los adultos.","breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#primaryimage","url":"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie.jpeg","contentUrl":"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2018\/03\/boca-mano-pie.jpeg","width":700,"height":525,"caption":"Enfermedad boca-mano-pie"},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/salud\/enfermedad-manos-pies-y-boca-en-ninos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/salud\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es la enfermedad manos, pies y boca?"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/salud\/#website","url":"https:\/\/www.euroresidentes.com\/salud\/","name":"Salud","description":"Consejos para el cuidado de la salud, vida sana, h\u00e1bitos saludables","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/salud\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/salud\/#\/schema\/person\/c0299534643677f2282b416ac1fe97f1","name":"Raquel Pomares","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/salud\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2016\/07\/YO2-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/salud\/wp-content\/uploads\/2016\/07\/YO2-150x150.jpg","caption":"Raquel Pomares"},"description":"Raquel PomaresBi\u00f3loga, doctora y divulgadora cient\u00edfica especializada en temas de salud.","sameAs":["https:\/\/www.euroresidentes.com\/salud\/raquel-pomares.html"],"url":"https:\/\/www.euroresidentes.com\/salud\/author\/raquel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/salud\/wp-json\/wp\/v2\/posts\/535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/salud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/salud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/salud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/salud\/wp-json\/wp\/v2\/comments?post=535"}],"version-history":[{"count":9,"href":"https:\/\/www.euroresidentes.com\/salud\/wp-json\/wp\/v2\/posts\/535\/revisions"}],"predecessor-version":[{"id":6929,"href":"https:\/\/www.euroresidentes.com\/salud\/wp-json\/wp\/v2\/posts\/535\/revisions\/6929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/salud\/wp-json\/wp\/v2\/media\/4780"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/salud\/wp-json\/wp\/v2\/media?parent=535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/salud\/wp-json\/wp\/v2\/categories?post=535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/salud\/wp-json\/wp\/v2\/tags?post=535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}