 

{"id":1850,"date":"2015-03-12T10:59:00","date_gmt":"2015-03-12T09:59:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria"},"modified":"2017-03-24T19:48:50","modified_gmt":"2017-03-24T18:48:50","slug":"descubren-un-tratamiento-que-podria","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/","title":{"rendered":"Descubren un tratamiento que podr\u00eda restaurar la memoria en los enfermos de Alzheimer"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: center;\">\n<a href=\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2015\/03\/nuevo-tratamiento-para-restaurar-la-memoria-en-los-enfermos-de-alzheimer1.jpg\" imageanchor=\"1\" style=\"margin-left: 1em; margin-right: 1em;\"><img decoding=\"async\" alt=\"Descubren un tratamiento que podr\u00eda restaurar la memoria en los enfermos de Alzheimer\" border=\"0\" src=\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2015\/03\/nuevo-tratamiento-para-restaurar-la-memoria-en-los-enfermos-de-alzheimer1.jpg\" title=\"Descubren un tratamiento que podr\u00eda restaurar la memoria en los enfermos de Alzheimer\" \/><\/a><\/div>\n<h3 style=\"text-align: justify;\">\n<\/h3>\n<h3 style=\"text-align: justify;\">\nUna nueva investigaci\u00f3n presenta una forma no farmacol\u00f3gica de eliminar el p\u00e9ptido amiloide del cerebro y de restaurar la memoria en un modelo de rat\u00f3n de enfermedad de Alzheimer.<\/h3>\n<div style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\">\nLa <b>acumulaci\u00f3n del p\u00e9ptido \u03b2-amiloide<\/b> se ha implicado en la patog\u00e9nesis de la enfermedad de Alzheimer. Los medicamentos que actualmente se utilizan para el tratamiento de la enfermedad de Alzheimer s\u00f3lo ayudan a mejorar un poco el rendimiento de la memoria durante un corto per\u00edodo de tiempo.&nbsp;<\/div>\n<div style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\">\nInvestigadores australianos han usado una novedosa t\u00e9cnica en ratones modificados gen\u00e9ticamente y han conseguido restaurar su memoria al mismo nivel que la que ten\u00edan los ratones sanos. El nuevo tratamiento utiliza <b>tecnolog\u00eda de ultrasonido<\/b> para ayudar a <b>despegar<\/b> la <b>placa de prote\u00edna \u03b2-amiloide<\/b> que se acumula en el cerebro de los enfermos de Alzheimer.&nbsp;<\/div>\n<div style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\">\nAunque este estudio se ha realizado en ratones modificados gen\u00e9ticamente, los autores tienen esperanzas de que este nuevo tratamiento sea una <b>opci\u00f3n terap\u00e9utica futura para los seres humanos<\/b>. El cerebro humano es m\u00e1s complejo y la cognici\u00f3n humana m\u00e1s compleja, pero si se consigue reducir los niveles de prote\u00edna amiloide en fases tempranas de la enfermedad, cuando est\u00e1 empezando a acumularse en el cerebro humano, los autores creen que con este nuevo tratamiento se podr\u00eda rescatar el deterioro de la memoria asociado al Alzheimer.<\/div>\n<div style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\">\nLos autores est\u00e1n dise\u00f1ando un dispositivo de ultrasonido m\u00e1s grande para probar en los cerebros de ovejas antes probando en humanos.&nbsp;<\/div>\n<div style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\">\n<br \/>\nLeinenga G y G\u00f6tz J. Science Translational Medicine (2015). <a href=\"http:\/\/stm.sciencemag.org\/content\/7\/278\/278ra33#corresp-1\" rel=\"nofollow\" target=\"_blank\">M\u00e1s informaci\u00f3n<\/a>.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<b>Seguir leyendo:&nbsp;<\/b><\/div>\n<div style=\"text-align: justify;\">\n<\/div>\n<ul>\n<li><a href=\"http:\/\/conviviendo-alzheimer.euroresidentes.com\/\" target=\"_blank\">Conviviendo con el Alzheimer<\/a><\/li>\n<li><a href=\"http:\/\/salud-hoy.euroresidentes.com\/2015\/02\/un-nuevo-tratamiento-podria-detener-la.html\" target=\"_blank\">Un nuevo tratamiento podr\u00eda detener la progresi\u00f3n del Alzheimer<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Una nueva investigaci\u00f3n presenta una forma no farmacol\u00f3gica de eliminar el p\u00e9ptido amiloide del cerebro y de restaurar la memoria en un modelo de rat\u00f3n de enfermedad de Alzheimer. La acumulaci\u00f3n del p\u00e9ptido \u03b2-amiloide se ha implicado en la patog\u00e9nesis de la enfermedad de Alzheimer. Los medicamentos que actualmente se utilizan para el tratamiento de la enfermedad de Alzheimer s\u00f3lo ayudan a mejorar un poco el rendimiento de la memoria durante un corto per\u00edodo de tiempo.&nbsp; Investigadores australianos han usado una novedosa t\u00e9cnica en ratones modificados gen\u00e9ticamente y han conseguido restaurar su memoria al mismo nivel que la que ten\u00edan <\/p>\n","protected":false},"author":2,"featured_media":2328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alzheimer","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Descubren un tratamiento que podr\u00eda restaurar la memoria en los enfermos de Alzheimer - Salud hoy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descubren un tratamiento que podr\u00eda restaurar la memoria en los enfermos de Alzheimer - Salud hoy\" \/>\n<meta property=\"og:description\" content=\"Una nueva investigaci\u00f3n presenta una forma no farmacol\u00f3gica de eliminar el p\u00e9ptido amiloide del cerebro y de restaurar la memoria en un modelo de rat\u00f3n de enfermedad de Alzheimer. La acumulaci\u00f3n del p\u00e9ptido \u03b2-amiloide se ha implicado en la patog\u00e9nesis de la enfermedad de Alzheimer. Los medicamentos que actualmente se utilizan para el tratamiento de la enfermedad de Alzheimer s\u00f3lo ayudan a mejorar un poco el rendimiento de la memoria durante un corto per\u00edodo de tiempo.&nbsp; Investigadores australianos han usado una novedosa t\u00e9cnica en ratones modificados gen\u00e9ticamente y han conseguido restaurar su memoria al mismo nivel que la que ten\u00edan\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/\" \/>\n<meta property=\"og:site_name\" content=\"Salud hoy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Salud-Euroresidentes-399995783365932\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-12T09:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-03-24T18:48:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2015\/03\/nuevo-tratamiento-para-restaurar-la-memoria-en-los-enfermos-de-alzheimer1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Raquel Pomares\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel Pomares\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/\"},\"author\":{\"name\":\"Raquel Pomares\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/#\/schema\/person\/c0299534643677f2282b416ac1fe97f1\"},\"headline\":\"Descubren un tratamiento que podr\u00eda restaurar la memoria en los enfermos de Alzheimer\",\"datePublished\":\"2015-03-12T09:59:00+00:00\",\"dateModified\":\"2017-03-24T18:48:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/\"},\"wordCount\":308,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2015\/03\/nuevo-tratamiento-para-restaurar-la-memoria-en-los-enfermos-de-alzheimer1.jpg\",\"articleSection\":[\"Alzheimer\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/\",\"url\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/\",\"name\":\"Descubren un tratamiento que podr\u00eda restaurar la memoria en los enfermos de Alzheimer - Salud hoy\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2015\/03\/nuevo-tratamiento-para-restaurar-la-memoria-en-los-enfermos-de-alzheimer1.jpg\",\"datePublished\":\"2015-03-12T09:59:00+00:00\",\"dateModified\":\"2017-03-24T18:48:50+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/#\/schema\/person\/c0299534643677f2282b416ac1fe97f1\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#primaryimage\",\"url\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2015\/03\/nuevo-tratamiento-para-restaurar-la-memoria-en-los-enfermos-de-alzheimer1.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2015\/03\/nuevo-tratamiento-para-restaurar-la-memoria-en-los-enfermos-de-alzheimer1.jpg\",\"width\":600,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descubren un tratamiento que podr\u00eda restaurar la memoria en los enfermos de Alzheimer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/\",\"name\":\"Salud hoy\",\"description\":\"Salud hoy Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/#\/schema\/person\/c0299534643677f2282b416ac1fe97f1\",\"name\":\"Raquel Pomares\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2016\/09\/raquel-pomares-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2016\/09\/raquel-pomares-150x150.jpg\",\"caption\":\"Raquel Pomares\"},\"description\":\"Raquel PomaresBi\u00f3loga, doctora y divulgadora cient\u00edfica especializada en temas de salud.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/salud\/raquel-pomares.html\"],\"url\":\"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/author\/raquel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descubren un tratamiento que podr\u00eda restaurar la memoria en los enfermos de Alzheimer - Salud hoy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/","og_locale":"es_ES","og_type":"article","og_title":"Descubren un tratamiento que podr\u00eda restaurar la memoria en los enfermos de Alzheimer - Salud hoy","og_description":"Una nueva investigaci\u00f3n presenta una forma no farmacol\u00f3gica de eliminar el p\u00e9ptido amiloide del cerebro y de restaurar la memoria en un modelo de rat\u00f3n de enfermedad de Alzheimer. La acumulaci\u00f3n del p\u00e9ptido \u03b2-amiloide se ha implicado en la patog\u00e9nesis de la enfermedad de Alzheimer. Los medicamentos que actualmente se utilizan para el tratamiento de la enfermedad de Alzheimer s\u00f3lo ayudan a mejorar un poco el rendimiento de la memoria durante un corto per\u00edodo de tiempo.&nbsp; Investigadores australianos han usado una novedosa t\u00e9cnica en ratones modificados gen\u00e9ticamente y han conseguido restaurar su memoria al mismo nivel que la que ten\u00edan","og_url":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/","og_site_name":"Salud hoy","article_publisher":"https:\/\/www.facebook.com\/Salud-Euroresidentes-399995783365932\/","article_published_time":"2015-03-12T09:59:00+00:00","article_modified_time":"2017-03-24T18:48:50+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2015\/03\/nuevo-tratamiento-para-restaurar-la-memoria-en-los-enfermos-de-alzheimer1.jpg","type":"image\/jpeg"}],"author":"Raquel Pomares","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Raquel Pomares","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#article","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/"},"author":{"name":"Raquel Pomares","@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/#\/schema\/person\/c0299534643677f2282b416ac1fe97f1"},"headline":"Descubren un tratamiento que podr\u00eda restaurar la memoria en los enfermos de Alzheimer","datePublished":"2015-03-12T09:59:00+00:00","dateModified":"2017-03-24T18:48:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/"},"wordCount":308,"commentCount":0,"image":{"@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2015\/03\/nuevo-tratamiento-para-restaurar-la-memoria-en-los-enfermos-de-alzheimer1.jpg","articleSection":["Alzheimer"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/","url":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/","name":"Descubren un tratamiento que podr\u00eda restaurar la memoria en los enfermos de Alzheimer - Salud hoy","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#primaryimage"},"image":{"@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2015\/03\/nuevo-tratamiento-para-restaurar-la-memoria-en-los-enfermos-de-alzheimer1.jpg","datePublished":"2015-03-12T09:59:00+00:00","dateModified":"2017-03-24T18:48:50+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/#\/schema\/person\/c0299534643677f2282b416ac1fe97f1"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#primaryimage","url":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2015\/03\/nuevo-tratamiento-para-restaurar-la-memoria-en-los-enfermos-de-alzheimer1.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2015\/03\/nuevo-tratamiento-para-restaurar-la-memoria-en-los-enfermos-de-alzheimer1.jpg","width":600,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/descubren-un-tratamiento-que-podria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/"},{"@type":"ListItem","position":2,"name":"Descubren un tratamiento que podr\u00eda restaurar la memoria en los enfermos de Alzheimer"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/#website","url":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/","name":"Salud hoy","description":"Salud hoy Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/#\/schema\/person\/c0299534643677f2282b416ac1fe97f1","name":"Raquel Pomares","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2016\/09\/raquel-pomares-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-content\/uploads\/sites\/9\/2016\/09\/raquel-pomares-150x150.jpg","caption":"Raquel Pomares"},"description":"Raquel PomaresBi\u00f3loga, doctora y divulgadora cient\u00edfica especializada en temas de salud.","sameAs":["https:\/\/www.euroresidentes.com\/salud\/raquel-pomares.html"],"url":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/author\/raquel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-json\/wp\/v2\/posts\/1850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-json\/wp\/v2\/comments?post=1850"}],"version-history":[{"count":1,"href":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-json\/wp\/v2\/posts\/1850\/revisions"}],"predecessor-version":[{"id":2329,"href":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-json\/wp\/v2\/posts\/1850\/revisions\/2329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-json\/wp\/v2\/media\/2328"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-json\/wp\/v2\/media?parent=1850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-json\/wp\/v2\/categories?post=1850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/salud\/salud-hoy\/wp-json\/wp\/v2\/tags?post=1850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}