{"id":1020,"date":"2004-11-13T07:46:00","date_gmt":"2004-11-13T07:46:00","guid":{"rendered":"http:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en"},"modified":"2017-01-09T12:42:56","modified_gmt":"2017-01-09T11:42:56","slug":"las-hipotecas-marcan-un-alza-rcord-en","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/","title":{"rendered":"Las hipotecas marcan un alza r\u00e9cord en septiembre"},"content":{"rendered":"<p>Los \u00faltimos datos confirman que el sector de la vivienda no quiere parar. La concesi\u00f3n de hipotecas sigue con r\u00e9cords hist\u00f3ricos. Seg\u00fan datos de la Asociaci\u00f3n Hipotecaria de Espa\u00f1a, en el pasado mes de septiembre se registr\u00f3 el mayor incremento (del 25,3%) en la concesi\u00f3n de pr\u00e9stamos hipotecarios desde 1996.<\/p>\n<p>Sin embargo, hay que se\u00f1alar que \u00ab<em>en estos momentos se estar\u00edan escriturando, y por tanto hipotecando, las viviendas que se vendieron sobre plano hace m\u00e1s de dieciocho meses<\/em>\u00ab, afirman. Este retraso har\u00e1 que el auge se mantenga en la concesi\u00f3n de hipotecas al menos durante este a\u00f1o y el pr\u00f3ximo, aunque las ventas y el auge de la vivienda decrezca en estos momentos.<\/p>\n<p>El crecimiento del saldo hipotecario acumulado en lo que va de a\u00f1o es ya del 17,8%, muy cerca del aumento del 18% que preve\u00eda la Asociaci\u00f3n Hipotecaria para todo el 2004. Se prev\u00e9 un incremento neto del cr\u00e9dito hipotecario del 22% (ligeramente inferior a la tasa de aumento del 24% que se registr\u00f3 el a\u00f1o anterior).<br \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los \u00faltimos datos confirman que el sector de la vivienda no quiere parar. La concesi\u00f3n de hipotecas sigue con r\u00e9cords hist\u00f3ricos. Seg\u00fan datos de la Asociaci\u00f3n Hipotecaria de Espa\u00f1a, en el pasado mes de septiembre se registr\u00f3 el mayor incremento (del 25,3%) en la concesi\u00f3n de pr\u00e9stamos hipotecarios desde 1996. Sin embargo, hay que se\u00f1alar que \u00aben estos momentos se estar\u00edan escriturando, y por tanto hipotecando, las viviendas que se vendieron sobre plano hace m\u00e1s de dieciocho meses\u00ab, afirman. Este retraso har\u00e1 que el auge se mantenga en la concesi\u00f3n de hipotecas al menos durante este a\u00f1o y el pr\u00f3ximo, <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[35,27],"class_list":["post-1020","post","type-post","status-publish","format-standard","hentry","category-general","tag-coyuntura","tag-hipotecas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las hipotecas marcan un alza r\u00e9cord en septiembre - Noticias vivienda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las hipotecas marcan un alza r\u00e9cord en septiembre - Noticias vivienda\" \/>\n<meta property=\"og:description\" content=\"Los \u00faltimos datos confirman que el sector de la vivienda no quiere parar. La concesi\u00f3n de hipotecas sigue con r\u00e9cords hist\u00f3ricos. Seg\u00fan datos de la Asociaci\u00f3n Hipotecaria de Espa\u00f1a, en el pasado mes de septiembre se registr\u00f3 el mayor incremento (del 25,3%) en la concesi\u00f3n de pr\u00e9stamos hipotecarios desde 1996. Sin embargo, hay que se\u00f1alar que \u00aben estos momentos se estar\u00edan escriturando, y por tanto hipotecando, las viviendas que se vendieron sobre plano hace m\u00e1s de dieciocho meses\u00ab, afirman. Este retraso har\u00e1 que el auge se mantenga en la concesi\u00f3n de hipotecas al menos durante este a\u00f1o y el pr\u00f3ximo,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias vivienda\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/euroresidentes\/\" \/>\n<meta property=\"article:published_time\" content=\"2004-11-13T07:46:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-09T11:42:56+00:00\" \/>\n<meta name=\"author\" content=\"Euroresidentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Euroresidentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/\",\"url\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/\",\"name\":\"Las hipotecas marcan un alza r\u00e9cord en septiembre - Noticias vivienda\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/#website\"},\"datePublished\":\"2004-11-13T07:46:00+00:00\",\"dateModified\":\"2017-01-09T11:42:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/#\/schema\/person\/072d6dc5ad9406b70bb3499e911bb321\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las hipotecas marcan un alza r\u00e9cord en septiembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/\",\"name\":\"Noticias vivienda\",\"description\":\"Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/#\/schema\/person\/072d6dc5ad9406b70bb3499e911bb321\",\"name\":\"Euroresidentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-content\/uploads\/sites\/9\/2016\/08\/logo-euroresidentes-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-content\/uploads\/sites\/9\/2016\/08\/logo-euroresidentes-150x150.jpg\",\"caption\":\"Euroresidentes\"},\"description\":\"EuroresidentesContenidos \u00fatiles para resolver las necesidades grandes y peque\u00f1as de la vida cotidiana.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/info.htm\"],\"url\":\"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/author\/euroresidentes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las hipotecas marcan un alza r\u00e9cord en septiembre - Noticias vivienda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/","og_locale":"es_ES","og_type":"article","og_title":"Las hipotecas marcan un alza r\u00e9cord en septiembre - Noticias vivienda","og_description":"Los \u00faltimos datos confirman que el sector de la vivienda no quiere parar. La concesi\u00f3n de hipotecas sigue con r\u00e9cords hist\u00f3ricos. Seg\u00fan datos de la Asociaci\u00f3n Hipotecaria de Espa\u00f1a, en el pasado mes de septiembre se registr\u00f3 el mayor incremento (del 25,3%) en la concesi\u00f3n de pr\u00e9stamos hipotecarios desde 1996. Sin embargo, hay que se\u00f1alar que \u00aben estos momentos se estar\u00edan escriturando, y por tanto hipotecando, las viviendas que se vendieron sobre plano hace m\u00e1s de dieciocho meses\u00ab, afirman. Este retraso har\u00e1 que el auge se mantenga en la concesi\u00f3n de hipotecas al menos durante este a\u00f1o y el pr\u00f3ximo,","og_url":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/","og_site_name":"Noticias vivienda","article_publisher":"https:\/\/www.facebook.com\/euroresidentes\/","article_published_time":"2004-11-13T07:46:00+00:00","article_modified_time":"2017-01-09T11:42:56+00:00","author":"Euroresidentes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Euroresidentes","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/","url":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/","name":"Las hipotecas marcan un alza r\u00e9cord en septiembre - Noticias vivienda","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/#website"},"datePublished":"2004-11-13T07:46:00+00:00","dateModified":"2017-01-09T11:42:56+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/#\/schema\/person\/072d6dc5ad9406b70bb3499e911bb321"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/las-hipotecas-marcan-un-alza-rcord-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/"},{"@type":"ListItem","position":2,"name":"Las hipotecas marcan un alza r\u00e9cord en septiembre"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/#website","url":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/","name":"Noticias vivienda","description":"Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/#\/schema\/person\/072d6dc5ad9406b70bb3499e911bb321","name":"Euroresidentes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-content\/uploads\/sites\/9\/2016\/08\/logo-euroresidentes-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-content\/uploads\/sites\/9\/2016\/08\/logo-euroresidentes-150x150.jpg","caption":"Euroresidentes"},"description":"EuroresidentesContenidos \u00fatiles para resolver las necesidades grandes y peque\u00f1as de la vida cotidiana.","sameAs":["https:\/\/www.euroresidentes.com\/info.htm"],"url":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/author\/euroresidentes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-json\/wp\/v2\/posts\/1020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-json\/wp\/v2\/comments?post=1020"}],"version-history":[{"count":1,"href":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-json\/wp\/v2\/posts\/1020\/revisions"}],"predecessor-version":[{"id":1498,"href":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-json\/wp\/v2\/posts\/1020\/revisions\/1498"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-json\/wp\/v2\/media?parent=1020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-json\/wp\/v2\/categories?post=1020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/hogar\/noticias-vivienda\/wp-json\/wp\/v2\/tags?post=1020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}