{"id":343,"date":"2015-04-22T16:43:00","date_gmt":"2015-04-22T16:43:00","guid":{"rendered":"http:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con"},"modified":"2016-08-16T13:03:44","modified_gmt":"2016-08-16T11:03:44","slug":"9-habitos-de-las-personas-con","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/","title":{"rendered":"9 H\u00e1bitos de las personas con Inteligencia Emocional"},"content":{"rendered":"<p>La Inteligencia Emocional (IE) es importante en nuestras vidas. Eso es algo que est\u00e1 ya m\u00e1s que demostrado.\u00a0<\/p>\n<div class=\"separator\" style=\"clear: both;text-align: center\"><a href=\"http:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/habitos-personas-inteligencia-emocional.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6080\" src=\"http:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/habitos-personas-inteligencia-emocional.jpg\" alt=\"H\u00e1bitos de las personas con Inteligencia Emocional\" width=\"700\" height=\"525\" srcset=\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/habitos-personas-inteligencia-emocional.jpg 700w, https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/habitos-personas-inteligencia-emocional-300x225.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><a href=\"http:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/habitos-personas-inteligencia-emocional.jpg\"><br \/> <\/a><\/div>\n<div class=\"separator\" style=\"clear: both;text-align: left\">Las personas con una alta Inteligencia Emocional\u00a0no lo son porque les ha ca\u00eddo del cielo. Siguen h\u00e1bitos y pautas para conseguir ser \u00a0inteligentes emocionalmente.<\/div>\n<div class=\"separator\" style=\"clear: both;text-align: left\">Hemos creado una <strong>infograf\u00eda de algunos h\u00e1bitos que siguen las personas emocionalmente inteligentes<\/strong>. Se trata de h\u00e1bitos muy sencillos para poner en pr\u00e1ctica ya mismo si quieres. Abajo te dejo la descripci\u00f3n de cada h\u00e1bito.<\/div>\n<div class=\"separator\" style=\"clear: both;text-align: left\">\u00c9chales un vistazo y a empezar. \u00bfPreparad@?\u00a0<\/div>\n<div class=\"separator\" style=\"clear: both;text-align: center\"><a style=\"margin-left: 1em;margin-right: 1em\" href=\"http:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/Inteligencia-Emocional-694x10241.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"\" title=\"9 H\u00e1bitos de las personas con Inteligencia Emocional\" src=\"http:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/Inteligencia-Emocional-694x10241.jpg\" alt=\"9 H\u00e1bitos de las personas con Inteligencia Emocional\" width=\"441\" height=\"650\" border=\"0\" \/><\/a><\/div>\n<h4><b>1. Est\u00e1n centradas en lo positivo.<\/b><\/h4>\n<p>Buscan soluciones a los problemas y se centran en todo lo que est\u00e1 dentro de su control. No pierden ni tiempo ni energ\u00eda en cuestiones que saben escapan a su alcance.\u00a0<\/p>\n<h4><b>2. Se rodean de gente c\u00e1lida.<\/b><\/h4>\n<p>Eso de \u00aberes el promedio de las 5 personas con las que m\u00e1s tiempo pasas\u00bb las personas IE lo conocen muy bien. No se contagian de negativistas.<\/p>\n<h4><b>3. Se conectan y solucionan.<\/b><\/h4>\n<p>Sus pensamientos los pasan a la acci\u00f3n. Nunca se quedar\u00e1n con la duda de \u00abqu\u00e9 habr\u00eda pasado si&#8230;?\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"http:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/h-bitos-personas-con-inteligencia-emocional.jpg\" alt=\"H\u00e1bitos de las personas con Inteligencia Emocional\" width=\"700\" height=\"525\" border=\"0\" \/><\/p>\n<p><b>4. Capaces de poner l\u00edmites.<\/b><\/p>\n<p>Saben decir no. Y saben que llega un momento en el que es mejor parar y reflexionar sobre el recorrido hecho que avanzar y avanzar y avanzar sin sentido.<\/p>\n<p><b>5. Piensan y miran hacia delante.<\/b><\/p>\n<p>Est\u00e1n en paz con su pasado. Puede haber sido peor o mejor pero no dejan que les atrape.\u00a0<\/p>\n<p><b>6. Aprenden de sus errores.\u00a0<\/b><\/p>\n<p>Fallar\u00e1n como cualquier ser humano, pero ese error les servir\u00e1 de lecci\u00f3n para el futuro.<\/p>\n<p><b>7. Buscan ser m\u00e1s felices.<\/b><\/p>\n<p>Est\u00e1n en continuo crecimiento, en continuo desarrollo. Cada d\u00eda aprenden.<\/p>\n<p><!-- inserta publi --><\/p>\n<p><b>8. Resuelven sus conflictos sin ira.<\/b><\/p>\n<p>No van a dejar arrastrarse por sus emociones. Se conocen a s\u00ed mismos, y saben que hablar y escuchar es la mejor v\u00eda para entenderse.<\/p>\n<p><b>9. Se educan firmemente. <\/b><\/p>\n<p>Para ser una persona IE debes crear, mantener y eliminar h\u00e1bitos. Te disciplinas a ello. Te esfuerzas. No se consigue por arte de magia.<\/p>\n<p> <b>Si te interesa la Inteligencia Emocional no te puedes perder:<\/b><\/p>\n<ul>\n<li><a href=\"http:\/\/superacion-personal.euroresidentes.com\/2014\/04\/11-pistas-que-demuestran-que-tienes.html\" target=\"_blank\">11 Pistas para saber si tienes Inteligencia Emocional<\/a><\/li>\n<li><a href=\"http:\/\/superacion-personal.euroresidentes.com\/2014\/04\/8-cosas-que-las-personas-con.html\" target=\"_blank\">8 Cosas que las personas con Inteligencia Emocional no hacen<\/a><\/li>\n<li><a href=\"http:\/\/superacion-personal.euroresidentes.com\/2014\/07\/test-ie-sabes-perdonar.html\" target=\"_blank\">Test IE: \u00bfSabes perdonar?<\/a><\/li>\n<\/ul>\n<div>Yo, como siempre, te espero en la pr\u00f3xima. Un gran saludo y un abrazo, Andrea.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Inteligencia Emocional (IE) es importante en nuestras vidas. Eso es algo que est\u00e1 ya m\u00e1s que demostrado.\u00a0 Las personas con una alta Inteligencia Emocional\u00a0no lo son porque les ha ca\u00eddo del cielo. Siguen h\u00e1bitos y pautas para conseguir ser \u00a0inteligentes emocionalmente. Hemos creado una infograf\u00eda de algunos h\u00e1bitos que siguen las personas emocionalmente inteligentes. Se trata de h\u00e1bitos muy sencillos para poner en pr\u00e1ctica ya mismo si quieres. Abajo te dejo la descripci\u00f3n de cada h\u00e1bito. \u00c9chales un vistazo y a empezar. \u00bfPreparad@?\u00a0 1. Est\u00e1n centradas en lo positivo. Buscan soluciones a los problemas y se centran en todo <\/p>\n","protected":false},"author":11,"featured_media":6080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-343","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inteligencia-emocional","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>9 H\u00e1bitos de las personas con Inteligencia Emocional<\/title>\n<meta name=\"description\" content=\"Si quieres ser m\u00e1s inteligente emocionalmente hablando sigue estos h\u00e1bitos de las personas con inteligencia emocional. El crecimiento personal no debe parar\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"9 H\u00e1bitos de las personas con Inteligencia Emocional\" \/>\n<meta property=\"og:description\" content=\"Si quieres ser m\u00e1s inteligente emocionalmente hablando sigue estos h\u00e1bitos de las personas con inteligencia emocional. El crecimiento personal no debe parar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/\" \/>\n<meta property=\"og:site_name\" content=\"Superaci\u00f3n personal\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sentir.bien.euroresidentes\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/andrea.mendezmolla?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-22T16:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-08-16T11:03:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/habitos-personas-inteligencia-emocional.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea M\u00e9ndez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sentirbien\" \/>\n<meta name=\"twitter:site\" content=\"@sentirbien\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea M\u00e9ndez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/\",\"url\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/\",\"name\":\"9 H\u00e1bitos de las personas con Inteligencia Emocional\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/habitos-personas-inteligencia-emocional.jpg\",\"datePublished\":\"2015-04-22T16:43:00+00:00\",\"dateModified\":\"2016-08-16T11:03:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/#\/schema\/person\/76d37e061b7949bad6c3f7fa5366bfcb\"},\"description\":\"Si quieres ser m\u00e1s inteligente emocionalmente hablando sigue estos h\u00e1bitos de las personas con inteligencia emocional. El crecimiento personal no debe parar\",\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/#primaryimage\",\"url\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/habitos-personas-inteligencia-emocional.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/habitos-personas-inteligencia-emocional.jpg\",\"width\":700,\"height\":525,\"caption\":\"H\u00e1bitos de las personas con Inteligencia Emocional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"9 H\u00e1bitos de las personas con Inteligencia Emocional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/\",\"name\":\"Superaci\u00f3n personal\",\"description\":\"Consejos de superaci\u00f3n personal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/#\/schema\/person\/76d37e061b7949bad6c3f7fa5366bfcb\",\"name\":\"Andrea M\u00e9ndez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2014\/08\/foto_autora_andrea.m-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2014\/08\/foto_autora_andrea.m-150x150.jpg\",\"caption\":\"Andrea M\u00e9ndez\"},\"description\":\"Andrea M\u00e9ndezPsic\u00f3loga y autora de blogs orientados a la motivaci\u00f3n, el liderazgo y la superaci\u00f3n personal.\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/andrea-mendez.html\",\"https:\/\/www.facebook.com\/andrea.mendezmolla?fref=ts\"],\"url\":\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/author\/andreamendez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"9 H\u00e1bitos de las personas con Inteligencia Emocional","description":"Si quieres ser m\u00e1s inteligente emocionalmente hablando sigue estos h\u00e1bitos de las personas con inteligencia emocional. El crecimiento personal no debe parar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/","og_locale":"es_ES","og_type":"article","og_title":"9 H\u00e1bitos de las personas con Inteligencia Emocional","og_description":"Si quieres ser m\u00e1s inteligente emocionalmente hablando sigue estos h\u00e1bitos de las personas con inteligencia emocional. El crecimiento personal no debe parar","og_url":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/","og_site_name":"Superaci\u00f3n personal","article_publisher":"https:\/\/www.facebook.com\/sentir.bien.euroresidentes\/","article_author":"https:\/\/www.facebook.com\/andrea.mendezmolla?fref=ts","article_published_time":"2015-04-22T16:43:00+00:00","article_modified_time":"2016-08-16T11:03:44+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/habitos-personas-inteligencia-emocional.jpg","type":"image\/jpeg"}],"author":"Andrea M\u00e9ndez","twitter_card":"summary_large_image","twitter_creator":"@sentirbien","twitter_site":"@sentirbien","twitter_misc":{"Written by":"Andrea M\u00e9ndez","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/","url":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/","name":"9 H\u00e1bitos de las personas con Inteligencia Emocional","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/#primaryimage"},"image":{"@id":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/habitos-personas-inteligencia-emocional.jpg","datePublished":"2015-04-22T16:43:00+00:00","dateModified":"2016-08-16T11:03:44+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/#\/schema\/person\/76d37e061b7949bad6c3f7fa5366bfcb"},"description":"Si quieres ser m\u00e1s inteligente emocionalmente hablando sigue estos h\u00e1bitos de las personas con inteligencia emocional. El crecimiento personal no debe parar","breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/#primaryimage","url":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/habitos-personas-inteligencia-emocional.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2015\/04\/habitos-personas-inteligencia-emocional.jpg","width":700,"height":525,"caption":"H\u00e1bitos de las personas con Inteligencia Emocional"},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/9-habitos-de-las-personas-con\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/"},{"@type":"ListItem","position":2,"name":"9 H\u00e1bitos de las personas con Inteligencia Emocional"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/#website","url":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/","name":"Superaci\u00f3n personal","description":"Consejos de superaci\u00f3n personal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/#\/schema\/person\/76d37e061b7949bad6c3f7fa5366bfcb","name":"Andrea M\u00e9ndez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2014\/08\/foto_autora_andrea.m-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-content\/uploads\/sites\/8\/2014\/08\/foto_autora_andrea.m-150x150.jpg","caption":"Andrea M\u00e9ndez"},"description":"Andrea M\u00e9ndezPsic\u00f3loga y autora de blogs orientados a la motivaci\u00f3n, el liderazgo y la superaci\u00f3n personal.","sameAs":["https:\/\/www.euroresidentes.com\/estilo-de-vida\/andrea-mendez.html","https:\/\/www.facebook.com\/andrea.mendezmolla?fref=ts"],"url":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/author\/andreamendez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-json\/wp\/v2\/posts\/343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-json\/wp\/v2\/comments?post=343"}],"version-history":[{"count":7,"href":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-json\/wp\/v2\/posts\/343\/revisions"}],"predecessor-version":[{"id":6083,"href":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-json\/wp\/v2\/posts\/343\/revisions\/6083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-json\/wp\/v2\/media\/6080"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-json\/wp\/v2\/media?parent=343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-json\/wp\/v2\/categories?post=343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/estilo-de-vida\/superacion-personal\/wp-json\/wp\/v2\/tags?post=343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}