{"id":193,"date":"2005-07-18T12:08:00","date_gmt":"2005-07-18T12:08:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/2005\/07\/la-epoca-del-romanticismo.html"},"modified":"2005-07-18T12:08:00","modified_gmt":"2005-07-18T12:08:00","slug":"la-epoca-del-romanticismo","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/","title":{"rendered":"La epoca del romanticismo"},"content":{"rendered":"<p>La Epoca  del Romanticismo en Europa entre 1830 y 1900  supuso una epoca de mayor realidad para la m\u00fasica y la literatura, llena de emoci\u00f3n, color y drama. Una \u00e9poca de actitudes y sensaciones intensas que se hizo especialmente popular en Alemania y Francia y, un poco m\u00e1s tarde, afect\u00f3 incluso a Gran Breta\u00f1a donde los poetas y escritores g\u00f3ticos dieron rienda suelta a su imaginaci\u00f3n.<\/p>\n<p>Aunque naciese en Francia, la familia de la soprano y compositora <strong>Pauline Viadot-Garcia<\/strong> era espa\u00f1ola. Su padre fue el primer Barbero de Sevilla de Rossini. La vida de esta mujer fuerte con un gran talento personifica esta \u00e9poca. Inspir\u00f3 a Chopin, Berilos, Meyerbeer, Gounod, Sant-Saens, Liszt, Wagner y Schumann. Este \u00faltimo le dedic\u00f3 a Pauline Viadot Garc\u00eda su ciclo de Canciones de Heine. La soprano cant\u00f3 en Londres, Berlin, Dresden, Viena y St. Petersburgo donde conoci\u00f3 al escritor Ivan Turgenev que se enamor\u00f3 de ella y vivi\u00f3 \u201cen estrecha proximidad\u201d con ella y su marido durante el resto de su vida.<\/p>\n<p>En el a\u00f1o 1863 cuando ten\u00eda 42 a\u00f1os, Viadot Garc\u00eda se retir\u00f3 de los escenarios y dej\u00f3  Francia por motivos pol\u00edticos (su marido era republicano). Ella y su familia se fueron a vivir en Baden-Baden donde dio clases a cantantes de todo el mundo. En Baden-Baden construy\u00f3 un museo de arte y un peque\u00f1o teatro de opera donde la familia actuaron algunos de sus obras, incluyendo peque\u00f1as operas y musicales. Transcribi\u00f3 doce de las mazurcas de Chopin (con la aprobaci\u00f3n del compositor), utilizando poemas de Louis Povey  adem\u00e1s de otras obras de Schubert y Brahms. Una colecci\u00f3n de las canciones de Pauline Viadot Garc\u00eda cantadas por Isabel Bayrakdarian fue grabado recientemente y recibi\u00f3 una valoraci\u00f3n entusiasta por parte de los criticos musicales.<\/p>\n<p>Un cr\u00edtico de Berl\u00edn dijo que Viadot-Garc\u00eda era \u201c<em>la hija de reyes descendientes de los dioses<\/em>\u201d. La foto de una mujer seria y peque\u00f1a en la NGDM no parece indicar tal cosa, pero sin duda tiene que haber sido una gran mujer!<\/p>\n<p>B.R.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Epoca del Romanticismo en Europa entre 1830 y 1900 supuso una epoca de mayor realidad para la m\u00fasica y la literatura, llena de emoci\u00f3n, color y drama. Una \u00e9poca de actitudes y sensaciones intensas que se hizo especialmente popular en Alemania y Francia y, un poco m\u00e1s tarde, afect\u00f3 incluso a Gran Breta\u00f1a donde los poetas y escritores g\u00f3ticos dieron rienda suelta a su imaginaci\u00f3n. Aunque naciese en Francia, la familia de la soprano y compositora Pauline Viadot-Garcia era espa\u00f1ola. Su padre fue el primer Barbero de Sevilla de Rossini. La vida de esta mujer fuerte con un gran <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-193","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La epoca del romanticismo - M\u00fasica cl\u00e1sica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La epoca del romanticismo - M\u00fasica cl\u00e1sica\" \/>\n<meta property=\"og:description\" content=\"La Epoca del Romanticismo en Europa entre 1830 y 1900 supuso una epoca de mayor realidad para la m\u00fasica y la literatura, llena de emoci\u00f3n, color y drama. Una \u00e9poca de actitudes y sensaciones intensas que se hizo especialmente popular en Alemania y Francia y, un poco m\u00e1s tarde, afect\u00f3 incluso a Gran Breta\u00f1a donde los poetas y escritores g\u00f3ticos dieron rienda suelta a su imaginaci\u00f3n. Aunque naciese en Francia, la familia de la soprano y compositora Pauline Viadot-Garcia era espa\u00f1ola. Su padre fue el primer Barbero de Sevilla de Rossini. La vida de esta mujer fuerte con un gran\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00fasica cl\u00e1sica\" \/>\n<meta property=\"article:published_time\" content=\"2005-07-18T12:08:00+00:00\" \/>\n<meta name=\"author\" content=\"Euroresidentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Euroresidentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/\",\"name\":\"La epoca del romanticismo - M\u00fasica cl\u00e1sica\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#website\"},\"datePublished\":\"2005-07-18T12:08:00+00:00\",\"dateModified\":\"2005-07-18T12:08:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#\/schema\/person\/e41441f91af6208631ba0be4ea9c5f01\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La epoca del romanticismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/\",\"name\":\"M\u00fasica cl\u00e1sica\",\"description\":\"Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#\/schema\/person\/e41441f91af6208631ba0be4ea9c5f01\",\"name\":\"Euroresidentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-content\/uploads\/sites\/20\/2016\/09\/logo-euroresidentes-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-content\/uploads\/sites\/20\/2016\/09\/logo-euroresidentes-150x150.jpg\",\"caption\":\"Euroresidentes\"},\"description\":\"Euroresidentes\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/info.htm\"],\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/author\/euroresidentes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La epoca del romanticismo - M\u00fasica cl\u00e1sica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/","og_locale":"es_ES","og_type":"article","og_title":"La epoca del romanticismo - M\u00fasica cl\u00e1sica","og_description":"La Epoca del Romanticismo en Europa entre 1830 y 1900 supuso una epoca de mayor realidad para la m\u00fasica y la literatura, llena de emoci\u00f3n, color y drama. Una \u00e9poca de actitudes y sensaciones intensas que se hizo especialmente popular en Alemania y Francia y, un poco m\u00e1s tarde, afect\u00f3 incluso a Gran Breta\u00f1a donde los poetas y escritores g\u00f3ticos dieron rienda suelta a su imaginaci\u00f3n. Aunque naciese en Francia, la familia de la soprano y compositora Pauline Viadot-Garcia era espa\u00f1ola. Su padre fue el primer Barbero de Sevilla de Rossini. La vida de esta mujer fuerte con un gran","og_url":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/","og_site_name":"M\u00fasica cl\u00e1sica","article_published_time":"2005-07-18T12:08:00+00:00","author":"Euroresidentes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Euroresidentes","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/","name":"La epoca del romanticismo - M\u00fasica cl\u00e1sica","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#website"},"datePublished":"2005-07-18T12:08:00+00:00","dateModified":"2005-07-18T12:08:00+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#\/schema\/person\/e41441f91af6208631ba0be4ea9c5f01"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/la-epoca-del-romanticismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/"},{"@type":"ListItem","position":2,"name":"La epoca del romanticismo"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#website","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/","name":"M\u00fasica cl\u00e1sica","description":"Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#\/schema\/person\/e41441f91af6208631ba0be4ea9c5f01","name":"Euroresidentes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-content\/uploads\/sites\/20\/2016\/09\/logo-euroresidentes-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-content\/uploads\/sites\/20\/2016\/09\/logo-euroresidentes-150x150.jpg","caption":"Euroresidentes"},"description":"Euroresidentes","sameAs":["https:\/\/www.euroresidentes.com\/info.htm"],"url":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/author\/euroresidentes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/posts\/193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/comments?post=193"}],"version-history":[{"count":0,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/posts\/193\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/media?parent=193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/categories?post=193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/tags?post=193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}