{"id":124,"date":"2006-06-26T07:11:00","date_gmt":"2006-06-26T07:11:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/2006\/06\/solomon-cutner-maestro-de-su-arte.html"},"modified":"2006-06-26T07:11:00","modified_gmt":"2006-06-26T07:11:00","slug":"solomon-cutner-maestro-de-su-arte","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/","title":{"rendered":"Solomon Cutner: Maestro de su Arte"},"content":{"rendered":"<p>Desastre en casa \u2026el reproductor de CDs se ha estropeado. As\u00ed que he estado escuchando viejos discos de vinilo y en particular los del legendario pianista Solomon (profesionalmente nunca uso su apellido).  Fue el s\u00e9ptimo hijo de un sastre de la zona pobre en el este de Londres.  Tuvo un profesor muy ambicioso Mathilde Verne y su primer actuaci\u00f3n al publico fue cuando solo tenia 8 a\u00f1os. Despu\u00e9s estudio en Paris y hizo una gira por Europa antes y despu\u00e9s de la guerra.  Visitaba el USA anualmente en los a\u00f1os 40 y 50.  Presento por primera vez el concierto para el piano de Arthur Bliss dirigido por Adrian Boult en Nueva York.<\/p>\n<p>Solo le vi en directo una vez&#8230;\u00a1en mi escuela! Como todos los m\u00fasicos que tocaban ah\u00ed tenia que usar el viejo piano de la escuela.  Se notaba en su cara que el piano no fue lo suficiente bueno para el.<\/p>\n<p>Soloman fue un pianista refinado fiel al compositor y con una t\u00e9cnica virtuosa. El cr\u00edtico William Hadley le describe como \u2018serio, refinado y resuelto\u2019. Fue un pianista con control total sobre lo que tocaba y tenia una delicadeza y certeza sobre su m\u00fasica. <\/p>\n<p>Yo estoy de acuerdo despu\u00e9s de escuchar su actuaci\u00f3n del segundo concierto para el piano de Brahms con el entonces nueva orquesta filarmon\u00eda dirigido por de Issay Dobrowen en 1947.  Es una actuaci\u00f3n maravillosa a pesar de la calidad de la grabaci\u00f3n en mono te sientes como si estuvieras ah\u00ed.  Un critico sugiri\u00f3  que es la mejor grabaci\u00f3n jam\u00e1s grabada incluso mejor que la de Emil Gilels.<\/p>\n<p> Solomon fue encargado para grabar todos las sonatas de Beethoven para piano.  Pero despu\u00e9s de hacer la mitad se dio cuenta de que sus dedos estaban resbalando y pocos meses mas tarde sufri\u00f3 una par\u00e1lisis de medio cuerpo. Entonces solo tenia 57 a\u00f1os y nunca volvi\u00f3 a tocar el piano en publico. Una tragedia para el y una gran perdida para el mundo de la m\u00fasica.  Pero tenemos sus grabaciones y nos ayudan compartir su perspectiva de los grandes compositores de los cuales fue un interprete brillante y fiel servidor.<\/p>\n<p>B.R.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desastre en casa \u2026el reproductor de CDs se ha estropeado. As\u00ed que he estado escuchando viejos discos de vinilo y en particular los del legendario pianista Solomon (profesionalmente nunca uso su apellido). Fue el s\u00e9ptimo hijo de un sastre de la zona pobre en el este de Londres. Tuvo un profesor muy ambicioso Mathilde Verne y su primer actuaci\u00f3n al publico fue cuando solo tenia 8 a\u00f1os. Despu\u00e9s estudio en Paris y hizo una gira por Europa antes y despu\u00e9s de la guerra. Visitaba el USA anualmente en los a\u00f1os 40 y 50. Presento por primera vez el concierto para <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-124","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Solomon Cutner: Maestro de su Arte - M\u00fasica cl\u00e1sica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solomon Cutner: Maestro de su Arte - M\u00fasica cl\u00e1sica\" \/>\n<meta property=\"og:description\" content=\"Desastre en casa \u2026el reproductor de CDs se ha estropeado. As\u00ed que he estado escuchando viejos discos de vinilo y en particular los del legendario pianista Solomon (profesionalmente nunca uso su apellido). Fue el s\u00e9ptimo hijo de un sastre de la zona pobre en el este de Londres. Tuvo un profesor muy ambicioso Mathilde Verne y su primer actuaci\u00f3n al publico fue cuando solo tenia 8 a\u00f1os. Despu\u00e9s estudio en Paris y hizo una gira por Europa antes y despu\u00e9s de la guerra. Visitaba el USA anualmente en los a\u00f1os 40 y 50. Presento por primera vez el concierto para\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/\" \/>\n<meta property=\"og:site_name\" content=\"M\u00fasica cl\u00e1sica\" \/>\n<meta property=\"article:published_time\" content=\"2006-06-26T07:11:00+00:00\" \/>\n<meta name=\"author\" content=\"Euroresidentes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Euroresidentes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/\",\"name\":\"Solomon Cutner: Maestro de su Arte - M\u00fasica cl\u00e1sica\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#website\"},\"datePublished\":\"2006-06-26T07:11:00+00:00\",\"dateModified\":\"2006-06-26T07:11:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#\/schema\/person\/e41441f91af6208631ba0be4ea9c5f01\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solomon Cutner: Maestro de su Arte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/\",\"name\":\"M\u00fasica cl\u00e1sica\",\"description\":\"Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#\/schema\/person\/e41441f91af6208631ba0be4ea9c5f01\",\"name\":\"Euroresidentes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-content\/uploads\/sites\/20\/2016\/09\/logo-euroresidentes-150x150.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-content\/uploads\/sites\/20\/2016\/09\/logo-euroresidentes-150x150.jpg\",\"caption\":\"Euroresidentes\"},\"description\":\"Euroresidentes\",\"sameAs\":[\"https:\/\/www.euroresidentes.com\/info.htm\"],\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/author\/euroresidentes\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solomon Cutner: Maestro de su Arte - M\u00fasica cl\u00e1sica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/","og_locale":"es_ES","og_type":"article","og_title":"Solomon Cutner: Maestro de su Arte - M\u00fasica cl\u00e1sica","og_description":"Desastre en casa \u2026el reproductor de CDs se ha estropeado. As\u00ed que he estado escuchando viejos discos de vinilo y en particular los del legendario pianista Solomon (profesionalmente nunca uso su apellido). Fue el s\u00e9ptimo hijo de un sastre de la zona pobre en el este de Londres. Tuvo un profesor muy ambicioso Mathilde Verne y su primer actuaci\u00f3n al publico fue cuando solo tenia 8 a\u00f1os. Despu\u00e9s estudio en Paris y hizo una gira por Europa antes y despu\u00e9s de la guerra. Visitaba el USA anualmente en los a\u00f1os 40 y 50. Presento por primera vez el concierto para","og_url":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/","og_site_name":"M\u00fasica cl\u00e1sica","article_published_time":"2006-06-26T07:11:00+00:00","author":"Euroresidentes","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Euroresidentes","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/","name":"Solomon Cutner: Maestro de su Arte - M\u00fasica cl\u00e1sica","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#website"},"datePublished":"2006-06-26T07:11:00+00:00","dateModified":"2006-06-26T07:11:00+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#\/schema\/person\/e41441f91af6208631ba0be4ea9c5f01"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/solomon-cutner-maestro-de-su-arte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/"},{"@type":"ListItem","position":2,"name":"Solomon Cutner: Maestro de su Arte"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#website","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/","name":"M\u00fasica cl\u00e1sica","description":"Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#\/schema\/person\/e41441f91af6208631ba0be4ea9c5f01","name":"Euroresidentes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-content\/uploads\/sites\/20\/2016\/09\/logo-euroresidentes-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-content\/uploads\/sites\/20\/2016\/09\/logo-euroresidentes-150x150.jpg","caption":"Euroresidentes"},"description":"Euroresidentes","sameAs":["https:\/\/www.euroresidentes.com\/info.htm"],"url":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/author\/euroresidentes\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/posts\/124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/comments?post=124"}],"version-history":[{"count":0,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/posts\/124\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/media?parent=124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/categories?post=124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/musica-clasica\/wp-json\/wp\/v2\/tags?post=124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}