{"id":2150,"date":"2016-09-10T13:35:00","date_gmt":"2016-09-10T11:35:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos"},"modified":"2018-03-06T14:21:19","modified_gmt":"2018-03-06T13:21:19","slug":"frases-de-besos","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/","title":{"rendered":"Frases de Besos"},"content":{"rendered":"<div class=\"separator\" style=\"clear: both; text-align: left;\">Besos de amor, besos de amistad, besos de despedida&#8230;besos de traici\u00f3n. Porque besos pueden haber de muchas clases, estas son frases de besos.<\/div>\n<div class=\"separator\" style=\"clear: both; text-align: left;\">\n<p>[bctt tweet=\u00bbUn beso puede ser una coma, un signo de interrogaci\u00f3n o un signo de exclamaci\u00f3n. Esa es la es la ortograf\u00eda b\u00e1sica que toda mujer debe saber. (Jeanne Bourgeois)\u00bb]<\/p>\n<p>[bctt tweet=\u00bbLas almas se encuentran en los labios de los amantes. (Percy Bysshe Shelley)\u00bb]<\/p>\n<p><!-- inserta publi --><\/p>\n<p>[bctt tweet=\u00bbEstoy a favor de la preservaci\u00f3n de la costumbre francesa de besar la mano de la mujer, despu\u00e9s de todo hay que empezar por alguna parte. (Sacha Guitry)\u00bb]<\/p>\n<p>[bctt tweet=\u00bbUn beso es un truco encantador dise\u00f1ado por la naturaleza para dejar de hablar cuando las palabras son superfluas. (Ingrid Bergman)\u00bb]<\/p>\n<\/div>\n<div class=\"separator\" style=\"clear: both; text-align: left;\">\u00a0<\/div>\n<div class=\"separator\" style=\"clear: both; text-align: left;\"><a href=\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-besar-euroresidentes.jpg\" rel=\"attachment wp-att-5023\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5023\" src=\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-besar-euroresidentes.jpg\" alt=\"Frases de besos, euroresidentes\" width=\"700\" height=\"525\" srcset=\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-besar-euroresidentes.jpg 700w, https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-besar-euroresidentes-300x225.jpg 300w, https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-besar-euroresidentes-396x297.jpg 396w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/div>\n<div>\u00a0<\/div>\n<p>[bctt tweet=\u00bbNo puedo leer los labios si no est\u00e1n tocando los m\u00edos. (Jon Troast)\u00bb]<\/p>\n<p>[bctt tweet=\u00bbBesar es un medio para conseguir que dos personas que est\u00e1n tan cerca no puedan verse los defectos. (Ren\u00e9 Yasenek)\u00bb]<\/p>\n<p>[bctt tweet=\u00bbMe bes\u00f3 sin pedir permiso y a m\u00ed me pareci\u00f3 la gloria. le devolv\u00ed el beso con hambre atrasada. -Mario Benedetti\u00bb]<\/p>\n<p><a href=\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-de-besar-euroresidentes.jpg\" rel=\"attachment wp-att-5024\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5024\" src=\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-de-besar-euroresidentes.jpg\" alt=\"Frases de besos y besar, euroresidentes\" width=\"700\" height=\"525\" srcset=\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-de-besar-euroresidentes.jpg 700w, https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-de-besar-euroresidentes-300x225.jpg 300w, https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-de-besar-euroresidentes-396x297.jpg 396w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>[bctt tweet=\u00bbNecesito un caf\u00e9 y un beso largo.\u00bb]<\/p>\n<p>[bctt tweet=\u00bbYo no la estaba besando, estaba susurr\u00e1ndole en la boca. (Chico Marx)\u00bb]<\/p>\n<p><!-- inserta publi 2 --><\/p>\n<p>[bctt tweet=\u00bbLos besos robados son siempre los m\u00e1s dulces. (Leigh Hunt)\u00bb]<\/p>\n<p>[bctt tweet=\u00bbBesar es como beber agua salada: Bebes y aumenta tu sed. (Proverbio chino)\u00bb]<\/p>\n<p>[bctt tweet=\u00bbTu beso sacudi\u00f3 mi boca, y a\u00fan me tiembla el recuerdo.\u00bb]<\/p>\n<p>[bctt tweet=\u00bbNo dejes para ma\u00f1ana los besos que puedes dar hoy. -An\u00f3nimo\u00bb]<\/p>\n<p>[bctt tweet=\u00bbQu\u00e9date con quien te bese el alma, la piel te la besa cualquiera.\u00bb]<\/p>\n<p>[bctt tweet=\u00bbB\u00e9same y veras cuan importante soy. (Sylvia Plath)\u00bb]<\/p>\n<p>[bctt tweet=\u00bbUn beso legal nunca es tan bueno como uno robado. (Guy de Maupassant)\u00bb]<\/p>\n<p>[bctt tweet=\u00bbLlenarte de besos, de esos que no dejan espacio para dudas.\u00bb]<\/p>\n<p>\n <b>Relacionado con frases de Besos:<\/b><\/p>\n<ul>\n<li><a href=\"https:\/\/www.euroresidentes.com\/amor\/todo-sobre-amor\/6-tipos-de-besos-y-sus-significados\/\">6 tipos de besos y sus significados<\/a><\/li>\n<li><a href=\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-amor-y-besos\">Frases de amor y besos<\/a><\/li>\n<li><a href=\"https:\/\/www.euroresidentes.com\/Poemas\/amor\/beso.htm\">Poema: beso<\/a><\/li>\n<li><a href=\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/los-dias-amargos-con-besos-se-llevan\">Los d\u00edas amargos con besos se llevan mejor<\/a><\/li>\n<li><a href=\"https:\/\/www.euroresidentes.com\/amor\/ligar\/los-mejores-besos.htm\">Los mejores besos de cine<\/a><\/li>\n<\/ul>\n<p>Comparte tus frases favoritas en <a href=\"http:\/\/www.euroresidentes.com\/Diversion\/frases.htm\">Mis Frases<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Besos de amor, besos de amistad, besos de despedida&#8230;besos de traici\u00f3n. Porque besos pueden haber de muchas clases, estas son frases de besos.    <\/p>\n","protected":false},"author":5,"featured_media":5024,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[95,265],"class_list":["post-2150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frases","tag-amor","tag-besos","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Frases de Besos - Frases y Citas C\u00e9lebres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frases de Besos - Frases y Citas C\u00e9lebres\" \/>\n<meta property=\"og:description\" content=\"Besos de amor, besos de amistad, besos de despedida&#8230;besos de traici\u00f3n. Porque besos pueden haber de muchas clases, estas son frases de besos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/\" \/>\n<meta property=\"og:site_name\" content=\"Frases y Citas C\u00e9lebres\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frases.euroresidentes\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-10T11:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-06T13:21:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-de-besar-euroresidentes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maril\u00fa Hern\u00e1ndez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maril\u00fa Hern\u00e1ndez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/\",\"name\":\"Frases de Besos - Frases y Citas C\u00e9lebres\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-de-besar-euroresidentes.jpg\",\"datePublished\":\"2016-09-10T11:35:00+00:00\",\"dateModified\":\"2018-03-06T13:21:19+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#\/schema\/person\/1d462109dd66b3c11cebec62193acfaa\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/#primaryimage\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-de-besar-euroresidentes.jpg\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-de-besar-euroresidentes.jpg\",\"width\":700,\"height\":525,\"caption\":\"Frases de besos y besar, euroresidentes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frases de Besos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/\",\"name\":\"Frases y Citas C\u00e9lebres\",\"description\":\"Frases, citas c\u00e9lebres de autores, refranes, frases de figuras hist\u00f3ricas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#\/schema\/person\/1d462109dd66b3c11cebec62193acfaa\",\"name\":\"Maril\u00fa Hern\u00e1ndez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2016\/08\/marilu-autor-2016-150x150.png\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2016\/08\/marilu-autor-2016-150x150.png\",\"caption\":\"Maril\u00fa Hern\u00e1ndez\"},\"description\":\"Maril\u00fa Hern\u00e1ndez- Apasionada de los libros, citas c\u00e9lebres, refranes y todo lo que a letras se refiera, cin\u00e9fila en mis ratos libres y amante de los postres.\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/author\/marilu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frases de Besos - Frases y Citas C\u00e9lebres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/","og_locale":"es_ES","og_type":"article","og_title":"Frases de Besos - Frases y Citas C\u00e9lebres","og_description":"Besos de amor, besos de amistad, besos de despedida&#8230;besos de traici\u00f3n. Porque besos pueden haber de muchas clases, estas son frases de besos.","og_url":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/","og_site_name":"Frases y Citas C\u00e9lebres","article_publisher":"https:\/\/www.facebook.com\/frases.euroresidentes\/","article_published_time":"2016-09-10T11:35:00+00:00","article_modified_time":"2018-03-06T13:21:19+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-de-besar-euroresidentes.jpg","type":"image\/jpeg"}],"author":"Maril\u00fa Hern\u00e1ndez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Maril\u00fa Hern\u00e1ndez","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/","name":"Frases de Besos - Frases y Citas C\u00e9lebres","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/#primaryimage"},"image":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-de-besar-euroresidentes.jpg","datePublished":"2016-09-10T11:35:00+00:00","dateModified":"2018-03-06T13:21:19+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#\/schema\/person\/1d462109dd66b3c11cebec62193acfaa"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/#primaryimage","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-de-besar-euroresidentes.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2011\/09\/frases-de-besar-euroresidentes.jpg","width":700,"height":525,"caption":"Frases de besos y besar, euroresidentes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-besos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/"},{"@type":"ListItem","position":2,"name":"Frases de Besos"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#website","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/","name":"Frases y Citas C\u00e9lebres","description":"Frases, citas c\u00e9lebres de autores, refranes, frases de figuras hist\u00f3ricas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#\/schema\/person\/1d462109dd66b3c11cebec62193acfaa","name":"Maril\u00fa Hern\u00e1ndez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2016\/08\/marilu-autor-2016-150x150.png","contentUrl":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2016\/08\/marilu-autor-2016-150x150.png","caption":"Maril\u00fa Hern\u00e1ndez"},"description":"Maril\u00fa Hern\u00e1ndez- Apasionada de los libros, citas c\u00e9lebres, refranes y todo lo que a letras se refiera, cin\u00e9fila en mis ratos libres y amante de los postres.","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/author\/marilu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/posts\/2150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/comments?post=2150"}],"version-history":[{"count":7,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/posts\/2150\/revisions"}],"predecessor-version":[{"id":7600,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/posts\/2150\/revisions\/7600"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/media\/5024"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/media?parent=2150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/categories?post=2150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/tags?post=2150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}