{"id":1878,"date":"2012-10-10T10:22:00","date_gmt":"2012-10-10T08:22:00","guid":{"rendered":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones"},"modified":"2017-01-23T19:16:13","modified_gmt":"2017-01-23T18:16:13","slug":"frases-de-canciones","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/","title":{"rendered":"Frases de Canciones"},"content":{"rendered":"<p><i>Todos tenemos una canci\u00f3n que nos hace recordar momentos, personas, lugares que nos erizan la piel con solo pensarlas. Para esos enamorados que han inmortalizado su amor con una canci\u00f3n, para todos los que una canci\u00f3n les hace levantarse de buen humor, para todos. Estas son frases de canciones.<\/p>\n<p><b>FRASES DE CANCIONES<\/b>:<\/i><\/p>\n<ul>\n<li><i><i>Si t\u00fa te vas, todos los d\u00edas llover\u00e1. -Bruno Mars<\/i><\/i><\/li>\n<li><i><i>No tengo planes m\u00e1s all\u00e1 de esta cena, es un misterio hacia d\u00f3nde la noche nos lleva. -Amaral<\/i><\/i><\/li>\n<li><i><i>Y ver\u00e1s que lo que nace se apaga, que de ser todo eres nada. -Dani Mart\u00edn<\/i><\/i><\/li>\n<li><i><i>Me asomo a la ventana eres la chica de ayer, jugando con las flores de mi jard\u00edn. -Nacha pop<\/i><\/i><\/li>\n<li><i><i>Tengo prisa ya por verte, por tenerte entre mis brazos, porque cuando tu est\u00e1s lejos no me late el coraz\u00f3n. Melendi<\/i><\/i><\/li>\n<li><i><i>Dormir contigo es estar solo dos veces, es la soledad al cuadrado. (Fito Paez)<\/i><\/i><\/li>\n<li><i><i>Vivir es lo m\u00e1s peligroso que tiene la vida -Alejandro Sanz<\/i><\/i><\/li>\n<li><i><i>Nunca despreci\u00e9 una causa perdida, nunca negar\u00e9 que son mis favoritas. H\u00e9roes del silencio<\/i><\/i><\/li>\n<li><i><i>Y en el final, el amor que tomas, es igual al amor que das. -Los Beatles.<\/i><\/i><\/li>\n<li><i><i>Cada vez que respires y cada movimiento que hagas, todo v\u00ednculo que rompas, cada paso que des, voy a estar mir\u00e1ndote. -Sting<\/i><\/i><\/li>\n<li><i><i>No tengo due\u00f1o, no soy tu esclavo, un poco tuyo y de todo el mundo. -Enrique Bunburi<\/i><\/i><\/li>\n<li><i><i>Deber\u00eda rendirme o simplemente continuar mi camino, aunque este no lleve a ninguna parte. -Adele<\/i><\/i><\/li>\n<li><i><i>Porque tus amores perros me van a matar sin haberme dado siquiera un poco de felicidad. -Julieat Venegas<\/i><\/i><\/li>\n<li><i><i>Sabes, quisiera darte siempre un poco m\u00e1s de lo que te pido. Sabes que so\u00f1ar\u00e9, si no est\u00e1s que me despierto contigo. -Fito &amp; Fitipaldis<\/i><\/i><\/li>\n<li><i><i>La vida es una c\u00e1rcel con las puertas abiertas. -Andr\u00e9s Calamaro<\/i><\/i><\/li>\n<li><i><i>Si quisieras quererme dejar\u00eda de fumar y me har\u00eda vegetariano, si durmieras conmigo dormir\u00edan menos tristes las palmas de mis manos y si los buenos chicos te atosigan y buscas chicos duros fingir\u00e9 ser el duro que castiga con besos de cianuro. -Joaqu\u00edn Sabina<\/i><\/i><\/li>\n<li><i><i>Despu\u00e9s de la tormenta siempre llega la calma, pero s\u00e9 que despu\u00e9s de ti, despu\u00e9s de ti no hay nada. -Alejandro sanz<\/i><\/i><\/li>\n<li><i><i>Yo no s\u00e9 si te merezco, s\u00f3lo s\u00e9 que a\u00fan deseo que le des luz a mi vida en los d\u00edas venideros. -Juanes<\/i><\/i><\/li>\n<li><i><i>Cuando envejezca estar\u00e9 ah\u00ed a tu lado para hacerte recordar c\u00f3mo a\u00fan te amo, a\u00fan te amo. -Queen<\/i><\/i><\/li>\n<\/ul>\n<p>\n<iframe loading=\"lazy\" allowfullscreen=\"allowfullscreen\" frameborder=\"0\" height=\"315\" src=\"http:\/\/www.youtube.com\/embed\/W-w3WfgpcGg\" width=\"560\"><\/iframe><\/p>\n<p>\n<i><br \/>\n<\/i><i> <b>Enlaces relacionados con Frases de canciones:<br \/>\n<\/b><\/i><\/p>\n<ul>\n<li><i><b><i><b><a href=\"http:\/\/frases-citas.euroresidentes.com\/2011\/07\/frases-de-amor-de-canciones.html\">Frases de amor de canciones<\/a><\/b><\/i><\/b><\/i><\/li>\n<p><i><b><\/p>\n<li><i><b><a href=\"http:\/\/frases-citas.euroresidentes.com\/2011\/02\/frases-lindas-de-canciones.html\">Frases de lindas de canciones<\/a><\/b><\/i><\/li>\n<li><i><b><a href=\"http:\/\/frases-citas.euroresidentes.com\/2012\/02\/frases-de-ricky-martin.html\">Frases de Ricky Martin<\/a><\/b><\/i><\/li>\n<li><i><b><a href=\"http:\/\/frases-citas.euroresidentes.com\/2011\/09\/frases-de-camila.html\">Frases de Camila<\/a><\/b><\/i><\/li>\n<p><\/b><\/i><\/ul>\n<p><i><b>Comparte tus frases favoritas en <a href=\"http:\/\/www.euroresidentes.com\/Diversion\/frases.htm\">Mis Frases<\/a><\/b><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos tenemos una canci\u00f3n que nos hace recordar momentos, personas, lugares que nos erizan la piel con solo pensarlas. Para esos enamorados que han inmortalizado su amor con una canci\u00f3n, para todos los que una canci\u00f3n les hace levantarse de buen humor, para todos. Estas son frases de canciones. FRASES DE CANCIONES: Si t\u00fa te vas, todos los d\u00edas llover\u00e1. -Bruno Mars No tengo planes m\u00e1s all\u00e1 de esta cena, es un misterio hacia d\u00f3nde la noche nos lleva. -Amaral Y ver\u00e1s que lo que nace se apaga, que de ser todo eres nada. -Dani Mart\u00edn Me asomo a la <\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[98],"class_list":["post-1878","post","type-post","status-publish","format-standard","hentry","category-frases","tag-canciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Frases de Canciones - Frases y Citas C\u00e9lebres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frases de Canciones - Frases y Citas C\u00e9lebres\" \/>\n<meta property=\"og:description\" content=\"Todos tenemos una canci\u00f3n que nos hace recordar momentos, personas, lugares que nos erizan la piel con solo pensarlas. Para esos enamorados que han inmortalizado su amor con una canci\u00f3n, para todos los que una canci\u00f3n les hace levantarse de buen humor, para todos. Estas son frases de canciones. FRASES DE CANCIONES: Si t\u00fa te vas, todos los d\u00edas llover\u00e1. -Bruno Mars No tengo planes m\u00e1s all\u00e1 de esta cena, es un misterio hacia d\u00f3nde la noche nos lleva. -Amaral Y ver\u00e1s que lo que nace se apaga, que de ser todo eres nada. -Dani Mart\u00edn Me asomo a la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Frases y Citas C\u00e9lebres\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/frases.euroresidentes\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-10T08:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-23T18:16:13+00:00\" \/>\n<meta name=\"author\" content=\"Maril\u00fa Hern\u00e1ndez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maril\u00fa Hern\u00e1ndez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/\",\"name\":\"Frases de Canciones - Frases y Citas C\u00e9lebres\",\"isPartOf\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#website\"},\"datePublished\":\"2012-10-10T08:22:00+00:00\",\"dateModified\":\"2017-01-23T18:16:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#\/schema\/person\/1d462109dd66b3c11cebec62193acfaa\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frases de Canciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#website\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/\",\"name\":\"Frases y Citas C\u00e9lebres\",\"description\":\"Frases, citas c\u00e9lebres de autores, refranes, frases de figuras hist\u00f3ricas\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#\/schema\/person\/1d462109dd66b3c11cebec62193acfaa\",\"name\":\"Maril\u00fa Hern\u00e1ndez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2016\/08\/marilu-autor-2016-150x150.png\",\"contentUrl\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2016\/08\/marilu-autor-2016-150x150.png\",\"caption\":\"Maril\u00fa Hern\u00e1ndez\"},\"description\":\"Maril\u00fa Hern\u00e1ndez- Apasionada de los libros, citas c\u00e9lebres, refranes y todo lo que a letras se refiera, cin\u00e9fila en mis ratos libres y amante de los postres.\",\"url\":\"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/author\/marilu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frases de Canciones - Frases y Citas C\u00e9lebres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/","og_locale":"es_ES","og_type":"article","og_title":"Frases de Canciones - Frases y Citas C\u00e9lebres","og_description":"Todos tenemos una canci\u00f3n que nos hace recordar momentos, personas, lugares que nos erizan la piel con solo pensarlas. Para esos enamorados que han inmortalizado su amor con una canci\u00f3n, para todos los que una canci\u00f3n les hace levantarse de buen humor, para todos. Estas son frases de canciones. FRASES DE CANCIONES: Si t\u00fa te vas, todos los d\u00edas llover\u00e1. -Bruno Mars No tengo planes m\u00e1s all\u00e1 de esta cena, es un misterio hacia d\u00f3nde la noche nos lleva. -Amaral Y ver\u00e1s que lo que nace se apaga, que de ser todo eres nada. -Dani Mart\u00edn Me asomo a la","og_url":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/","og_site_name":"Frases y Citas C\u00e9lebres","article_publisher":"https:\/\/www.facebook.com\/frases.euroresidentes\/","article_published_time":"2012-10-10T08:22:00+00:00","article_modified_time":"2017-01-23T18:16:13+00:00","author":"Maril\u00fa Hern\u00e1ndez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Maril\u00fa Hern\u00e1ndez","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/","name":"Frases de Canciones - Frases y Citas C\u00e9lebres","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#website"},"datePublished":"2012-10-10T08:22:00+00:00","dateModified":"2017-01-23T18:16:13+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#\/schema\/person\/1d462109dd66b3c11cebec62193acfaa"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/frases-de-canciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/"},{"@type":"ListItem","position":2,"name":"Frases de Canciones"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#website","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/","name":"Frases y Citas C\u00e9lebres","description":"Frases, citas c\u00e9lebres de autores, refranes, frases de figuras hist\u00f3ricas","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#\/schema\/person\/1d462109dd66b3c11cebec62193acfaa","name":"Maril\u00fa Hern\u00e1ndez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/#\/schema\/person\/image\/","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2016\/08\/marilu-autor-2016-150x150.png","contentUrl":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-content\/uploads\/sites\/7\/2016\/08\/marilu-autor-2016-150x150.png","caption":"Maril\u00fa Hern\u00e1ndez"},"description":"Maril\u00fa Hern\u00e1ndez- Apasionada de los libros, citas c\u00e9lebres, refranes y todo lo que a letras se refiera, cin\u00e9fila en mis ratos libres y amante de los postres.","url":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/author\/marilu\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/posts\/1878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/comments?post=1878"}],"version-history":[{"count":1,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/posts\/1878\/revisions"}],"predecessor-version":[{"id":2741,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/posts\/1878\/revisions\/2741"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/media?parent=1878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/categories?post=1878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/entretenimiento\/frases-citas-imagenes\/wp-json\/wp\/v2\/tags?post=1878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}