
{"id":9,"date":"2015-09-08T10:01:00","date_gmt":"2015-09-08T10:01:00","guid":{"rendered":""},"modified":"2016-02-24T10:10:41","modified_gmt":"2016-02-24T10:10:41","slug":"15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/","title":{"rendered":"15 cosas destacables de Sheryl Sandberg, la ejecutiva m\u00e1s popular en Silicon Valley"},"content":{"rendered":"<p><b>Sheryl Sandberg<\/b> es <b>directora de operaciones de Facebook, activista de los derechos de la mujer y miembro del consejo de varias empresas<\/b>. Adem\u00e1s de escritora del emblem\u00e1tico libro <i>Lean In: Women, Work, and the Will to Lead and found Lean In<\/i>, dedicado a ayudar a las mujeres a alcanzar sus metas.<\/p>\n<div style=\"clear: both; text-align: center;\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/PORTADA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"\" title=\"PORTADA\" src=\"http:\/\/euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/PORTADA-300x225.jpg\" alt=\"PORTADA\" width=\"532\" height=\"414\" border=\"0\" \/><\/a><\/div>\n<h3><\/h3>\n<h3>15 cosas que debes conocer sobre ella:<\/h3>\n<h4>1. Verdadero cerebro empresarial de Facebook<\/h4>\n<p>Es la directora de operaciones de Facebook y<b> n\u00famero dos de la compa\u00f1\u00eda<\/b>. Su papel fundamental en esta famosa red social repleta de hombres j\u00f3venes es dotarla de una supervisi\u00f3n adulta y ayudar a que Facebook crezca y construya su propio modelo de negocio. Cabe destacar que, desde que Sheryl est\u00e1 a los mandos de Facebook, la plataforma social cuenta con 500 millones, siete veces m\u00e1s que antes de su llegada. Es la que le ha dado m\u00e1s protagonismo al negocio m\u00f3vil de la red social. Hay quien la cataloga como una <b>superestrella en el mundo de los negocios<\/b>.<\/p>\n<h4>2. Su vida antes de llegar a Facebook<\/h4>\n<p>Fue <b>directiva de Google durante siete a\u00f1os<\/b>, desde 2001 hasta 2008. \u00a0Estudi\u00f3 un m\u00e1ster en la Universidad de Harvard, un doctorado dirigido por el economista Larry Summers y fue directora de la secretar\u00eda del Tesoro en la Casa Blanca de Bill Clinton en 2011. Creo que no hace falta que os comente que siempre fue la primera de su clase.<\/p>\n<div align=\"center\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/Sheryl-Sandberg-2Baumentada.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"Sheryl-Sandberg aumentada\" src=\"http:\/\/euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/Sheryl-Sandberg-2Baumentada-300x225.jpg\" alt=\"Sheryl-Sandberg aumentada\" width=\"400\" height=\"300\" border=\"0\" \/><\/a><\/div>\n<h4>3. Joven y millonaria<\/h4>\n<p>Se ha convertido en una de las multimillonarias m\u00e1s j\u00f3venes de la historia de Estados Unidos. <b>Su fortuna supera los 1.000 millones de d\u00f3lares<\/b>. La ejecutiva posee 12,3 millones de acciones de Facebook que ya cotiza cerca de los 62 d\u00f3lares.<\/p>\n<h4>4. Un ejemplo de que se puede tener \u00e9xito en la vida profesional y en la vida familiar<\/h4>\n<p>En la vida familiar, es <b>madre de dos hijos<\/b> y estuvo casada con otro gran directivo de Silicon Valley, <b>David Goldberg<\/b>, quien muri\u00f3 unos meses atr\u00e1s. En su libro \u00abLean In\u00bb Sheryl Sandberg atribuye gran parte de su propio \u00e9xito al matrimonio con Goldberg, que seg\u00fan ella le dio su apoyo en las decisiones de su carrera y compart\u00eda con ella por igual el cuidado de sus ni\u00f1os peque\u00f1os. Se casaron en 2004. En la vida profesional, <b>forma parte del reducido grupo de mujeres que ha conseguido colarse en los equipos directivos de las grandes compa\u00f1\u00edas estadounidenses, un 14%.<\/b><\/p>\n<div align=\"center\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/BODA-2BSHERYL-2BBUENA-2Baumentada.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"BODA SHERYL\" src=\"http:\/\/euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/BODA-2BSHERYL-2BBUENA-2Baumentada-300x225.jpg\" alt=\"BODA SHERYL\" width=\"400\" height=\"300\" border=\"0\" \/><\/a><\/div>\n<h4>5. Activista de los derechos de la mujer<\/h4>\n<p>Frecuentemente ha denunciado las dificultades a las que se enfrentan las mujeres en campos dominados por los hombres, como por ejemplo, la tecnolog\u00eda, y es que la n\u00famero dos de Facebook est\u00e1 comprometida con las pol\u00edticas y acciones por la mujer. <b>Defiende que se les permita a las madres trabajadoras cuidar a sus hijos peque\u00f1os y adoptar bajas por maternidad<\/b>. De hecho, cree que es algo esencial para que una organizaci\u00f3n, del tipo y el sector que sea, compita en la econom\u00eda de hoy en d\u00eda. Y, por supuesto, es muy <b>apasionada sobre la presencia de las mujeres en los puestos de mando<\/b>.<\/p>\n<h4>6. Llora en el trabajo<\/h4>\n<p>Y lo ha admitido p\u00fablicamente, no se averg\u00fcenza de ello. Le ha llegado a llorar a Mark Zuckerberg, creador de Facebook, a lo que \u00e9l le contest\u00f3 \u00ab\u00bfQuieres que te d\u00e9 un abrazo?\u00bb. <b>Eso es precisamente lo que reconforta a esta superwoman: el contacto f\u00edsico<\/b>.<\/p>\n<h4>7. Miembro del consejo ejecutivo de varias empresas<\/h4>\n<p>Ha sido miembro de los consejos directivos de cinco grandes empresas: <b>The Walt Disney Company, Women International, V-Day, Starbucks y Ad Council<\/b>.<\/p>\n<h4>8. Escritora<\/h4>\n<p>Autora del best seller <i>Lean In: Women, Work, and the Will to Lead and found Lean In<\/i> (en espa\u00f1ol: <i><b>Vayamos adelante: Las mujeres, el trabajo y la voluntad de liderar<\/b><\/i>), dedicado a ayudar a las mujeres a alcanzar sus metas. El libro habla de por qu\u00e9 los hombres a\u00fan dominan las funciones de liderazgo tanto en los negocios como en el gobierno y, a trav\u00e9s de este, anima a que las mujeres sean proactivas en la vida profesional.<\/p>\n<p>\u00abCuando las mujeres est\u00e1n sentadas junto a hombres que tienen el mismo nivel de rendimiento, ellos creen que son mejores de lo que nosotras creemos que somos, y hay que cambiar eso\u00bb, explic\u00f3 en una entrevista a la agencia EFE durante la presentaci\u00f3n de su libro.<\/p>\n<div align=\"center\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/LIBRO-2BSHERYL-2BBUENA.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"LIBRO SHERYL BUENA\" src=\"http:\/\/euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/LIBRO-2BSHERYL-2BBUENA.jpg\" alt=\"LIBRO SHERYL BUENA\" width=\"265\" height=\"400\" border=\"0\" \/><\/a><\/div>\n<h4>9. Reconocida por Fortune<\/h4>\n<p>Pocos meses antes de pasar a ser la mano derecha de Zuckerberg, la economista entr\u00f3 en la lista que elabora The Wall Street Journal dedicada a las mujeres que no hay que perder de vista. En el ranking de Fortune aparece en el puesto 16\u00ba de un total de 50 mujeres relevantes en el mundo de los negocios y es considerada como <b>la quinta mujer m\u00e1s poderosa del mundo empresarial<\/b>. Adem\u00e1s, la revista Time la sit\u00faa como <b>una de las 100 personalidades m\u00e1s influyentes del mundo<\/b> y su nombre est\u00e1 grabado en el directorio de Walt Disney y Starbucks.<\/p>\n<h4>10. Simpatizante del partido Dem\u00f3crata<\/h4>\n<p>Sandler est\u00e1 activa en la pol\u00edtica. Entre los hechos pol\u00edticos en los que ha participado se encuentran los siguientes:<br \/>\n1. Fue una <b>gran recaudadora para la campa\u00f1a de reelecci\u00f3n del presidente Obama<\/b> dej\u00e1ndole hacer uso de la plataforma de Facebook para comunicarse con una audiencia internacional.<br \/>\n2. Ha donado <b>fondos a<\/b> un gran n\u00famero de <b>candidatos dem\u00f3cratas<\/b>.3. En 2011 fue <b>directora de la secretar\u00eda del Tesoro en la Casa Blanca de Bill Clinton<\/b>.<\/p>\n<h4>11. Nunca se marcha del trabajo m\u00e1s tarde de las 17.30<\/h4>\n<p>Y es que Sheryl es un genio en cuestiones de organizaci\u00f3n. Asimismo, <b>se levanta antes de las seis y se acuesta a las doce de la noche para cuidar a sus hijos<\/b>.<\/p>\n<div align=\"center\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/FRASE-2BSHERYL-2BBUENA.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/FRASE-2BSHERYL-2BBUENA-300x300.jpg\" alt=\"\" width=\"320\" height=\"320\" border=\"0\" \/><\/a><\/div>\n<h4>12. Fue vicepresidenta de Google<\/h4>\n<p>En Google era la responsable de las ventas y operaciones globales, desde donde vio la dimensi\u00f3n y el potencial del negocio.<\/p>\n<h4>13. Frases c\u00e9lebres de la n\u00famero dos de Facebook<\/h4>\n<p>\u201cSi quieres marcar la diferencia, debes pensar a lo grande\u201d<br \/>\n<span style=\"background-color: white;\">\u201cSi la mitad de nuestras empresas fueran dirigidas por mujeres y la mitad de nuestros hogares por hombres, las cosas ser\u00edan mejores\u201d<\/span><\/p>\n<div align=\"center\"><a style=\"margin-left: 1em; margin-right: 1em;\" href=\"http:\/\/euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/images.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"dibujo mujer\" src=\"http:\/\/euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/images-300x150.jpg\" alt=\"dibujo mujer\" width=\"400\" height=\"200\" border=\"0\" \/><\/a><\/div>\n<h4>14. Siempre tuvo claro que quer\u00eda estar en el coraz\u00f3n del cambio tecnol\u00f3gico<\/h4>\n<p>Ella misma explic\u00f3 en una entrevista que dio el primer salto en Google porque \u201ces un lugar lleno de ambici\u00f3n y de ideas\u201d. Del mismo modo que ocurre con Facebook. Como explic\u00f3 en un discurso ante reci\u00e9n graduados: \u00abNo se trata solo de colgar fotos y usar Facebook para estar en contacto. \u00abQueremos conectar el mundo entero, hacerlo m\u00e1s abierto y transparente\u00bb.<\/p>\n<h4>15. Su sue\u00f1o<\/h4>\n<p>Ayudar a lograr que las mujeres alcancen la igualdad.<b>En el siguiente v\u00eddeo Sheryl Sandberg explica por qu\u00e9 llegan m\u00e1s hombres que mujeres a la cima de su profesi\u00f3n. Asimismo, da 3 consejos para aquellas mujeres que aspiren y quieran llegar a lo m\u00e1s alto.\u00a0<\/b><\/p>\n<div align=\"center\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/C1gbC7s-9FE\" width=\"450\" height=\"253\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<p><b>Asimismo, recomiendo leer <a href=\"http:\/\/www.huffingtonpost.es\/sheryl-sandberg\/despues-de-la-muerte-de_b_7517722.html\" target=\"_blank\" rel=\"nofollow\">la maravillosa carta<\/a> que escribi\u00f3 Sheryl Sandberg a su marido tras este fallecer s\u00fabitamente.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sheryl Sandberg es directora de operaciones de Facebook, activista de los derechos de la mujer y miembro del consejo de varias empresas. Adem\u00e1s de escritora del emblem\u00e1tico libro Lean In: Women, Work, and the Will to Lead and found Lean In, dedicado a ayudar a las mujeres a alcanzar sus metas. 15 cosas que debes conocer sobre ella: 1. Verdadero cerebro empresarial de Facebook Es la directora de operaciones de Facebook y n\u00famero dos de la compa\u00f1\u00eda. Su papel fundamental en esta famosa red social repleta de hombres j\u00f3venes es dotarla de una supervisi\u00f3n adulta y ayudar a que Facebook <\/p>\n","protected":false},"author":15,"featured_media":27,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-9","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ejecutivas","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>15 cosas destacables de Sheryl Sandberg, la ejecutiva m\u00e1s popular en Silicon Valley - Mujeres que rompen moldes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"15 cosas destacables de Sheryl Sandberg, la ejecutiva m\u00e1s popular en Silicon Valley - Mujeres que rompen moldes\" \/>\n<meta property=\"og:description\" content=\"Sheryl Sandberg es directora de operaciones de Facebook, activista de los derechos de la mujer y miembro del consejo de varias empresas. Adem\u00e1s de escritora del emblem\u00e1tico libro Lean In: Women, Work, and the Will to Lead and found Lean In, dedicado a ayudar a las mujeres a alcanzar sus metas. 15 cosas que debes conocer sobre ella: 1. Verdadero cerebro empresarial de Facebook Es la directora de operaciones de Facebook y n\u00famero dos de la compa\u00f1\u00eda. Su papel fundamental en esta famosa red social repleta de hombres j\u00f3venes es dotarla de una supervisi\u00f3n adulta y ayudar a que Facebook\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/\" \/>\n<meta property=\"og:site_name\" content=\"Mujeres que rompen moldes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/euroresidentes\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-08T10:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-24T10:10:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/PORTADA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura C\u00e1rdenas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura C\u00e1rdenas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\\\/\"},\"author\":{\"name\":\"Laura C\u00e1rdenas\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/#\\\/schema\\\/person\\\/421f8bd7657686e00fe14b7b8819ffc3\"},\"headline\":\"15 cosas destacables de Sheryl Sandberg, la ejecutiva m\u00e1s popular en Silicon Valley\",\"datePublished\":\"2015-09-08T10:01:00+00:00\",\"dateModified\":\"2016-02-24T10:10:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\\\/\"},\"wordCount\":1189,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2015\\\/09\\\/PORTADA.jpg\",\"articleSection\":[\"Ejecutivas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\\\/\",\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\\\/\",\"name\":\"15 cosas destacables de Sheryl Sandberg, la ejecutiva m\u00e1s popular en Silicon Valley - Mujeres que rompen moldes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2015\\\/09\\\/PORTADA.jpg\",\"datePublished\":\"2015-09-08T10:01:00+00:00\",\"dateModified\":\"2016-02-24T10:10:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/#\\\/schema\\\/person\\\/421f8bd7657686e00fe14b7b8819ffc3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2015\\\/09\\\/PORTADA.jpg\",\"contentUrl\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2015\\\/09\\\/PORTADA.jpg\",\"width\":600,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"15 cosas destacables de Sheryl Sandberg, la ejecutiva m\u00e1s popular en Silicon Valley\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/#website\",\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/\",\"name\":\"Mujeres que rompen moldes\",\"description\":\"Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/#\\\/schema\\\/person\\\/421f8bd7657686e00fe14b7b8819ffc3\",\"name\":\"Laura C\u00e1rdenas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2016\\\/02\\\/laura_cardenas-150x150.jpg\",\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2016\\\/02\\\/laura_cardenas-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2016\\\/02\\\/laura_cardenas-150x150.jpg\",\"caption\":\"Laura C\u00e1rdenas\"},\"description\":\"Laura CardenasConsultora de comunicaci\u00f3n y visibilidad, cooperaci\u00f3n y RSC. Experta en proyectos de cooperaci\u00f3n de la Uni\u00f3n Europea.\",\"sameAs\":[\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/laura-cardenas.html\"],\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/mujeres-que-rompen-moldes\\\/author\\\/lauracardenas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"15 cosas destacables de Sheryl Sandberg, la ejecutiva m\u00e1s popular en Silicon Valley - Mujeres que rompen moldes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/","og_locale":"es_ES","og_type":"article","og_title":"15 cosas destacables de Sheryl Sandberg, la ejecutiva m\u00e1s popular en Silicon Valley - Mujeres que rompen moldes","og_description":"Sheryl Sandberg es directora de operaciones de Facebook, activista de los derechos de la mujer y miembro del consejo de varias empresas. Adem\u00e1s de escritora del emblem\u00e1tico libro Lean In: Women, Work, and the Will to Lead and found Lean In, dedicado a ayudar a las mujeres a alcanzar sus metas. 15 cosas que debes conocer sobre ella: 1. Verdadero cerebro empresarial de Facebook Es la directora de operaciones de Facebook y n\u00famero dos de la compa\u00f1\u00eda. Su papel fundamental en esta famosa red social repleta de hombres j\u00f3venes es dotarla de una supervisi\u00f3n adulta y ayudar a que Facebook","og_url":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/","og_site_name":"Mujeres que rompen moldes","article_publisher":"https:\/\/www.facebook.com\/euroresidentes\/","article_published_time":"2015-09-08T10:01:00+00:00","article_modified_time":"2016-02-24T10:10:41+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/PORTADA.jpg","type":"image\/jpeg"}],"author":"Laura C\u00e1rdenas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Laura C\u00e1rdenas","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/#article","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/"},"author":{"name":"Laura C\u00e1rdenas","@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/#\/schema\/person\/421f8bd7657686e00fe14b7b8819ffc3"},"headline":"15 cosas destacables de Sheryl Sandberg, la ejecutiva m\u00e1s popular en Silicon Valley","datePublished":"2015-09-08T10:01:00+00:00","dateModified":"2016-02-24T10:10:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/"},"wordCount":1189,"commentCount":2,"image":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/PORTADA.jpg","articleSection":["Ejecutivas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/","url":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/","name":"15 cosas destacables de Sheryl Sandberg, la ejecutiva m\u00e1s popular en Silicon Valley - Mujeres que rompen moldes","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/#primaryimage"},"image":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/PORTADA.jpg","datePublished":"2015-09-08T10:01:00+00:00","dateModified":"2016-02-24T10:10:41+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/#\/schema\/person\/421f8bd7657686e00fe14b7b8819ffc3"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/#primaryimage","url":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/PORTADA.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2015\/09\/PORTADA.jpg","width":600,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/15-cosas-destacables-de-sheryl-sandberg-la-ejecutiva-mas-popular-en-silicon-valley\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/"},{"@type":"ListItem","position":2,"name":"15 cosas destacables de Sheryl Sandberg, la ejecutiva m\u00e1s popular en Silicon Valley"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/#website","url":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/","name":"Mujeres que rompen moldes","description":"Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/#\/schema\/person\/421f8bd7657686e00fe14b7b8819ffc3","name":"Laura C\u00e1rdenas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2016\/02\/laura_cardenas-150x150.jpg","url":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2016\/02\/laura_cardenas-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-content\/uploads\/sites\/5\/2016\/02\/laura_cardenas-150x150.jpg","caption":"Laura C\u00e1rdenas"},"description":"Laura CardenasConsultora de comunicaci\u00f3n y visibilidad, cooperaci\u00f3n y RSC. Experta en proyectos de cooperaci\u00f3n de la Uni\u00f3n Europea.","sameAs":["https:\/\/www.euroresidentes.com\/empresa\/laura-cardenas.html"],"url":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/author\/lauracardenas\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-json\/wp\/v2\/posts\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":4,"href":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-json\/wp\/v2\/posts\/9\/revisions"}],"predecessor-version":[{"id":4066,"href":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-json\/wp\/v2\/posts\/9\/revisions\/4066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-json\/wp\/v2\/media\/27"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-json\/wp\/v2\/media?parent=9"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-json\/wp\/v2\/categories?post=9"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/mujeres-que-rompen-moldes\/wp-json\/wp\/v2\/tags?post=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}