
{"id":794,"date":"2016-11-02T15:17:31","date_gmt":"2016-11-02T14:17:31","guid":{"rendered":"http:\/\/www.euroresidentes.com\/empresa\/liderazgo\/?p=794"},"modified":"2016-11-03T20:16:50","modified_gmt":"2016-11-03T19:16:50","slug":"motivar-a-los-empleados","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/","title":{"rendered":"Para motivar a tus empleados, haz estas 3 cosas bien"},"content":{"rendered":"<h3>\u00bfC\u00f3mo motivar a los empleados?<\/h3>\n<p>Una encuesta reciente publicada en <a href=\"http:\/\/www.gallup.com\/topic\/employee_engagement.aspx\" target=\"_blank\">Gallup<\/a> mostr\u00f3 que el 70% de los empleados\u00a0no se sienten \u00abcomprometidos\u00bb ni \u00abconectados\u00bb a su trabajo. Los l\u00edderes -como es normal- deben buscar soluciones a este problema.<\/p>\n<p><a href=\"http:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-795\" src=\"http:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados.jpg\" alt=\"motivar a los empleados\" width=\"700\" height=\"525\" srcset=\"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados.jpg 700w, https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados-300x225.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>Algunos recurren a recompensas materiales (pagas, salas de juegos, comida gratis) con la esperanza de hacer m\u00e1s felices a sus empleados. Sin embargo, la investigaci\u00f3n sugiere que esa clase de esfuerzos, aunque apreciados, <a href=\"http:\/\/www.tandfonline.com\/doi\/abs\/10.1080\/17439760.2013.830764\" target=\"_blank\">no conducen a mayor bienestar<\/a> a largo plazo.<\/p>\n<p><!-- inserta publi --><\/p>\n<p><strong>Si los l\u00edderes realmente quieren motivar y hacer sentir bien a sus empleados han de hacer 3 cosas:<\/strong><\/p>\n<h3>1. Inspiraci\u00f3n<\/h3>\n<p>No importa a qu\u00e9 se dedica tu organizaci\u00f3n, lo importante es que la cultura de la empresa se transmita con un sentido. <a href=\"http:\/\/psycnet.apa.org\/journals\/gpr\/13\/3\/242\/\" target=\"_blank\">Los estudios <\/a>demuestran que las personas que tienen un prop\u00f3sito en su trabajo est\u00e1n m\u00e1s centradas, son m\u00e1s creativas y <a href=\"https:\/\/www.euroresidentes.com\/estilo-de-vida\/sentir-bien\/que-es-la-resiliencia-y-su-importancia\" target=\"_blank\">resilientes<\/a>, <strong>por eso los l\u00edderes siempre\u00a0deber\u00edan encargarse de recordar a sus empleados c\u00f3mo su trabajo est\u00e1 mejorando la vida de otras personas<\/strong>.\u00a0Compartir las opiniones positivas de los clientes y anunciar cu\u00e1ndo se donan\u00a0ayudas a organizaciones ben\u00e9ficas\u00a0son s\u00f3lo un par de ejemplos de c\u00f3mo hacerlo.<\/p>\n<p><!-- inserta publi --><\/p>\n<p>La <a href=\"http:\/\/amr.aom.org\/content\/37\/4\/589.abstract\" target=\"_blank\">investigaci\u00f3n llevada a cabo por\u00a0Adam Grant<\/a> muestra que incluso los trabajadores insatisfechos se sienten mejor con\u00a0su trabajo cuando dedican tiempo a buenas causas <strong>y sienten que su empresa apoya programas que son efectivos no s\u00f3lo para\u00a0gente que necesita ayuda, tambi\u00e9n para quien puede darla.\u00a0<\/strong><\/p>\n<p>Los l\u00edderes pueden ser tambi\u00e9n grandes fuentes de inspiraci\u00f3n para sus\u00a0empleados. Los estudios muestran que cuando act\u00faan desinteresadamente, demostrando que se preocupan m\u00e1s por el equipo que por ellos mismos, <strong>los trabajadores son m\u00e1s cooperativos, leales, comprometidos, confiados y mejores compa\u00f1eros<\/strong>. Los jefes que demuestran que son justos tambi\u00e9n inspiran a sus empleados a una mayor dedicaci\u00f3n y productividad, <a href=\"http:\/\/onlinelibrary.wiley.com\/doi\/10.1111\/j.1540-5885.2009.00344.x\/abstract\" target=\"_blank\">como Wayne Baker ha demostrado<\/a>.\u00a0<\/p>\n<p>Aseg\u00farate de trabajar con tu\u00a0equipo\u00a0sobre unas bases diarias o semanales, mostrando tu lealtad hacia ellos y hacia la organizaci\u00f3n en general.\u00a0<\/p>\n<h3>2. Amabilidad<\/h3>\n<p><a href=\"http:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados-liderazgo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-796\" src=\"http:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados-liderazgo.jpg\" alt=\"motivar a los empleados\" width=\"700\" height=\"525\" srcset=\"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados-liderazgo.jpg 700w, https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados-liderazgo-300x225.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>Somos criaturas profundamente sociales, pero las interacciones en el lugar de trabajo no son m\u00e1s que\u00a0simples intercambios. <strong>Esto es un error<\/strong>. De acuerdo con un <a href=\"https:\/\/www.aat.org.uk\/about-aat\/press-releases\/britains-workers-value-companionship-recognition-over-big-salary\" target=\"_blank\">estudio brit\u00e1nico<\/a>, el compa\u00f1erismo y el reconocimiento son m\u00e1s importantes para\u00a0la lealtad de los empleados que un salario alto.\u00a0<\/p>\n<p><a href=\"http:\/\/onlinelibrary.wiley.com\/doi\/10.1111\/joop.12053\/abstract\" target=\"_blank\">Otro estudio<\/a> confirma que tener\u00a0relaciones positivas y cercanas con los compa\u00f1eros\u00a0es uno de los predictores m\u00e1s importantes del bienestar psicol\u00f3gico, <strong>de ah\u00ed la importancia de que los l\u00edderes sean conscientes\u00a0de la cultura que est\u00e1n creando y los sentimientos que expresan en el trabajo.<\/strong><\/p>\n<p>Los fundamentos de una cultura amable incluyen consideraci\u00f3n y respeto, lo que hace aumentar la creatividad tanto individual como grupalmente, tal y como han\u00a0descubierto <a href=\"http:\/\/webuser.bus.umich.edu\/janedut\/High%20Quality%20Connections\/Respect%20as%20an%20Engine.pdf\" target=\"_blank\">Jane Dutton y sus colegas<\/a> en la Universidad de Michigan. <strong>La calidez del l\u00edder tambi\u00e9n importa:<\/strong> la <a href=\"http:\/\/psycnet.apa.org\/journals\/apl\/69\/3\/422\/\" target=\"_blank\">investigaci\u00f3n de Dean Tjosvold<\/a> en la Universidad de Lingnan ha demostrado que un l\u00edder cercano hace m\u00e1s productivos y motivados a sus trabajadores, lo que hace que su liderazgo sea mucho m\u00e1s efectivo.<\/p>\n<p>Aunque mostrar ira y enfado puede tener algunos beneficios (Daan Van Knippenburg demostr\u00f3 que algunos trabajadores respond\u00edan positivamente a ellas, y <a href=\"http:\/\/web.mit.edu\/curhan\/www\/docs\/Articles\/15341_Readings\/Affect\/Tiedens.pdf\" target=\"_blank\">Lara Tiedens<\/a> que el algunos casos mostrar ira te hac\u00eda parecer m\u00e1s poderoso y competente) <a href=\"http:\/\/onlinelibrary.wiley.com\/doi\/10.1002\/%28SICI%291099-1379%28200003%2921:2%3C221::AID-JOB36%3E3.0.CO;2-0\/abstract\" target=\"_blank\">la mayor\u00eda de estudios<\/a> confirma que l<strong>as emociones negativas generalmente causan que los l\u00edderes sean vistos como menos efectivos.<\/strong><\/p>\n<p>Los l\u00edderes amables hacen peque\u00f1as cosas para demostrar que ven a su equipo como personas, no simplemente como meros empleados. Simplemente preguntar a alguno de ellos c\u00f3mo le va con x cosa y escuchar su respuesta es un buen primer paso. Adem\u00e1s estas pr\u00e1cticas pueden convertirse en un h\u00e1bito para la empresa. En una de las 100 primeras empresas en la lista Fortune, <strong>si un empleado est\u00e1 seriamente enfermo o ha sufrido un p\u00e9rdida, se le notifica inmediatamente al CEO para que pueda comunicarse con la persona cuanto antes<\/strong>. En uno de los casos, despu\u00e9s de que una ejecutivo notificara a su jefe que hab\u00eda sigo diagnosticada con c\u00e1ncer cerebral, el CEO la llam\u00f3 a los 15 minutos pregunt\u00e1ndole c\u00f3mo \u00e9l y la organizaci\u00f3n pod\u00edan ayudarla.<\/p>\n<h3>3. Autocuidado<\/h3>\n<p><a href=\"http:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/como-motivar-a-los-empleados.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-797\" src=\"http:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/como-motivar-a-los-empleados.jpg\" alt=\"c\u00f3mo motivar a los empleados\" width=\"700\" height=\"525\" srcset=\"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/como-motivar-a-los-empleados.jpg 700w, https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/como-motivar-a-los-empleados-300x225.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>Muchas empresas presumen de lo que hacen por el bienestar de sus empleados &#8211; por ejemplo ofreciendo descuentos, yoga, o clases de meditaci\u00f3n- pero los intensos horarios de trabajo a\u00fan no permiten a la gente aprovecharse de sus ventajas.<\/p>\n<p><strong>Los programas de bienestar no funcionan hasta que no crees una cultura en tu empresa donde se priorice el autocuidado.<\/strong> <a href=\"http:\/\/onlinelibrary.wiley.com\/doi\/10.1002\/job.1924\/abstract\" target=\"_blank\">Seg\u00fan Sabine Sonnentag<\/a> de la Universidad de Konstanz en Alemania el ejercicios, las pausas en el trabajo, las actividades de relajaci\u00f3n y poner l\u00edmites m\u00e1s estrictos entre el trabajo y casa pueden reducir el estr\u00e9s laboral y aumentar el compromiso y el bienestar de los empleados.<\/p>\n<p><!-- inserta publi 2 --><\/p>\n<p>Tambi\u00e9n puedes animarles a que cuiden de un recurso b\u00e1sico: <a href=\"http:\/\/sloanreview.mit.edu\/article\/why-sleep-is-a-strategic-resource\/\" target=\"_blank\">dormir<\/a>. Un personal bien descansado es m\u00e1s feliz y rinde m\u00e1s. Numerosos estudios, entre ellos e<a href=\"http:\/\/www.sciencedirect.com\/science\/article\/pii\/S2211368111000052\" target=\"_blank\">l de las Fuerzas Aer\u00e9as estadounidenses<\/a>, muestran que <strong>no dormir afecta las habilidades cognitivas y motoras<\/strong>, mientras que <a href=\"http:\/\/cdp.sagepub.com\/content\/18\/4\/210.abstract\" target=\"_blank\">otros aseguran<\/a> que<strong> las mejores ideas y soluciones a los problemas vienen cuando el cerebro est\u00e1 en modo alfa,\u00a0ese estado borroso del cerebro cuando est\u00e1s a punto de dormirte<\/strong>. As\u00ed que anima a tus empleados a que hagan ejercicio, hagan descansos, y duerman bien.<\/p>\n<p>Podr\u00edas seguir el ejemplo de algunas empresas alemanas y prohibir el correo fuera de las horas de trabajo\u00a0exceptuando emergencias, o dar a los empleados ejercicios y consejos para una buena higiene del sue\u00f1o, como Fitbits. <strong>No olvides adem\u00e1s que el ejemplo es m\u00e1s poderoso que cualquier palabra, as\u00ed que cuida de ti mismo.<\/strong><\/p>\n<p>Es f\u00e1cil perder de vista lo que motiva a tus\u00a0empleados cuando est\u00e1s teniendo una dura semana de trabajo o est\u00e1s en medio de un importante proyecto. Los mejores l\u00edderes son capaces de dar un paso atr\u00e1s y mantener el toque humano en el lugar de trabajo. Inspirando a otros, siendo amables con ellos, y anim\u00e1ndolos a cuidar de s\u00ed mismos.<\/p>\n<p>Yo como siempre te espero en la pr\u00f3xima. Un gran saludo y un abrazo, Andrea.<\/p>\n<p><strong>Ver m\u00e1s:<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/www.euroresidentes.com\/empresa\/liderazgo\/lider-carismatico-e-influyente\" target=\"_blank\">Cultivando el carisma: 3 Consejos para convertirte en un l\u00edder m\u00e1s influyente<\/a><\/li>\n<li><a href=\"http:\/\/www.euroresidentes.com\/empresa\/liderazgo\/10-consejos-para-motivar-a-tus-empleados\" target=\"_blank\">10 Consejos para motivar a tus empleados<\/a><\/li>\n<li><a href=\"http:\/\/www.euroresidentes.com\/empresa\/liderazgo\/100-reglas-de-sentido-comun-para-los-lideres\" target=\"_blank\">100 Reglas de sentido com\u00fan para los l\u00edderes<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo motivar a los empleados? Una encuesta reciente publicada en Gallup mostr\u00f3 que el 70% de los empleados\u00a0no se sienten \u00abcomprometidos\u00bb ni \u00abconectados\u00bb a su trabajo. Los l\u00edderes -como es normal- deben buscar soluciones a este problema. Algunos recurren a recompensas materiales (pagas, salas de juegos, comida gratis) con la esperanza de hacer m\u00e1s felices a sus empleados. Sin embargo, la investigaci\u00f3n sugiere que esa clase de esfuerzos, aunque apreciados, no conducen a mayor bienestar a largo plazo. Si los l\u00edderes realmente quieren motivar y hacer sentir bien a sus empleados han de hacer 3 cosas: 1. Inspiraci\u00f3n No importa <\/p>\n","protected":false},"author":12,"featured_media":796,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-habilidades","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Para motivar a tus empleados, haz estas 3 cosas bien - Liderazgo<\/title>\n<meta name=\"description\" content=\"El 70% de los empleados no se sienten comprometidos. Si los l\u00edderes realmente quieren motivar a los empleados y hacerles sentir bien deben hacer 3 cosas:\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Para motivar a tus empleados, haz estas 3 cosas bien - Liderazgo\" \/>\n<meta property=\"og:description\" content=\"El 70% de los empleados no se sienten comprometidos. Si los l\u00edderes realmente quieren motivar a los empleados y hacerles sentir bien deben hacer 3 cosas:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/\" \/>\n<meta property=\"og:site_name\" content=\"Liderazgo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sentir.bien.euroresidentes\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/andrea.mendezmolla?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-02T14:17:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-11-03T19:16:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados-liderazgo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea M\u00e9ndez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea M\u00e9ndez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/motivar-a-los-empleados\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/motivar-a-los-empleados\\\/\"},\"author\":{\"name\":\"Andrea M\u00e9ndez\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/#\\\/schema\\\/person\\\/281adc4944d313f79100bfefb794fbcf\"},\"headline\":\"Para motivar a tus empleados, haz estas 3 cosas bien\",\"datePublished\":\"2016-11-02T14:17:31+00:00\",\"dateModified\":\"2016-11-03T19:16:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/motivar-a-los-empleados\\\/\"},\"wordCount\":1124,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/motivar-a-los-empleados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/11\\\/motivar-a-los-empleados-liderazgo.jpg\",\"articleSection\":[\"Habilidades\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/motivar-a-los-empleados\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/motivar-a-los-empleados\\\/\",\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/motivar-a-los-empleados\\\/\",\"name\":\"Para motivar a tus empleados, haz estas 3 cosas bien - Liderazgo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/motivar-a-los-empleados\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/motivar-a-los-empleados\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/11\\\/motivar-a-los-empleados-liderazgo.jpg\",\"datePublished\":\"2016-11-02T14:17:31+00:00\",\"dateModified\":\"2016-11-03T19:16:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/#\\\/schema\\\/person\\\/281adc4944d313f79100bfefb794fbcf\"},\"description\":\"El 70% de los empleados no se sienten comprometidos. Si los l\u00edderes realmente quieren motivar a los empleados y hacerles sentir bien deben hacer 3 cosas:\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/motivar-a-los-empleados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/motivar-a-los-empleados\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/motivar-a-los-empleados\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/11\\\/motivar-a-los-empleados-liderazgo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/11\\\/motivar-a-los-empleados-liderazgo.jpg\",\"width\":700,\"height\":525,\"caption\":\"motivar a los empleados\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/motivar-a-los-empleados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Para motivar a tus empleados, haz estas 3 cosas bien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/#website\",\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/\",\"name\":\"Liderazgo\",\"description\":\"Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/#\\\/schema\\\/person\\\/281adc4944d313f79100bfefb794fbcf\",\"name\":\"Andrea M\u00e9ndez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/02\\\/foto_Andrea-150x150.png\",\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/02\\\/foto_Andrea-150x150.png\",\"contentUrl\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2016\\\/02\\\/foto_Andrea-150x150.png\",\"caption\":\"Andrea M\u00e9ndez\"},\"description\":\"Andrea M\u00e9ndezPsic\u00f3loga y autora de blogs orientados a la motivaci\u00f3n, el liderazgo y la superaci\u00f3n personal.\",\"sameAs\":[\"https:\\\/\\\/www.euroresidentes.com\\\/estilo-de-vida\\\/andrea-mendez\",\"https:\\\/\\\/www.facebook.com\\\/andrea.mendezmolla?fref=ts\"],\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/liderazgo\\\/author\\\/andrea\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Para motivar a tus empleados, haz estas 3 cosas bien - Liderazgo","description":"El 70% de los empleados no se sienten comprometidos. Si los l\u00edderes realmente quieren motivar a los empleados y hacerles sentir bien deben hacer 3 cosas:","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/","og_locale":"es_ES","og_type":"article","og_title":"Para motivar a tus empleados, haz estas 3 cosas bien - Liderazgo","og_description":"El 70% de los empleados no se sienten comprometidos. Si los l\u00edderes realmente quieren motivar a los empleados y hacerles sentir bien deben hacer 3 cosas:","og_url":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/","og_site_name":"Liderazgo","article_publisher":"https:\/\/www.facebook.com\/sentir.bien.euroresidentes\/","article_author":"https:\/\/www.facebook.com\/andrea.mendezmolla?fref=ts","article_published_time":"2016-11-02T14:17:31+00:00","article_modified_time":"2016-11-03T19:16:50+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados-liderazgo.jpg","type":"image\/jpeg"}],"author":"Andrea M\u00e9ndez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Andrea M\u00e9ndez","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/#article","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/"},"author":{"name":"Andrea M\u00e9ndez","@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/#\/schema\/person\/281adc4944d313f79100bfefb794fbcf"},"headline":"Para motivar a tus empleados, haz estas 3 cosas bien","datePublished":"2016-11-02T14:17:31+00:00","dateModified":"2016-11-03T19:16:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/"},"wordCount":1124,"commentCount":0,"image":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados-liderazgo.jpg","articleSection":["Habilidades"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/","url":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/","name":"Para motivar a tus empleados, haz estas 3 cosas bien - Liderazgo","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/#primaryimage"},"image":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados-liderazgo.jpg","datePublished":"2016-11-02T14:17:31+00:00","dateModified":"2016-11-03T19:16:50+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/#\/schema\/person\/281adc4944d313f79100bfefb794fbcf"},"description":"El 70% de los empleados no se sienten comprometidos. Si los l\u00edderes realmente quieren motivar a los empleados y hacerles sentir bien deben hacer 3 cosas:","breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/#primaryimage","url":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados-liderazgo.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/11\/motivar-a-los-empleados-liderazgo.jpg","width":700,"height":525,"caption":"motivar a los empleados"},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/motivar-a-los-empleados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/"},{"@type":"ListItem","position":2,"name":"Para motivar a tus empleados, haz estas 3 cosas bien"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/#website","url":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/","name":"Liderazgo","description":"Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/#\/schema\/person\/281adc4944d313f79100bfefb794fbcf","name":"Andrea M\u00e9ndez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/02\/foto_Andrea-150x150.png","url":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/02\/foto_Andrea-150x150.png","contentUrl":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-content\/uploads\/sites\/6\/2016\/02\/foto_Andrea-150x150.png","caption":"Andrea M\u00e9ndez"},"description":"Andrea M\u00e9ndezPsic\u00f3loga y autora de blogs orientados a la motivaci\u00f3n, el liderazgo y la superaci\u00f3n personal.","sameAs":["https:\/\/www.euroresidentes.com\/estilo-de-vida\/andrea-mendez","https:\/\/www.facebook.com\/andrea.mendezmolla?fref=ts"],"url":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/author\/andrea\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-json\/wp\/v2\/posts\/794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-json\/wp\/v2\/comments?post=794"}],"version-history":[{"count":2,"href":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-json\/wp\/v2\/posts\/794\/revisions"}],"predecessor-version":[{"id":799,"href":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-json\/wp\/v2\/posts\/794\/revisions\/799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-json\/wp\/v2\/media\/796"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-json\/wp\/v2\/media?parent=794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-json\/wp\/v2\/categories?post=794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/liderazgo\/wp-json\/wp\/v2\/tags?post=794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}