
{"id":2020,"date":"2019-06-18T09:25:40","date_gmt":"2019-06-18T07:25:40","guid":{"rendered":"http:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/?p=2020"},"modified":"2019-06-18T09:25:41","modified_gmt":"2019-06-18T07:25:41","slug":"negocio-alquiler-balcones","status":"publish","type":"post","link":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/","title":{"rendered":"El negocio de alquiler de balcones"},"content":{"rendered":"<p style=\"text-align: justify\">Hace unos meses comenz\u00f3 el plazo de presentaci\u00f3n de la Declaraci\u00f3n de la Renta 2018 para cumplir con Hacienda por los ingresos obtenidos en el ejercicio pasado.<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">Por regla general, la campa\u00f1a de la Declaraci\u00f3n de la Renta de cada a\u00f1o trae consigo algunas novedades. Este a\u00f1o destacamos el nuevo umbral para determinar qui\u00e9nes est\u00e1n obligados a declarar, la ampliaci\u00f3n de las deducciones para familias numerosas y la exenci\u00f3n del pago de IRPF de los ingresos correspondientes a prestaciones de maternidad y paternidad.<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">Pero \u00bfQu\u00e9 pasa con otras costumbres de menor repercusi\u00f3n, pero muy habituales en nuestro Pa\u00eds?<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">En resumidas cuent<span style=\"color: #333333\">as, para evitar sorpresas en preciso no olvidarse de incluir en el IRPF todos los ingresos y operaciones econ\u00f3micas sujetas a tributaci\u00f3n.\u00a0<\/span><\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">Hacienda lleva a\u00f1os advirti\u00e9ndolo, hasta que finalmente ha sido en la campa\u00f1a de la Renta 2018 cuando ha implantado la obligaci\u00f3n de declarar el alquiler de los balcones para ver las procesiones de Semana Santa.<\/p>\n<p style=\"text-align: justify\"><a href=\"http:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2019\/06\/spain-711632_1920.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2021\" src=\"http:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2019\/06\/spain-711632_1920-300x214.jpg\" alt=\"\" width=\"400\" height=\"285\" srcset=\"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2019\/06\/spain-711632_1920-300x214.jpg 300w, https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2019\/06\/spain-711632_1920-768x548.jpg 768w, https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2019\/06\/spain-711632_1920.jpg 1024w, https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2019\/06\/spain-711632_1920-416x297.jpg 416w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/p>\n<p style=\"text-align: justify\">El alquiler de balcones para disfrutar de las procesiones de Semana Santa desde un sitio con mejores vistas es una costumbre que en esas fechas es cada vez m\u00e1s com\u00fan y solicitada. En los \u00faltimos a\u00f1os ha incrementado tanto la oferta como la demanda, hasta llegar a pagar miles de euros por un d\u00eda o por tan s\u00f3lo unas horas.<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">A partir de ahora es muy importante tener en cuenta que no s\u00f3lo hay que declarar los ingresos obtenidos como consecuencia del alquiler de balcones, sino que, en el caso de no hacerlo, se impondr\u00e1n a los responsables importantes sanciones consistentes en multas econ\u00f3micas.<\/p>\n<p style=\"text-align: justify\">De ahora en adelante, la Agencia Tributaria estar\u00e1 especialmente atenta a este tipo de celebraciones para controlar irregularidades e imponer las sanciones que procedan.<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">Por una parte, es muy recomendado formalizar un contrato de alquiler en el que intervengan ambas partes y conste debidamente firmado.<\/p>\n<p style=\"text-align: justify\">Un contrato que refleje en la medida de lo posible todas las condiciones relevantes de dicho acuerdo, por ejemplo:<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<ul style=\"text-align: justify\">\n<li>La fecha; si se trata de un alquiler de balc\u00f3n para varios d\u00edas, un \u00fanico d\u00eda o simplemente unas horas;<\/li>\n<li>El precio para pagar y la forma de abonarlo;<\/li>\n<li>La posibilidad de usar otras partes de la vivienda en cuesti\u00f3n en el caso de que sea un alquiler por horas;<\/li>\n<li>Consecuencias de la posible cancelaci\u00f3n del evento.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">Por otra parte, para declarar el alquiler de un balc\u00f3n en Semana Santa, se deber\u00e1 incluir en la declaraci\u00f3n de la renta como un rendimiento de capital inmobiliario, indicando exactamente cu\u00e1nto se ha recibido por dicho alquiler.<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">La Ley 35\/2006, de 28 de noviembre, del Impuesto sobre la Renta de las Personas F\u00edsicas y de modificaci\u00f3n parcial de las leyes de los Impuestos sobre Sociedades, sobre la Renta de no Residentes y sobre el Patrimonio establece en su art\u00edculo 25 qu\u00e9 se entiende por rendimientos de capital mobiliario. Concretamente, es en el punto cuarto del referido art\u00edculo donde se encuentra reflejado el alquiler de balcones.<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\"><em>\u201c4. Otros rendimientos del capital mobiliario.<\/em><\/p>\n<p style=\"text-align: justify\"><em>Quedan incluidos en este apartado, entre otros, los siguientes rendimientos, dinerarios o en especie:<\/em><\/p>\n<p style=\"text-align: justify\"><em>\u00a0<\/em><\/p>\n<ol style=\"text-align: justify\">\n<li><em>a) Los procedentes de la propiedad intelectual cuando el contribuyente no sea el autor y los procedentes de la propiedad industrial que no se encuentre afecta a actividades econ\u00f3micas realizadas por el contribuyente.<\/em><\/li>\n<li><em>b) Los procedentes de la prestaci\u00f3n de asistencia t\u00e9cnica, salvo que dicha prestaci\u00f3n tenga lugar en el \u00e1mbito de una actividad econ\u00f3mica.<\/em><\/li>\n<li><em>c) Los procedentes del arrendamiento de bienes muebles, negocios o minas, as\u00ed como los procedentes del subarrendamiento percibidos por el subarrendador, que no constituyan actividades econ\u00f3micas.<\/em><\/li>\n<li><em>d) Los procedentes de la cesi\u00f3n del derecho a la explotaci\u00f3n de la imagen o del consentimiento o autorizaci\u00f3n para su utilizaci\u00f3n, salvo que dicha cesi\u00f3n tenga lugar en el \u00e1mbito de una actividad econ\u00f3mica\u201d.<\/em><\/li>\n<\/ol>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">Por \u00faltimo, es importante conocer las consecuencias de no declarar este tipo de alquileres.<\/p>\n<p style=\"text-align: justify\">La respuesta: una multa.<\/p>\n<p style=\"text-align: justify\">De no hacerlo, el propietario se enfrentar\u00e1 a multas graduales de entre un 50 y un 150 por ciento del precio pactado por el alquiler del balc\u00f3n y no declarado en la renta. Adem\u00e1s de estar en el punto de mira de Hacienda para los pr\u00f3ximos a\u00f1os.<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">Estamos hablando de una pr\u00e1ctica muy habitual en muchas localidades de nuestro Pa\u00eds, pero no s\u00f3lo durante la Semana Santa sino tambi\u00e9n en otras fiestas nacional e internacionalmente conocidas como los Sanfermines, donde se alquilan balcones o incluso zonas de ventanales para disfrutar del \u201cChupinazo y de los encierros\u201d o las Fallas, donde los balcones de la Plaza del Ayuntamiento se convierten en lo m\u00e1s cotizado de la ciudad para disfrutar de la Masclet\u00e1.\u00a0<\/p>\n<p style=\"text-align: justify\">\u00a0<\/p>\n<p style=\"text-align: justify\">Habr\u00e1 que esperar a que finalice el plazo para presentar la Renta de 2018 para ver si realmente el negocio de alquiler de los balcones es un ingreso declarado como exige Hacienda o sigue estando en la sombra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace unos meses comenz\u00f3 el plazo de presentaci\u00f3n de la Declaraci\u00f3n de la Renta 2018 para cumplir con Hacienda por los ingresos obtenidos en el ejercicio pasado. \u00a0 Por regla general, la campa\u00f1a de la Declaraci\u00f3n de la Renta de cada a\u00f1o trae consigo algunas novedades. Este a\u00f1o destacamos el nuevo umbral para determinar qui\u00e9nes est\u00e1n obligados a declarar, la ampliaci\u00f3n de las deducciones para familias numerosas y la exenci\u00f3n del pago de IRPF de los ingresos correspondientes a prestaciones de maternidad y paternidad. \u00a0 Pero \u00bfQu\u00e9 pasa con otras costumbres de menor repercusi\u00f3n, pero muy habituales en nuestro Pa\u00eds? <\/p>\n","protected":false},"author":9,"featured_media":2021,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[268,270,269],"class_list":["post-2020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-alquiler-balcones","tag-declarar","tag-irpf","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El negocio de alquiler de balcones - Derecho Mercantil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El negocio de alquiler de balcones - Derecho Mercantil\" \/>\n<meta property=\"og:description\" content=\"Hace unos meses comenz\u00f3 el plazo de presentaci\u00f3n de la Declaraci\u00f3n de la Renta 2018 para cumplir con Hacienda por los ingresos obtenidos en el ejercicio pasado. \u00a0 Por regla general, la campa\u00f1a de la Declaraci\u00f3n de la Renta de cada a\u00f1o trae consigo algunas novedades. Este a\u00f1o destacamos el nuevo umbral para determinar qui\u00e9nes est\u00e1n obligados a declarar, la ampliaci\u00f3n de las deducciones para familias numerosas y la exenci\u00f3n del pago de IRPF de los ingresos correspondientes a prestaciones de maternidad y paternidad. \u00a0 Pero \u00bfQu\u00e9 pasa con otras costumbres de menor repercusi\u00f3n, pero muy habituales en nuestro Pa\u00eds?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/\" \/>\n<meta property=\"og:site_name\" content=\"Derecho Mercantil\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/euroresidentes\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-18T07:25:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-18T07:25:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2019\/06\/spain-711632_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"731\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Manuel Pomares\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Pomares\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/negocio-alquiler-balcones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/negocio-alquiler-balcones\\\/\"},\"author\":{\"name\":\"Manuel Pomares\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/#\\\/schema\\\/person\\\/1f848038ac5623245414f398a267708f\"},\"headline\":\"El negocio de alquiler de balcones\",\"datePublished\":\"2019-06-18T07:25:40+00:00\",\"dateModified\":\"2019-06-18T07:25:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/negocio-alquiler-balcones\\\/\"},\"wordCount\":856,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/negocio-alquiler-balcones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2019\\\/06\\\/spain-711632_1920.jpg\",\"keywords\":[\"alquiler balcones\",\"declarar\",\"IRPF\"],\"articleSection\":[\"General\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/negocio-alquiler-balcones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/negocio-alquiler-balcones\\\/\",\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/negocio-alquiler-balcones\\\/\",\"name\":\"El negocio de alquiler de balcones - Derecho Mercantil\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/negocio-alquiler-balcones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/negocio-alquiler-balcones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2019\\\/06\\\/spain-711632_1920.jpg\",\"datePublished\":\"2019-06-18T07:25:40+00:00\",\"dateModified\":\"2019-06-18T07:25:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/#\\\/schema\\\/person\\\/1f848038ac5623245414f398a267708f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/negocio-alquiler-balcones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/negocio-alquiler-balcones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/negocio-alquiler-balcones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2019\\\/06\\\/spain-711632_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2019\\\/06\\\/spain-711632_1920.jpg\",\"width\":1024,\"height\":731},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/negocio-alquiler-balcones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El negocio de alquiler de balcones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/#website\",\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/\",\"name\":\"Derecho Mercantil\",\"description\":\"Derecho y Empresa Euroresidentes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/#\\\/schema\\\/person\\\/1f848038ac5623245414f398a267708f\",\"name\":\"Manuel Pomares\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2016\\\/08\\\/manuel-pomares-abogados-150x150.jpg\",\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2016\\\/08\\\/manuel-pomares-abogados-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2016\\\/08\\\/manuel-pomares-abogados-150x150.jpg\",\"caption\":\"Manuel Pomares\"},\"description\":\"Manuel PomaresAbogado y socio director de la firma Pomares Abogados. Especialista en derecho mercantil-societario, bancario y responsabilidad civil-seguro.\",\"sameAs\":[\"http:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/manuel-pomares-2.html\"],\"url\":\"https:\\\/\\\/www.euroresidentes.com\\\/empresa\\\/derecho-mercantil\\\/author\\\/manuel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El negocio de alquiler de balcones - Derecho Mercantil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/","og_locale":"es_ES","og_type":"article","og_title":"El negocio de alquiler de balcones - Derecho Mercantil","og_description":"Hace unos meses comenz\u00f3 el plazo de presentaci\u00f3n de la Declaraci\u00f3n de la Renta 2018 para cumplir con Hacienda por los ingresos obtenidos en el ejercicio pasado. \u00a0 Por regla general, la campa\u00f1a de la Declaraci\u00f3n de la Renta de cada a\u00f1o trae consigo algunas novedades. Este a\u00f1o destacamos el nuevo umbral para determinar qui\u00e9nes est\u00e1n obligados a declarar, la ampliaci\u00f3n de las deducciones para familias numerosas y la exenci\u00f3n del pago de IRPF de los ingresos correspondientes a prestaciones de maternidad y paternidad. \u00a0 Pero \u00bfQu\u00e9 pasa con otras costumbres de menor repercusi\u00f3n, pero muy habituales en nuestro Pa\u00eds?","og_url":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/","og_site_name":"Derecho Mercantil","article_publisher":"https:\/\/www.facebook.com\/euroresidentes\/","article_published_time":"2019-06-18T07:25:40+00:00","article_modified_time":"2019-06-18T07:25:41+00:00","og_image":[{"width":1024,"height":731,"url":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2019\/06\/spain-711632_1920.jpg","type":"image\/jpeg"}],"author":"Manuel Pomares","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Manuel Pomares","Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/#article","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/"},"author":{"name":"Manuel Pomares","@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/#\/schema\/person\/1f848038ac5623245414f398a267708f"},"headline":"El negocio de alquiler de balcones","datePublished":"2019-06-18T07:25:40+00:00","dateModified":"2019-06-18T07:25:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/"},"wordCount":856,"commentCount":0,"image":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2019\/06\/spain-711632_1920.jpg","keywords":["alquiler balcones","declarar","IRPF"],"articleSection":["General"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/","url":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/","name":"El negocio de alquiler de balcones - Derecho Mercantil","isPartOf":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/#primaryimage"},"image":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/#primaryimage"},"thumbnailUrl":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2019\/06\/spain-711632_1920.jpg","datePublished":"2019-06-18T07:25:40+00:00","dateModified":"2019-06-18T07:25:41+00:00","author":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/#\/schema\/person\/1f848038ac5623245414f398a267708f"},"breadcrumb":{"@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/#primaryimage","url":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2019\/06\/spain-711632_1920.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2019\/06\/spain-711632_1920.jpg","width":1024,"height":731},{"@type":"BreadcrumbList","@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/negocio-alquiler-balcones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/"},{"@type":"ListItem","position":2,"name":"El negocio de alquiler de balcones"}]},{"@type":"WebSite","@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/#website","url":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/","name":"Derecho Mercantil","description":"Derecho y Empresa Euroresidentes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/#\/schema\/person\/1f848038ac5623245414f398a267708f","name":"Manuel Pomares","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2016\/08\/manuel-pomares-abogados-150x150.jpg","url":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2016\/08\/manuel-pomares-abogados-150x150.jpg","contentUrl":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-content\/uploads\/sites\/12\/2016\/08\/manuel-pomares-abogados-150x150.jpg","caption":"Manuel Pomares"},"description":"Manuel PomaresAbogado y socio director de la firma Pomares Abogados. Especialista en derecho mercantil-societario, bancario y responsabilidad civil-seguro.","sameAs":["http:\/\/www.euroresidentes.com\/empresa\/manuel-pomares-2.html"],"url":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/author\/manuel\/"}]}},"_links":{"self":[{"href":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-json\/wp\/v2\/posts\/2020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-json\/wp\/v2\/comments?post=2020"}],"version-history":[{"count":1,"href":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-json\/wp\/v2\/posts\/2020\/revisions"}],"predecessor-version":[{"id":2022,"href":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-json\/wp\/v2\/posts\/2020\/revisions\/2022"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-json\/wp\/v2\/media\/2021"}],"wp:attachment":[{"href":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-json\/wp\/v2\/media?parent=2020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-json\/wp\/v2\/categories?post=2020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroresidentes.com\/empresa\/derecho-mercantil\/wp-json\/wp\/v2\/tags?post=2020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}